{"id":17407,"date":"2024-12-09T16:28:53","date_gmt":"2024-12-09T12:58:53","guid":{"rendered":"https:\/\/taaghche.com\/blog\/?p=17407"},"modified":"2025-10-27T17:09:43","modified_gmt":"2025-10-27T13:39:43","slug":"%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84","status":"publish","type":"post","link":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/","title":{"rendered":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u0633\u0627\u0644\u0647"},"content":{"rendered":"\n<p>\u0631\u0648\u0627\u0646\u200c\u0634\u0646\u0627\u0633\u0627\u0646 \u0648 \u0639\u0644\u0645\u0627\u06cc \u062a\u0639\u0644\u06cc\u0645\u200c\u0648\u062a\u0631\u0628\u06cc\u062a \u0645\u0639\u062a\u0642\u062f \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0648\u0631\u0647\u200c\u06cc \u062a\u0648\u0644\u062f \u062a\u0627 \u06f2\u0633\u0627\u0644\u06af\u06cc \u062f\u0648\u0631\u0647\u200c\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u062d\u06cc\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062f\u0648\u0631\u0647 \u0627\u0632 \u0631\u0634\u062f \u06a9\u0648\u062f\u06a9 \u0631\u0627 \u062f\u0648\u0631\u0647\u200c\u06cc \u062d\u0633\u06cc\u200c\u062d\u0631\u06a9\u062a\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u06af\u0648\u06cc\u0646\u062f\u061b \u0686\u0648\u0646 \u06a9\u0648\u062f\u06a9 \u0628\u0627 \u062d\u0631\u06a9\u0627\u062a \u0648 \u0627\u0639\u0636\u0627\u06cc \u062d\u0633\u06cc \u062e\u0648\u062f \u0628\u0627 \u0645\u062d\u06cc\u0637 \u0648 \u0627\u0637\u0631\u0627\u0641\u06cc\u0627\u0646 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0631\u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0632\u06cc\u0631 \u06f2 \u0633\u0627\u0644 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0627\u0645\u0627 \u0630\u0647\u0646 \u0622\u0646\u200c\u0647\u0627 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0648 \u0622\u0645\u0627\u062f\u06af\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0631\u0634\u062f \u0648 \u062a\u06a9\u0627\u0645\u0644 \u062f\u0627\u0631\u062f. \u0642\u062f\u0631\u062a \u062c\u0630\u0628 \u0644\u063a\u062a \u062f\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06f0 \u062a\u0627 \u06f2 \u0633\u0627\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627\u0633\u062a \u0648 \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0631\u062f\u0647\u200c\u06cc \u0633\u0646\u06cc \u062e\u0648\u0627\u0646\u062f\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0627\u0631\u0647\u0627 \u0648 \u0628\u0627 \u0635\u062f\u0627\u06cc \u0628\u0644\u0646\u062f \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0627\u0632 \u0628\u0644\u0627\u06af \u0637\u0627\u0642\u0686\u0647\u060c \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u0648 \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0646\u06cc\u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0648 \u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u0639\u0631\u0641\u06cc \u062e\u0648\u0627\u0647\u062f \u0634\u062f. \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0644\u0627\u0644\u0627\u06cc\u06cc \u0648 \u0634\u0639\u0631 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0635\u0648\u062a\u06cc \u062f\u0627\u0633\u062a\u0627\u0646\u06cc \u0645\u0639\u0631\u0641\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u0648 \u0628\u0631\u0627\u06cc \u0645\u0639\u0631\u0641\u06cc \u06a9\u062a\u0627\u0628 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u0628\u0647 \u0645\u0648\u0636\u0648\u0639\u0627\u062a \u06af\u0648\u0646\u0627\u06af\u0648\u0646 \u0648 \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0646\u06cc\u0627\u0632 \u0632\u06cc\u0633\u062a\u06cc \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u062c\u0646\u0628\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062a\u0648\u062c\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D8%A7%D8%B3%D8%AA%D8%A7%D9%86_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%86%D9%88%D8%B2%D8%A7%D8%AF%D8%A7%D9%86\" >\u06a9\u062a\u0627\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%BE%D8%B1%D9%86%DB%8C%D8%A7%D9%86_%D9%88_%D8%A2%D8%A8\" >\u067e\u0631\u0646\u06cc\u0627\u0646 \u0648 \u0622\u0628<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%D9%84%D8%A7%D9%84%D8%A7%DB%8C%DB%8C_%D9%88%D8%A7%D8%B3%D9%87_%D9%86%DB%8C%E2%80%8C%D9%86%DB%8C\" >\u0645\u062c\u0645\u0648\u0639\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0648\u0627\u0633\u0647 \u0646\u06cc\u200c\u0646\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%84%D8%A7%D9%84%D8%A7%E2%80%8C%DB%8C%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AE%D8%A7%D9%86%D9%85_%DA%A9%D9%84%D8%A7%D8%BA%D9%87\" >\u0644\u0627\u0644\u0627\u200c\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u0645 \u06a9\u0644\u0627\u063a\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AF%D9%86%DB%8C%D8%A7_%D8%AF%D9%86%DB%8C%D8%A7_%D9%84%D8%A7%D9%84%D8%A7%DB%8C%DB%8C\" >\u062f\u0646\u06cc\u0627 \u062f\u0646\u06cc\u0627 \u0644\u0627\u0644\u0627\u06cc\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%A7%D9%85%D8%A7%D9%86_%D8%AA%D8%B1%D8%A8%DA%86%D9%87_%D9%84%D8%A7%D9%84%D8%A7%DB%8C%DB%8C_%D8%A8%D8%AE%D9%88%D8%A7%D9%86\" >\u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%84%D8%A7%D9%84%D8%A7_%DA%AF%D9%84%D8%AF%D9%88%D9%86%D8%8C_%D9%84%D8%A7_%D9%84%D8%A7_%D9%85%D8%A7%D9%87%DB%8C-%D8%A7%D8%B2_%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%D9%84%D8%A7%D9%84%D8%A7%DB%8C%DB%8C_%D9%87%D8%A7\" >\u0644\u0627\u0644\u0627 \u06af\u0644\u062f\u0648\u0646\u060c \u0644\u0627 \u0644\u0627 \u0645\u0627\u0647\u06cc-\u0627\u0632 \u0645\u062c\u0645\u0648\u0639\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%86%DB%8C_%D9%86%DB%8C_%D9%82%D8%A7%D9%85_%D9%82%D8%A7%D9%85\" >\u0646\u06cc \u0646\u06cc \u0642\u0627\u0645 \u0642\u0627\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D9%BE%D9%86%D8%AC_%D8%A7%D9%86%DA%AF%D8%B4%D8%AA_%D8%A8%D9%88%D8%AF%D9%86%D8%AF_%DA%A9%D9%87%E2%80%A6_%D8%BA%D8%B0%D8%A7%D9%87%D8%A7_%D9%88_%D8%A8%D8%A7%D8%B2%DB%8C%E2%80%8C%D9%87%D8%A7\" >\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646\u062f \u06a9\u0647\u2026 (\u063a\u0630\u0627\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D9%BE%D9%86%D8%AC_%D8%AA%D8%A7_%D8%A7%D9%86%DA%AF%D8%B4%D8%AA_%D8%A8%D9%88%D8%AF%D9%86_%DA%A9%D9%87%E2%80%A6_%D9%85%D8%B1%D8%A7%D8%B3%D9%85_%D9%88_%D8%B4%D8%BA%D9%84%E2%80%8C%D9%87%D8%A7\" >\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u062a\u0627 \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646 \u06a9\u0647\u2026 (\u0645\u0631\u0627\u0633\u0645 \u0648 \u0634\u063a\u0644\u200c\u0647\u0627)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%DA%A9%DB%8C_%D8%A8%D9%88%D8%AF%D8%9F_%DA%A9%DB%8C_%D8%A8%D9%88%D8%AF%D8%9F\" >\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u06a9\u06cc \u0628\u0648\u062f\u061f \u06a9\u06cc \u0628\u0648\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D8%AE%D9%88%D8%A7%D8%A8_%D9%82%D8%B4%D9%86%DA%AF_%DA%A9%D8%AC%D8%A7%DB%8C%DB%8C%D8%9F\" >\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062e\u0648\u0627\u0628 \u0642\u0634\u0646\u06af \u06a9\u062c\u0627\u06cc\u06cc\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%D9%82%D8%B5%D9%87_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%DA%A9%D9%88%D8%AF%DA%A9%D8%A7%D9%86\" >\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0635\u0647 \u0646\u0645\u0627\u06cc\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D8%A8%D8%B2_%D8%B2%D9%86%DA%AF%D9%88%D9%84%D9%87%E2%80%8C%D9%BE%D8%A7\" >\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0628\u0632 \u0632\u0646\u06af\u0648\u0644\u0647\u200c\u067e\u0627<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%A9%D8%AA%D8%A7%D8%A8_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D9%88%D8%AF%DA%A9_%DB%8C%DA%A9_%D8%B3%D8%A7%D9%84%D9%87_%D9%88_%D8%AF%D9%88_%D8%B3%D8%A7%D9%84%D9%87\" >\u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u062f\u0648 \u0633\u0627\u0644\u0647<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AC%D9%88%D8%AC%D9%87_%DA%A9%D9%88%DA%86%D9%88%D9%84%D9%88_%D8%AA%DB%8C%E2%80%8C%D8%AA%D8%A7%D9%BE%D8%8C_%D8%AA%DB%8C%E2%80%8C%D8%AA%D8%A7%D9%BE%D8%8C_%D8%A8%D8%AF%D9%88\" >\u062c\u0648\u062c\u0647 \u06a9\u0648\u0686\u0648\u0644\u0648! \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u0628\u062f\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%A7%D8%B4%DB%8C%D9%86_%D9%87%D8%A7\" >\u0645\u0627\u0634\u06cc\u0646 \u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%D9%86%DB%8C%E2%80%8C%D9%86%DB%8C%E2%80%8C%D9%87%D8%A7\" >\u0645\u062c\u0645\u0648\u0639\u0647 \u0646\u06cc\u200c\u0646\u06cc\u200c\u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%86%DB%8C_%D9%86%DB%8C_%DA%A9%D9%88%DA%86%D9%88%D9%84%D9%88\" >\u0646\u06cc \u0646\u06cc \u06a9\u0648\u0686\u0648\u0644\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%A7%DA%98%D8%AF%D9%87%D8%A7_%D9%88_%D8%AF%D8%B3%D8%AA%D8%B4%D9%88%DB%8C%DB%8C_%D8%B1%D9%81%D8%AA%D9%86\" >\u0627\u0698\u062f\u0647\u0627 \u0648 \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc \u0631\u0641\u062a\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%87%D8%B1_%D8%AC%D8%A7%DB%8C%DB%8C_%D8%AC%DB%8C%D8%B4_%D9%86%DA%A9%D9%86\" >\u0647\u0631 \u062c\u0627\u06cc\u06cc \u062c\u06cc\u0634 \u0646\u06a9\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%B2%D8%B1%D9%86%DA%AF_%D8%AA%D8%B1_%D8%A7%D8%B2_%D8%AC%DB%8C%D8%B4_%D9%88_%D9%BE%DB%8C_%D9%BE%DB%8C\" >\u0632\u0631\u0646\u06af \u062a\u0631 \u0627\u0632 \u062c\u06cc\u0634 \u0648 \u067e\u06cc \u067e\u06cc!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%A7%DB%8C%D9%86_%DA%A9%D8%A7%D8%B1%D8%A7_%DA%A9%D8%A7%D8%B1_%D8%AC%DB%8C%D8%B4%D9%87\" >\u0627\u06cc\u0646 \u06a9\u0627\u0631\u0627 \u06a9\u0627\u0631 \u062c\u06cc\u0634\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AE%D8%B1%DA%AF%D9%88%D8%B4%DA%A9_%D9%BE%DB%8C_%D9%BE%DB%8C_%D9%85%DB%8C_%DA%A9%D9%86%D8%AF\" >\u062e\u0631\u06af\u0648\u0634\u06a9 \u067e\u06cc \u067e\u06cc \u0645\u06cc \u06a9\u0646\u062f!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%82%D8%B5%D9%87_%D9%87%D8%A7%DB%8C%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%DB%B2_%D8%B3%D8%A7%D9%84%D9%87_%D9%87%D8%A7\" >\u0642\u0635\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%82%D8%B5%D9%87_%D9%87%D8%A7%DB%8C_%DB%B2_%D8%B3%D8%A7%D9%84%D9%87_%D9%87%D8%A7\" >\u0642\u0635\u0647 \u0647\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%AF%D8%B1%DA%AF_%DA%A9%D9%88%DA%86%D9%88%D9%84%D9%88_%D8%AF%DB%8C%DA%AF%D8%B1_%D9%BE%D8%B3%D8%AA%D8%A7%D9%86%DA%A9_%D9%86%D9%85%DB%8C_%D8%AE%D9%88%D8%A7%D9%87%D8%AF\" >\u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u06cc\u06af\u0631 \u067e\u0633\u062a\u0627\u0646\u06a9 \u0646\u0645\u06cc \u062e\u0648\u0627\u0647\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D9%86_%D8%A7%D8%B2_%D9%BE%D8%B3%D8%B4_%D8%A8%D8%B1_%D9%85%DB%8C_%D8%A2%DB%8C%D9%85\" >\u0645\u0646 \u0627\u0632 \u067e\u0633\u0634 \u0628\u0631 \u0645\u06cc \u0622\u06cc\u0645!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%A7%DB%8C_%D9%88%D8%A7%DB%8C%D8%8C_%DA%AF%D9%85_%D8%B4%D8%AF%D9%85\" >\u0627\u06cc \u0648\u0627\u06cc\u060c \u06af\u0645 \u0634\u062f\u0645!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%A8%D8%A7%D8%B2%DB%8C_%D8%A8%D8%A7_%D8%A7%D9%86%DA%AF%D8%B4%D8%AA_%D9%87%D8%A7\" >\u0628\u0627\u0632\u06cc \u0628\u0627 \u0627\u0646\u06af\u0634\u062a \u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AF%D8%A7%D9%84%DB%8C\" >\u062f\u0627\u0644\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AA%D8%B1%D8%A7%D9%86%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%DB%8C_%D9%85%DB%8C_%D9%86%DB%8C_%D9%88_%D9%85%D8%A7%D9%85%D8%A7%D9%86%DB%8C\" >\u062a\u0631\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u06cc \u0645\u06cc \u0646\u06cc \u0648 \u0645\u0627\u0645\u0627\u0646\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%DA%A9%D8%AA%D8%A7%D8%A8%E2%80%8C%D9%87%D8%A7%DB%8C_%DA%AF%D8%B1%D8%AF%D9%88\" >\u0645\u062c\u0645\u0648\u0639\u0647 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u06af\u0631\u062f\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%AA%D8%B9%D8%A7%D9%85%D9%84%DB%8C_%D8%AE%D8%B1%DA%AF%D9%88%D8%B4%DB%8C\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062a\u0639\u0627\u0645\u0644\u06cc \u062e\u0631\u06af\u0648\u0634\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-35\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D9%82%D9%87%D8%B1%D9%85%D8%A7%D9%86_%D8%B4%D9%86%D9%84%E2%80%8C%D9%BE%D9%88%D8%B4\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0642\u0647\u0631\u0645\u0627\u0646 \u0634\u0646\u0644\u200c\u067e\u0648\u0634<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-36\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D9%85%D8%A7_%D8%A7%DB%8C%D9%86%D8%AC%D8%A7_%D8%B2%D9%86%D8%AF%DA%AF%DB%8C_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%DB%8C%D9%85\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0645\u0627 \u0627\u06cc\u0646\u062c\u0627 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-37\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%AE%D9%85%DB%8C%D8%B1%DB%8C%E2%80%8C%D9%87%D8%A7\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062e\u0645\u06cc\u0631\u06cc\u200c\u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-38\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%AF%D9%86%DB%8C%D8%A7%DB%8C_%D9%BE%D9%BE%D8%A7\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062f\u0646\u06cc\u0627\u06cc \u067e\u067e\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-39\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D9%86%DA%AF%D8%A7%D9%87_%DA%A9%D9%86\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0646\u06af\u0627\u0647 \u06a9\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-40\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%DA%AF%D8%B1%DA%AF%D9%88%D8%B4%DA%A9%D8%9B_%DA%AF%D8%B1%DA%AF_%DA%A9%D9%88%DA%86%D9%88%D9%84%D9%88_%D8%AF%D8%B1_%D8%AE%D8%A7%D9%86%D9%88%D8%A7%D8%AF%D9%87_%D8%AE%D8%B1%DA%AF%D9%88%D8%B4_%D9%87%D8%A7\" >\u06af\u0631\u06af\u0648\u0634\u06a9\u061b \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062e\u0631\u06af\u0648\u0634 \u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-41\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%B4%D8%A7%DB%8C%D8%AF_%D8%B3%DB%8C%D8%A8_%D8%A8%D8%A7%D8%B4%D8%AF\" >\u0634\u0627\u06cc\u062f \u0633\u06cc\u0628 \u0628\u0627\u0634\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-42\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%B3%D9%84%D8%A7%D9%85_%D8%AF%D9%86%DB%8C%D8%A7\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0633\u0644\u0627\u0645 \u062f\u0646\u06cc\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-43\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%B3%D8%B1%D8%B3%D8%B1%DB%8C_%D8%AF%D8%B3_%D8%AF%D8%B3%DB%8C\" >\u0633\u0631\u0633\u0631\u06cc \u062f\u0633 \u062f\u0633\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-44\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%AE%D8%B1%D8%B3%DB%8C_%D9%88_%D8%AF%D9%88%D8%B3%D8%AA%D8%A7%D9%86\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062e\u0631\u0633\u06cc \u0648 \u062f\u0648\u0633\u062a\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-45\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AA%D9%82_%D8%AA%D9%82%D8%8C_%D8%A8%DB%8C%D8%A7_%D8%A8%DB%8C%D8%B1%D9%88%D9%86\" >\u062a\u0642 \u062a\u0642\u060c \u0628\u06cc\u0627 \u0628\u06cc\u0631\u0648\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-46\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%A8%D8%A7_%D8%B3%D8%B1_%D8%A8%D8%B1%DB%8C%D9%85_%D8%AA%D9%88%DB%8C_%DA%A9%D8%AA%D8%A7%D8%A8\" >\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0628\u0627 \u0633\u0631 \u0628\u0631\u06cc\u0645 \u062a\u0648\u06cc \u06a9\u062a\u0627\u0628&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-47\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AE%D8%A7%D9%86%D9%85_%D8%AD%D9%86%D8%A7_%D8%A8%D9%87_%DA%AF%D8%B1%D8%AF%D8%B4_%D9%85%DB%8C_%D8%B1%D9%88%D8%AF\" >\u062e\u0627\u0646\u0645 \u062d\u0646\u0627 \u0628\u0647 \u06af\u0631\u062f\u0634 \u0645\u06cc \u0631\u0648\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-48\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D9%85%D9%87%D9%85%D8%A7%D9%86_%D8%A7%D9%86%D8%A7%D8%B1\" >\u0645\u0647\u0645\u0627\u0646 \u0627\u0646\u0627\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-49\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%A7%D8%B3%DA%A9%D8%A7%D8%B1_%D9%84%D9%86%DA%AF%D9%87_%D8%AC%D9%88%D8%B1%D8%A7%D8%A8%DB%8C\" >\u0627\u0633\u06a9\u0627\u0631 \u0644\u0646\u06af\u0647 \u062c\u0648\u0631\u0627\u0628\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-50\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%A8%D8%B2%D9%86_%D8%B1%D9%88%DB%8C_%D8%AF%D8%B1%D8%AE%D8%AA_%D8%AC%D8%A7%D8%AF%D9%88%DB%8C%DB%8C\" >\u0628\u0632\u0646 \u0631\u0648\u06cc \u062f\u0631\u062e\u062a \u062c\u0627\u062f\u0648\u06cc\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-51\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AF%DA%A9%D9%85%D9%87_%D9%82%D8%B1%D9%85%D8%B2_%D8%B1%D8%A7_%D9%81%D8%B4%D8%A7%D8%B1_%D8%A8%D8%AF%D9%87\" >\u062f\u06a9\u0645\u0647 \u0642\u0631\u0645\u0632 \u0631\u0627 \u0641\u0634\u0627\u0631 \u0628\u062f\u0647<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-52\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\" >\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%AF%D8%A7%D8%B3%D8%AA%D8%A7%D9%86_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%86%D9%88%D8%B2%D8%A7%D8%AF%D8%A7%D9%86\"><\/span>\u06a9\u062a\u0627\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634 \u0627\u0632 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a\u060c \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0631\u0627 \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.<\/p>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%BE%D8%B1%D9%86%DB%8C%D8%A7%D9%86_%D9%88_%D8%A2%D8%A8\"><\/span>\u067e\u0631\u0646\u06cc\u0627\u0646 \u0648 \u0622\u0628<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/166097.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/166097\/\u067e\u0631\u0646\u06cc\u0627\u0646-\u0648-\u0622\u0628\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u067e\u0631\u0646\u06cc\u0627\u0646 \u0648 \u0622\u0628\" >\u067e\u0631\u0646\u06cc\u0627\u0646 \u0648 \u0622\u0628<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u062b\u0631\u06cc\u0627 \u0642\u0632\u0644\u200a\u0627\u06cc\u0627\u063a                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u06a9\u062a\u0627\u0628 \u0686                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/166097\/\u067e\u0631\u0646\u06cc\u0627\u0646-\u0648-\u0622\u0628'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u067e\u0631\u0646\u06cc\u0627\u0646 \u0648 \u0622\u0628\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627 \u0645\u0639\u062c\u0632\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0622\u0647\u0646\u06af\u06cc\u0646 \u0628\u0648\u062f\u0646 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0648 \u062a\u0631\u06a9\u06cc\u0628 \u0622\u0646 \u0628\u0627 \u0635\u062f\u0627\u06cc \u0622\u0631\u0627\u0645\u0634\u200c\u0628\u062e\u0634 \u0645\u0627\u062f\u0631 \u0647\u062f\u06cc\u0647\u200c\u06cc \u06af\u0631\u0627\u0646\u0628\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u062a\u0642\u062f\u06cc\u0645 \u06a9\u0646\u06cc\u062f. \u06a9\u062a\u0627\u0628 \u067e\u0631\u0646\u06cc\u0627\u0646 \u0648 \u0622\u0628 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u06af\u0648\u0634 \u06a9\u0648\u062f\u06a9 \u0634\u0645\u0627 \u0631\u0627 \u0646\u0648\u0627\u0632\u0634 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647\u06cc \u0631\u0627 \u0631\u0648\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0628\u06cc\u0634\u062a\u0631 \u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0647 \u0637\u0628\u06cc\u0639\u062a \u0648 \u0639\u0646\u0627\u0635\u0631 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0622\u0646 \u0627\u0634\u0627\u0631\u0647 \u062f\u0627\u0631\u0646\u062f \u0648 \u0627\u0633\u0627\u0645\u06cc \u0627\u0646\u0648\u0627\u0639 \u06af\u0644\u200c\u0647\u0627 \u0648 \u0641\u0635\u0644\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062f\u0631 \u0622\u0646 \u0641\u0631\u0627\u0648\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%D9%84%D8%A7%D9%84%D8%A7%DB%8C%DB%8C_%D9%88%D8%A7%D8%B3%D9%87_%D9%86%DB%8C%E2%80%8C%D9%86%DB%8C\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0648\u0627\u0633\u0647 \u0646\u06cc\u200c\u0646\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/210554.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/210554\/\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0648\u0627\u0633\u0647-\u0646\u06cc-\u0646\u06cc-\u06f1\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0648\u0627\u0633\u0647 \u0646\u06cc \u0646\u06cc (\u06f1)\" >\u0644\u0627\u0644\u0627\u06cc\u06cc \u0648\u0627\u0633\u0647 \u0646\u06cc \u0646\u06cc (\u06f1)<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u062a\u06a9\u062a\u0645 \u0628\u06cc\u062f\u0644                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u062d\u0627\u0645\u06cc\u0627\u0646                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/210554\/\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0648\u0627\u0633\u0647-\u0646\u06cc-\u0646\u06cc-\u06f1'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0648\u0627\u0633\u0647 \u0646\u06cc \u0646\u06cc (\u06f1)\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0635\u062f\u0627\u06cc \u0645\u0627\u062f\u0631\u0627\u0646 \u0622\u0631\u0627\u0645\u0634\u200c\u0628\u062e\u0634\u200c\u062a\u0631\u06cc\u0646 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0627\u0633\u062a. \u0648\u0642\u062a\u06cc \u0627\u06cc\u0646 \u0635\u062f\u0627 \u0628\u0627 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0645\u0631\u0627\u0647 \u0634\u0648\u062f \u062e\u0648\u0627\u0628 \u0631\u0627\u062d\u062a\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0628\u0647\u200c\u0647\u0645\u0631\u0627\u0647 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a. \u0627\u06af\u0631 \u0628\u0647\u200c\u062f\u0646\u0628\u0627\u0644 \u06a9\u062a\u0627\u0628 \u0646\u0648\u0632\u0627\u062f\u06cc \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0644\u0627\u0644\u0627\u06cc\u06cc \u0648\u0627\u0633\u0647 \u0646\u06cc\u200c\u0646\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0646\u0627\u0633\u0628\u06cc \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u062a\u06a9\u062a\u0645 \u0628\u06cc\u062f\u0644 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0634\u0639\u0631\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647 \u0648 \u0634\u06cc\u0631\u06cc\u0646\u06cc \u0631\u0627 \u0633\u0631\u0648\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0622\u0631\u0627\u0645\u0634 \u062e\u0648\u0627\u0628 \u0646\u0648\u0632\u0627\u062f \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<p>\u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f <a href=\"https:\/\/taaghche.com\/filter?filter-label=13772&amp;order=undefined\">\u0645\u062c\u0645\u0648\u0639\u0647 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0644\u0627\u0644\u0627\u06cc\u06cc \u0648\u0627\u0633\u0647 \u0646\u06cc\u200c\u0646\u06cc<\/a> \u0631\u0627 \u0627\u0632 \u0633\u0627\u06cc\u062a \u0637\u0627\u0642\u0686\u0647 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u0648 \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u0646\u06cc\u062f.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%84%D8%A7%D9%84%D8%A7%E2%80%8C%DB%8C%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AE%D8%A7%D9%86%D9%85_%DA%A9%D9%84%D8%A7%D8%BA%D9%87\"><\/span>\u0644\u0627\u0644\u0627\u200c\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u0645 \u06a9\u0644\u0627\u063a\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u0644\u0627\u0644\u0627\u06cc\u06cc\u200c \u0627\u0632 \u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062f\u0648\u0631 \u0645\u0646\u0628\u0639 \u0622\u0631\u0627\u0645\u0634 \u0648 \u0627\u0646\u062a\u0642\u0627\u0644 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u0628\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0648 \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0628\u0648\u062f\u0647\u200c \u0627\u0633\u062a \u0648 \u0627\u06cc\u0646 \u0641\u0631\u0647\u0646\u06af \u062a\u0627 \u0628\u0647 \u0627\u0645\u0631\u0648\u0632 \u0646\u06cc\u0632 \u0627\u062f\u0627\u0645\u0647 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u0645 \u06a9\u0644\u0627\u063a\u0647 <strong>\u06a9\u062a\u0627\u0628\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0632\u06cc\u0631 \u06cc\u06a9 \u0633\u0627\u0644<\/strong> \u0627\u0633\u062a \u06a9\u0647 \u0645\u0698\u06af\u0627\u0646 \u0634\u06cc\u062e\u06cc \u062f\u0631 \u0622\u0646 \u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0631\u0627 \u0633\u0631\u0648\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0642\u0635\u0647 \u062f\u0627\u0631\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0628\u0647 \u0645\u0647\u0627\u0631\u062a \u0634\u0646\u06cc\u062f\u0627\u0631\u06cc \u0648 \u0632\u0628\u0627\u0646\u200c\u0622\u0645\u0648\u0632\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/216015\/\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0647\u0627\u06cc-\u062e\u0627\u0646\u0645-\u06a9\u0644\u0627\u063a\u0647\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627\u06cc \u062e\u0627\u0646\u0645 \u06a9\u0644\u0627\u063a\u0647\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627\u06cc \u062e\u0627\u0646\u0645 \u06a9\u0644\u0627\u063a\u0647<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/216015.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627\u06cc \u062e\u0627\u0646\u0645 \u06a9\u0644\u0627\u063a\u0647                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0698\u06af\u0627\u0646 \u0634\u06cc\u062e\u06cc                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0645\u06cc\u0631\u0631\u0636\u0627 \u0633\u0644\u0637\u0627\u0646 \u062e\u0648\u0627\u0647 \u0628\u06cc\u062f\u062e\u062a\u06cc                     <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0635\u062f\u0627\u06cc \u0622\u0628\u06cc (\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0639\u0644\u0645\u06cc \u0648 \u0641\u0631\u0647\u0646\u06af\u06cc)                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiZmFiYjNjNmMtNTM4NC00ODYxLWE3NjMtOWU3MTg1MTYyNDliIiwiaWF0IjoxNzc4Njk0NDYyLCJleHAiOjUzNzg2OTQ0NjJ9.b-D3l-74pBtsUBeJ7kj0JRMI5MMxfPq-XPA_KS1pMzI \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/216015\/\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0647\u0627\u06cc-\u062e\u0627\u0646\u0645-\u06a9\u0644\u0627\u063a\u0647'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627\u06cc \u062e\u0627\u0646\u0645 \u06a9\u0644\u0627\u063a\u0647\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D8%AF%D9%86%DB%8C%D8%A7_%D8%AF%D9%86%DB%8C%D8%A7_%D9%84%D8%A7%D9%84%D8%A7%DB%8C%DB%8C\"><\/span>\u062f\u0646\u06cc\u0627 \u062f\u0646\u06cc\u0627 \u0644\u0627\u0644\u0627\u06cc\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062f\u0646\u06cc\u0627 \u062f\u0646\u06cc\u0627 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0633\u0631\u0648\u062f\u0647\u200c\u06cc \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0646\u0648\u06cc\u0633\u0646\u062f\u0647\u200c\u06cc \u0646\u0627\u0645\u200c\u0622\u0634\u0646\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062f\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0631\u0627 \u0627\u0632 \u0632\u0628\u0627\u0646 \u067e\u062f\u0631\u0647\u0627 \u0648 \u0645\u0627\u062f\u0631\u0647\u0627 \u0648 \u06af\u0627\u0647\u06cc \u0628\u0686\u0647\u200c\u0647\u0627 \u0633\u0631\u0648\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 <strong>\u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647<\/strong> \u0648 \u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0644\u0630\u062a\u200c\u0628\u062e\u0634 \u0628\u0627\u0634\u062f. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627 \u0644\u0630\u062a \u0645\u06cc\u200c\u0628\u0631\u0646\u062f \u0648 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647\u200c\u062e\u0627\u0637\u0631 \u0645\u06cc\u200c\u0633\u067e\u0627\u0631\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u0639\u0631\u0648\u0633\u06a9\u200c\u0647\u0627\u06cc\u0634\u0627\u0646 \u0628\u0627\u0632\u062e\u0648\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/40189\/\u062f\u0646\u06cc\u0627-\u062f\u0646\u06cc\u0627-\u0644\u0627\u0644\u0627\u06cc\u06cc\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062f\u0646\u06cc\u0627 \u062f\u0646\u06cc\u0627 \u0644\u0627\u0644\u0627\u06cc\u06cc\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062f\u0646\u06cc\u0627 \u062f\u0646\u06cc\u0627 \u0644\u0627\u0644\u0627\u06cc\u06cc<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/40189.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u062f\u0646\u06cc\u0627 \u062f\u0646\u06cc\u0627 \u0644\u0627\u0644\u0627\u06cc\u06cc                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06af\u0631\u0648\u0647 \u06af\u0648\u06cc\u0646\u062f\u06af\u0627\u0646                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0648\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u06af\u0648\u06cc\u0627                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiMzZhZDY1ODQtNWMyNy00Y2Y4LTgzNjktM2FhZGM2M2FlNjI0IiwiaWF0IjoxNzc4Njk0NDYyLCJleHAiOjUzNzg2OTQ0NjJ9.pr8M0qbunY6jDxfBxgXZMyX7-1ayz2fTa-F0zD_gy1E \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/40189\/\u062f\u0646\u06cc\u0627-\u062f\u0646\u06cc\u0627-\u0644\u0627\u0644\u0627\u06cc\u06cc'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062f\u0646\u06cc\u0627 \u062f\u0646\u06cc\u0627 \u0644\u0627\u0644\u0627\u06cc\u06cc\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n                                        <div class=\"relatedpost\">\n                        <div class=\"d-flex align-items-center\">\n                            <img decoding=\"async\" data-src=\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2020\/08\/641-4.jpg\" class=\"relatedimg lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1140px; --smush-placeholder-aspect-ratio: 1140\/641;\" \/>\n                            <div class=\"inforelated\">\n                                <p>\n                                    \u062f\u0631 \u0645\u062c\u0644\u0647\u200c\u06cc \u0637\u0627\u0642\u0686\u0647 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:\n                                <\/p>\n                                <a href=\"https:\/\/taaghche.com\/blog\/1399\/06\/03\/%da%a9%d8%aa%d8%a7%d8%a8-%d9%84%d8%a7%d9%84%d8%a7%db%8c%db%8c-%da%a9%d9%88%d8%af%da%a9\/\" target=\"_blank\">                      \n                                    <p class=\"relatedname\">\n                                        \u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u0627\u0644\u0627\u06cc\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646\u0647 \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0628                                    <\/p>\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%A7%D9%85%D8%A7%D9%86_%D8%AA%D8%B1%D8%A8%DA%86%D9%87_%D9%84%D8%A7%D9%84%D8%A7%DB%8C%DB%8C_%D8%A8%D8%AE%D9%88%D8%A7%D9%86\"><\/span>\u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0627\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/167675.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/167675\/\u0645\u0627\u0645\u0627\u0646-\u062a\u0631\u0628\u0686\u0647-\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0628\u062e\u0648\u0627\u0646\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0627\u0646\" >\u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0627\u0646<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0639\u0635\u0648\u0645\u0647 \u06cc\u0632\u062f\u0627\u0646\u06cc                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0639\u0644\u0645\u06cc \u0648 \u0641\u0631\u0647\u0646\u06af\u06cc                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/167675\/\u0645\u0627\u0645\u0627\u0646-\u062a\u0631\u0628\u0686\u0647-\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0628\u062e\u0648\u0627\u0646'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0627\u0646\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627 \u0628\u0633\u062a\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0631\u0627\u06cc \u0622\u0645\u0648\u0632\u0634 \u0645\u0641\u0627\u0647\u06cc\u0645 \u0645\u062e\u062a\u0644\u0641 \u0647\u0633\u062a\u0646\u062f. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627 \u0634\u0646\u06cc\u062f\u0646 \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0627\u0646\u060c \u0646\u0648\u0634\u062a\u0647\u200c\u06cc \u0645\u0639\u0635\u0648\u0645\u06cc \u06cc\u0632\u062f\u0627\u0646\u06cc\u060c \u0628\u0627 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0648\u0627\u0698\u0647\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u062f\u0631\u0639\u06cc\u0646\u200c\u062d\u0627\u0644 \u0644\u0630\u062a \u0645\u06cc\u200c\u0628\u0631\u0646\u062f. \u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0627\u0646 \u06a9\u062a\u0627\u0628\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u06f6\u0645\u0627\u0647\u0647 \u0648 \u062d\u062a\u06cc \u0628\u0632\u0631\u06af\u200c\u062a\u0631 \u0627\u0633\u062a \u0648 \u062f\u0627\u0633\u062a\u0627\u0646 \u06cc\u06a9 \u0631\u0648\u0632 \u0628\u0627\u0631\u0627\u0646\u06cc \u0631\u0627 \u0631\u0648\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u062a\u0631\u0628\u0686\u0647 \u0628\u0627 \u06cc\u06a9 \u0642\u0627\u0631\u0686 \u062f\u06a9\u0645\u0647\u200c\u0627\u06cc \u06a9\u0648\u0686\u0648\u0644\u0648 \u0628\u0631\u062e\u0648\u0631\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0627\u0648 \u0631\u0627 \u0645\u0627\u0645\u0627 \u0635\u062f\u0627 \u0645\u06cc\u200c\u0632\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/198984\/\u0645\u0627\u0645\u0627\u0646-\u062a\u0631\u0628\u0686\u0647-\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0628\u062e\u0648\u0646\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0646\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0646<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/198984.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0646                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0639\u0635\u0648\u0645\u0647 \u06cc\u0632\u062f\u0627\u0646\u06cc                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u062d\u06cc\u0627 \u0633\u0627\u0639\u062f\u06cc                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0635\u062f\u0627\u06cc \u0622\u0628\u06cc (\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0639\u0644\u0645\u06cc \u0648 \u0641\u0631\u0647\u0646\u06af\u06cc)                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiZWFhMjAyOTUtOTYyZS00NmU0LWIzOGYtZjYxNGZjMjc0MmQ3IiwiaWF0IjoxNzc4Njk0NDYyLCJleHAiOjUzNzg2OTQ0NjJ9.6lgDp5kDTYNm7qfoAPhMSFlLvLQsWRdK6IbkqB3LPJc \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/198984\/\u0645\u0627\u0645\u0627\u0646-\u062a\u0631\u0628\u0686\u0647-\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0628\u062e\u0648\u0646'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u0627\u0645\u0627\u0646 \u062a\u0631\u0628\u0686\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0628\u062e\u0648\u0646\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%84%D8%A7%D9%84%D8%A7_%DA%AF%D9%84%D8%AF%D9%88%D9%86%D8%8C_%D9%84%D8%A7_%D9%84%D8%A7_%D9%85%D8%A7%D9%87%DB%8C-%D8%A7%D8%B2_%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%D9%84%D8%A7%D9%84%D8%A7%DB%8C%DB%8C_%D9%87%D8%A7\"><\/span>\u0644\u0627\u0644\u0627 \u06af\u0644\u062f\u0648\u0646\u060c \u0644\u0627 \u0644\u0627 \u0645\u0627\u0647\u06cc-\u0627\u0632 \u0645\u062c\u0645\u0648\u0639\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/498.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/498\/\u0644\u0627\u0644\u0627-\u06af\u0644\u062f\u0648\u0646\u060c-\u0644\u0627-\u0644\u0627-\u0645\u0627\u0647\u06cc-\u0627\u0632-\u0645\u062c\u0645\u0648\u0639\u0647-\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0647\u0627\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0644\u0627\u0644\u0627 \u06af\u0644\u062f\u0648\u0646\u060c \u0644\u0627 \u0644\u0627 \u0645\u0627\u0647\u06cc-\u0627\u0632 \u0645\u062c\u0645\u0648\u0639\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627\" >\u0644\u0627\u0644\u0627 \u06af\u0644\u062f\u0648\u0646\u060c \u0644\u0627 \u0644\u0627 \u0645\u0627\u0647\u06cc-\u0627\u0632 \u0645\u062c\u0645\u0648\u0639\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0641\u0633\u0627\u0646\u0647 \u0634\u0639\u0628\u0627\u0646\u200c\u0646\u0698\u0627\u062f                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0634\u06a9\u0648\u0641\u0647 \u0627\u0645\u06cc\u0631\u06a9\u0628\u06cc\u0631                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/498\/\u0644\u0627\u0644\u0627-\u06af\u0644\u062f\u0648\u0646\u060c-\u0644\u0627-\u0644\u0627-\u0645\u0627\u0647\u06cc-\u0627\u0632-\u0645\u062c\u0645\u0648\u0639\u0647-\u0644\u0627\u0644\u0627\u06cc\u06cc-\u0647\u0627'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0644\u0627\u0644\u0627 \u06af\u0644\u062f\u0648\u0646\u060c \u0644\u0627 \u0644\u0627 \u0645\u0627\u0647\u06cc-\u0627\u0632 \u0645\u062c\u0645\u0648\u0639\u0647 \u0644\u0627\u0644\u0627\u06cc\u06cc \u0647\u0627\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0627\u0641\u0633\u0627\u0646\u0647 \u0634\u0639\u0628\u0627\u0646\u200c\u0646\u0698\u0627\u062f \u0634\u0627\u0639\u0631 \u0646\u0627\u0645\u200c\u0622\u0634\u0646\u0627\u06cc \u0634\u0639\u0631 \u06a9\u0648\u062f\u06a9 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0644\u0627\u0644\u0627 \u06af\u0644\u062f\u0648\u0646\u060c \u0644\u0627\u0644\u0627 \u0645\u0627\u0647\u06cc \u0627\u0632 \u0639\u0646\u0627\u0635\u0631 \u0637\u0628\u06cc\u0639\u062a \u0628\u0631\u0627\u06cc \u0633\u0631\u0648\u062f\u0646 \u0644\u0627\u0644\u0627\u06cc\u06cc\u200c\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u0639\u0646\u0627\u0635\u0631 \u062f\u0631 \u0634\u0639\u0631 \u0622\u0631\u0627\u0645\u0634\u06cc \u0627\u0632 \u062c\u0646\u0633 \u0637\u0628\u06cc\u0639\u062a \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0628\u0647\u200c\u0627\u0631\u0645\u063a\u0627\u0646 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f.\u00a0<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n                                        <div class=\"relatedpost\">\n                        <div class=\"d-flex align-items-center\">\n                            <img decoding=\"async\" data-src=\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2022\/04\/\u06a9\u062a\u0627\u0628-\u0634\u0639\u0631-\u06a9\u0648\u062f\u06a9.webp\" class=\"relatedimg lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/>\n                            <div class=\"inforelated\">\n                                <p>\n                                    \u062f\u0631 \u0645\u062c\u0644\u0647\u200c\u06cc \u0637\u0627\u0642\u0686\u0647 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:\n                                <\/p>\n                                <a href=\"https:\/\/taaghche.com\/blog\/1401\/01\/13\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%b4%d8%b9%d8%b1-%da%a9%d9%88%d8%aa%d8%a7%d9%87-%da%a9%d9%88%d8%af%da%a9%d8%a7%d9%86%d9%87\/\" target=\"_blank\">                      \n                                    <p class=\"relatedname\">\n                                        \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0634\u0639\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646\u0647                                    <\/p>\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%86%DB%8C_%D9%86%DB%8C_%D9%82%D8%A7%D9%85_%D9%82%D8%A7%D9%85\"><\/span>\u0646\u06cc \u0646\u06cc \u0642\u0627\u0645 \u0642\u0627\u0645<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/141990.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/141990\/\u0646\u06cc-\u0646\u06cc-\u0642\u0627\u0645-\u0642\u0627\u0645\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0646\u06cc \u0646\u06cc \u0642\u0627\u0645 \u0642\u0627\u0645\" >\u0646\u06cc \u0646\u06cc \u0642\u0627\u0645 \u0642\u0627\u0645<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0627\u0631\u0646 \u06a9\u062a\u0633                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0632\u0647\u0631\u0627 \u0645\u0648\u0633\u0648\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0641\u0646\u06cc \u0627\u06cc\u0631\u0627\u0646 (\u06a9\u062a\u0627\u0628 \u0647\u0627\u06cc \u0646\u0631\u062f\u0628\u0627\u0646)                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/141990\/\u0646\u06cc-\u0646\u06cc-\u0642\u0627\u0645-\u0642\u0627\u0645'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0646\u06cc \u0646\u06cc \u0642\u0627\u0645 \u0642\u0627\u0645\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0646\u06cc\u200c\u0646\u06cc \u0642\u0627\u0645\u200c\u0642\u0627\u0645 \u0627\u0632 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062f\u0627\u0644\u06cc\u200c\u0628\u0627\u0632\u06cc \u06a9\u062a\u0627\u0628\u06cc \u0645\u062e\u0635\u0648\u0635 \u0646\u0648\u0632\u0627\u062f \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u0627\u0648 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u062f. \u06a9\u0627\u0631\u0646 \u06a9\u062a\u0633 \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0627 \u0627\u0634\u0639\u0627\u0631 \u06a9\u0648\u062a\u0627\u0647 \u0648 \u062a\u0635\u0627\u0648\u06cc\u0631 \u0631\u0646\u06af\u0627\u0631\u0646\u06af \u0648\u0633\u0627\u06cc\u0644 \u0646\u0642\u0644\u06cc\u0647\u200c \u0631\u0627 \u0628\u0647 \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0648 \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u0646\u0633\u062e\u0647\u200c\u06cc \u0686\u0627\u067e\u06cc \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646 \u0628\u0627 \u0646\u0648\u0632\u0627\u062f \u062a\u0647\u06cc\u0647 \u0634\u0648\u062f \u062a\u0627 \u062a\u0639\u0627\u0645\u0644 \u0628\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0634\u06a9\u0644 \u0635\u0648\u0631\u062a \u06af\u06cc\u0631\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D9%BE%D9%86%D8%AC_%D8%A7%D9%86%DA%AF%D8%B4%D8%AA_%D8%A8%D9%88%D8%AF%D9%86%D8%AF_%DA%A9%D9%87%E2%80%A6_%D8%BA%D8%B0%D8%A7%D9%87%D8%A7_%D9%88_%D8%A8%D8%A7%D8%B2%DB%8C%E2%80%8C%D9%87%D8%A7\"><\/span>\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646\u062f \u06a9\u0647\u2026 (\u063a\u0630\u0627\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u0627\u06af\u0631 \u0628\u0647\u200c\u062f\u0646\u0628\u0627\u0644 <strong>\u06a9\u062a\u0627\u0628 \u06a9\u0648\u062f\u06a9 \u0632\u06cc\u0631 \u06cc\u06a9\u200c\u0633\u0627\u0644\u06cc<\/strong> \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0647\u0645 \u0645\u0648\u0633\u06cc\u0642\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0647\u0645 \u062a\u0631\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0634\u0627\u062f \u0648 \u0647\u0645 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u06a9\u0645\u06a9 \u0622\u0646 \u06cc\u06a9 \u0646\u0645\u0627\u06cc\u0634 \u0627\u0646\u06af\u0634\u062a\u06cc \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f \u0648 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0627\u062c\u0631\u0627 \u06a9\u0646\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646\u062f \u06a9\u0647\u2026 \u06af\u0632\u06cc\u0646\u0647\u200c\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628\u06cc \u0627\u0633\u062a. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062f\u0631\u0628\u0627\u0631\u0647\u200c\u06cc \u063a\u0630\u0627\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627\u0633\u062a.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/40187\/\u067e\u0646\u062c-\u0627\u0646\u06af\u0634\u062a-\u0628\u0648\u062f\u0646\u062f-\u06a9\u0647-\u063a\u0630\u0627\u0647\u0627-\u0648-\u0628\u0627\u0632\u06cc-\u0647\u0627\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646\u062f \u06a9\u0647... (\u063a\u0630\u0627\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627)\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646\u062f \u06a9\u0647&#8230; (\u063a\u0630\u0627\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627)<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/40187.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646\u062f \u06a9\u0647&#8230; (\u063a\u0630\u0627\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627)                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0648\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u06af\u0648\u06cc\u0627                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiZGQ0ODE0YjQtNGVmNy00ZmUyLWFhYjctM2UyYzA2ODkyZWZiIiwiaWF0IjoxNzc4Njk0NDYyLCJleHAiOjUzNzg2OTQ0NjJ9.Ei_bkHujZLWGQ0UbFEDEfk96dgBi7o5a61MWdnB6FFE \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/40187\/\u067e\u0646\u062c-\u0627\u0646\u06af\u0634\u062a-\u0628\u0648\u062f\u0646\u062f-\u06a9\u0647-\u063a\u0630\u0627\u0647\u0627-\u0648-\u0628\u0627\u0632\u06cc-\u0647\u0627'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646\u062f \u06a9\u0647... (\u063a\u0630\u0627\u0647\u0627 \u0648 \u0628\u0627\u0632\u06cc\u200c\u0647\u0627)\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D9%BE%D9%86%D8%AC_%D8%AA%D8%A7_%D8%A7%D9%86%DA%AF%D8%B4%D8%AA_%D8%A8%D9%88%D8%AF%D9%86_%DA%A9%D9%87%E2%80%A6_%D9%85%D8%B1%D8%A7%D8%B3%D9%85_%D9%88_%D8%B4%D8%BA%D9%84%E2%80%8C%D9%87%D8%A7\"><\/span>\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u062a\u0627 \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646 \u06a9\u0647\u2026 (\u0645\u0631\u0627\u0633\u0645 \u0648 \u0634\u063a\u0644\u200c\u0647\u0627)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0646\u06cc\u0632 \u0645\u062b\u0644 \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646\u062f \u06a9\u0647\u2026 \u062a\u0631\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0634\u0627\u062f\u06cc \u0631\u0627 \u062f\u0631\u0628\u0627\u0631\u0647\u200c\u06cc \u0645\u0631\u0627\u0633\u0645 \u0648 \u0634\u063a\u0644\u200c\u0647\u0627 \u0633\u0631\u0648\u062f\u0647 \u0627\u0633\u062a. \u0635\u062f\u0627\u06cc \u06af\u0631\u0645 \u0648 \u062f\u0644\u0646\u0634\u06cc\u0646 \u062e\u0648\u062f \u0646\u0648\u06cc\u0633\u0646\u062f\u0647 \u0627\u0632 \u062f\u06cc\u0631 \u0645\u0632\u06cc\u062a\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0628\u0647\u200c\u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0631\u0648\u062f.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/40186\/\u067e\u0646\u062c-\u062a\u0627-\u0627\u0646\u06af\u0634\u062a-\u0628\u0648\u062f\u0646-\u06a9\u0647-\u0645\u0631\u0627\u0633\u0645-\u0648-\u0634\u063a\u0644-\u0647\u0627\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u062a\u0627 \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646 \u06a9\u0647 ... (\u0645\u0631\u0627\u0633\u0645 \u0648 \u0634\u063a\u0644\u200c\u0647\u0627)\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u062a\u0627 \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646 \u06a9\u0647 &#8230; (\u0645\u0631\u0627\u0633\u0645 \u0648 \u0634\u063a\u0644\u200c\u0647\u0627)<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/40186.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u067e\u0646\u062c \u062a\u0627 \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646 \u06a9\u0647 &#8230; (\u0645\u0631\u0627\u0633\u0645 \u0648 \u0634\u063a\u0644\u200c\u0647\u0627)                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0648\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u06af\u0648\u06cc\u0627                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiMzk2ZTJiYjItMTE1My00M2U0LTg4ZGItYTQwMWUwMTcyNzBhIiwiaWF0IjoxNzc4Njk0NDYzLCJleHAiOjUzNzg2OTQ0NjN9.wojgUa2lH_F818ubLP96KRYfK89WKMKq4fprvMKHvRc \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/40186\/\u067e\u0646\u062c-\u062a\u0627-\u0627\u0646\u06af\u0634\u062a-\u0628\u0648\u062f\u0646-\u06a9\u0647-\u0645\u0631\u0627\u0633\u0645-\u0648-\u0634\u063a\u0644-\u0647\u0627'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u067e\u0646\u062c \u062a\u0627 \u0627\u0646\u06af\u0634\u062a \u0628\u0648\u062f\u0646 \u06a9\u0647 ... (\u0645\u0631\u0627\u0633\u0645 \u0648 \u0634\u063a\u0644\u200c\u0647\u0627)\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%DA%A9%DB%8C_%D8%A8%D9%88%D8%AF%D8%9F_%DA%A9%DB%8C_%D8%A8%D9%88%D8%AF%D8%9F\"><\/span>\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u06a9\u06cc \u0628\u0648\u062f\u061f \u06a9\u06cc \u0628\u0648\u062f\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u0634\u0646\u06cc\u062f\u0646 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0627\u0635\u06cc\u0644 \u0627\u06cc\u0631\u0627\u0646\u06cc \u0627\u0632 \u0632\u0645\u0627\u0646 \u0646\u0648\u0632\u0627\u062f\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u0647\u0645 \u0627\u0646\u062a\u0642\u0627\u0644 \u0641\u0631\u0647\u0646\u06af \u0627\u0633\u062a. \u0627\u06af\u0631 <strong>\u06a9\u062a\u0627\u0628\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0632\u06cc\u0631 \u06cc\u06a9\u200c\u0633\u0627\u0644<\/strong> \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0647 \u06af\u0648\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u0628\u0627 \u0627\u06cc\u0646 \u0645\u06cc\u0631\u0627\u062b \u06af\u0631\u0627\u0646\u200c\u0642\u062f\u0631 \u0622\u0634\u0646\u0627 \u06a9\u0646\u062f \u0648 \u062f\u0631 \u06a9\u0646\u0627\u0631\u0634 \u0634\u0639\u0631\u0647\u0627\u06cc\u06cc \u0627\u0632 \u0634\u0627\u0639\u0631 \u0645\u0634\u0647\u0648\u0631\u06cc \u0686\u0648\u0646 \u0646\u0627\u0635\u0631 \u06a9\u0634\u0627\u0648\u0631\u0632 \u062e\u0648\u0627\u0646\u062f\u0647 \u0634\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u06a9\u06cc\u200c \u0628\u0648\u062f\u061f \u06a9\u06cc \u0628\u0648\u062f\u061f \u0627\u0646\u062a\u062e\u0627\u0628 \u062e\u0648\u0628\u06cc \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u062e\u0648\u0627\u0646\u062f\u0646 \u0634\u0639\u0631\u0647\u0627 \u0627\u0632 \u0633\u0648\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0627\u0632 \u062f\u06cc\u06af\u0631 \u0646\u06a9\u0627\u062a \u062f\u0644\u067e\u0630\u06cc\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0627\u0633\u062a.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/75728\/\u06a9\u06cc-\u0628\u0648\u062f\u061f-\u06a9\u06cc-\u0628\u0648\u062f\u061f\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u06a9\u06cc \u0628\u0648\u062f\u061f \u06a9\u06cc \u0628\u0648\u062f\u061f\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u06a9\u06cc \u0628\u0648\u062f\u061f \u06a9\u06cc \u0628\u0648\u062f\u061f<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/75728.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u06a9\u06cc \u0628\u0648\u062f\u061f \u06a9\u06cc \u0628\u0648\u062f\u061f                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0627\u0635\u0631 \u06a9\u0634\u0627\u0648\u0631\u0632                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06af\u0631\u0648\u0647 \u06af\u0648\u06cc\u0646\u062f\u06af\u0627\u0646                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0648\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u06af\u0648\u06cc\u0627                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiMjA4MzZiNDgtZGFlYS00YWI3LWIxMDEtMDllMDIwMGJlZGVhIiwiaWF0IjoxNzc4Njk0NDYzLCJleHAiOjUzNzg2OTQ0NjN9.PTuvLwCeOzPceewIu6p-G9tFQsDVNeeHjZ_Tva9Mpf0 \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/75728\/\u06a9\u06cc-\u0628\u0648\u062f\u061f-\u06a9\u06cc-\u0628\u0648\u062f\u061f'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u06a9\u06cc \u0628\u0648\u062f\u061f \u06a9\u06cc \u0628\u0648\u062f\u061f\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D8%AE%D9%88%D8%A7%D8%A8_%D9%82%D8%B4%D9%86%DA%AF_%DA%A9%D8%AC%D8%A7%DB%8C%DB%8C%D8%9F\"><\/span>\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062e\u0648\u0627\u0628 \u0642\u0634\u0646\u06af \u06a9\u062c\u0627\u06cc\u06cc\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062e\u0648\u0627\u0628 \u0642\u0634\u0646\u06af \u06a9\u062c\u0627\u06cc\u06cc \u0628\u0627 \u0633\u0631\u0648\u062f\u0647\u200c\u0647\u0627 \u0648 \u0635\u062f\u0627\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646 \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a \u0627\u0632 \u0622\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0622\u0631\u0627\u0645\u0634 \u0648 \u0644\u062d\u0638\u0627\u062a \u062e\u0648\u0628\u06cc \u0631\u0627 \u0628\u0647 \u062e\u0648\u0627\u0628 \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u062f\u0644\u0628\u0646\u062f \u0647\u062f\u06cc\u0647 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/40369\/\u062e\u0648\u0627\u0628-\u0642\u0634\u0646\u06af-\u06a9\u062c\u0627\u06cc\u06cc\u061f\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062e\u0648\u0627\u0628 \u0642\u0634\u0646\u06af \u06a9\u062c\u0627\u06cc\u06cc\u061f\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062e\u0648\u0627\u0628 \u0642\u0634\u0646\u06af \u06a9\u062c\u0627\u06cc\u06cc\u061f<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/40369.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u062e\u0648\u0627\u0628 \u0642\u0634\u0646\u06af \u06a9\u062c\u0627\u06cc\u06cc\u061f                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06af\u0631\u0648\u0647 \u06af\u0648\u06cc\u0646\u062f\u06af\u0627\u0646                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0648\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u06af\u0648\u06cc\u0627                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiN2EzNjFhOTgtNjJlMy00ODI0LWE0MjctZDliMjI4ODY5Mjk5IiwiaWF0IjoxNzc4Njk0NDYzLCJleHAiOjUzNzg2OTQ0NjN9._4Vt70J1UvyLyq_m2xPJQ5x5RrCFo1FeUVE7CcYYElQ \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/40369\/\u062e\u0648\u0627\u0628-\u0642\u0634\u0646\u06af-\u06a9\u062c\u0627\u06cc\u06cc\u061f'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u062e\u0648\u0627\u0628 \u0642\u0634\u0646\u06af \u06a9\u062c\u0627\u06cc\u06cc\u061f\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n                                        <div class=\"relatedpost\">\n                        <div class=\"d-flex align-items-center\">\n                            <img decoding=\"async\" data-src=\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2022\/04\/\u06a9\u062a\u0627\u0628-\u0642\u0635\u0647-\u0647\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646\u0647-\u0628\u0631\u0627\u06cc-\u062e\u0648\u0627\u0628.webp\" class=\"relatedimg lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/>\n                            <div class=\"inforelated\">\n                                <p>\n                                    \u062f\u0631 \u0645\u062c\u0644\u0647\u200c\u06cc \u0637\u0627\u0642\u0686\u0647 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:\n                                <\/p>\n                                <a href=\"https:\/\/taaghche.com\/blog\/1401\/01\/29\/%da%a9%d8%aa%d8%a7%d8%a8-%d9%82%d8%b5%d9%87-%da%a9%d9%88%d8%af%da%a9%d8%a7%d9%86%d9%87-%d8%a8%d8%b1%d8%a7%db%8c-%d8%ae%d9%88%d8%a7%d8%a8\/\" target=\"_blank\">                      \n                                    <p class=\"relatedname\">\n                                        \u0645\u0639\u0631\u0641\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0642\u0635\u0647 \u0647\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646\u0647 \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0628                                    <\/p>\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%D9%82%D8%B5%D9%87_%D9%86%D9%85%D8%A7%DB%8C%D8%B4_%DA%A9%D9%88%D8%AF%DA%A9%D8%A7%D9%86\"><\/span>\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0635\u0647 \u0646\u0645\u0627\u06cc\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u06a9\u0644\u06cc\u0644\u0647 \u0648 \u062f\u0645\u0646\u0647 \u0627\u0632 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u06a9\u0647\u0646 \u0641\u0627\u0631\u0633\u06cc \u0627\u0633\u062a \u0648 \u0686\u0647 \u062e\u0648\u0628 \u0627\u0633\u062a \u0627\u0632 \u0647\u0645\u06cc\u0646 \u062f\u0648\u0631\u0627\u0646 \u0646\u0648\u0632\u0627\u062f\u06cc \u06af\u0648\u0634 \u0628\u0686\u0647\u200c\u0647\u0627 \u0631\u0627 \u0628\u0627 \u0627\u06cc\u0646 \u0642\u0635\u0647\u200c\u0647\u0627 \u0622\u0634\u0646\u0627 \u06a9\u0646\u06cc\u0645. \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0635\u0647 \u0646\u0645\u0627\u06cc\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646 <strong>\u06a9\u062a\u0627\u0628 \u0645\u062e\u0635\u0648\u0635 \u0646\u0648\u0632\u0627\u062f<\/strong> \u0627\u0633\u062a \u06a9\u0647 \u0645\u0647\u0631\u06cc \u0645\u0627\u0647\u0648\u062a\u06cc \u062f\u0631 \u0622\u0646 \u0647\u0641\u062a \u062f\u0627\u0633\u062a\u0627\u0646 \u0635\u0648\u062a\u06cc \u0627\u0632 \u06a9\u0644\u06cc\u0644\u0647 \u0648 \u062f\u0645\u0646\u0647 \u0631\u0627 \u0628\u0647 \u0632\u0628\u0627\u0646 \u06a9\u0648\u062f\u06a9\u0627\u0646\u0647 \u0628\u0627\u0632\u06af\u0648 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0632\u0631\u06af\u200c\u062a\u0631 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u067e\u062e\u0634 \u06a9\u0646\u06cc\u062f.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/49304\/\u0645\u062c\u0645\u0648\u0639\u0647-\u0642\u0635\u0647-\u0646\u0645\u0627\u06cc\u0634-\u06a9\u0648\u062f\u06a9\u0627\u0646\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0635\u0647 \u0646\u0645\u0627\u06cc\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0635\u0647 \u0646\u0645\u0627\u06cc\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/49304.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0635\u0647 \u0646\u0645\u0627\u06cc\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0647\u0631\u06cc \u0645\u0627\u0647\u0648\u062a\u06cc                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06af\u0631\u0648\u0647 \u06af\u0648\u06cc\u0646\u062f\u06af\u0627\u0646                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0633\u0645\u0627\u0648\u0627                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiYmNkOGM4ZTctNTUzOS00ODU1LTllOTctZjc4ZGRkMjkyOTMwIiwiaWF0IjoxNzc4Njk0NDYzLCJleHAiOjUzNzg2OTQ0NjN9.tgBdNHCZB5Tt9d2edK4ZpMGZmhCUHfYzk60Shp_rFTk \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/49304\/\u0645\u062c\u0645\u0648\u0639\u0647-\u0642\u0635\u0647-\u0646\u0645\u0627\u06cc\u0634-\u06a9\u0648\u062f\u06a9\u0627\u0646'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0635\u0647 \u0646\u0645\u0627\u06cc\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%B5%D9%88%D8%AA%DB%8C_%D8%A8%D8%B2_%D8%B2%D9%86%DA%AF%D9%88%D9%84%D9%87%E2%80%8C%D9%BE%D8%A7\"><\/span>\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0628\u0632 \u0632\u0646\u06af\u0648\u0644\u0647\u200c\u067e\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u0628\u0632 \u0632\u0646\u06af\u0648\u0644\u0647\u200c\u067e\u0627 \u0627\u0632 \u0622\u0646 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u062a\u0645\u0627\u0645 \u0628\u0686\u0647\u200c\u0647\u0627\u06cc \u0646\u0633\u0644\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0628\u0627 \u0634\u0646\u06cc\u062f\u0646 \u0622\u0646 \u0628\u0632\u0631\u06af \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0627\u0645\u0627\u0646 \u0628\u0632\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0633\u0647 \u0641\u0631\u0632\u0646\u062f \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u062e\u0627\u0646\u0647 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f \u0648 \u06af\u0631\u06af \u0628\u062f\u062c\u0646\u0633 \u0628\u0647\u200c\u0633\u0631\u0627\u063a \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc\u200c\u0631\u0648\u062f. \u0645\u0641\u0627\u0647\u06cc\u0645 \u06af\u0648\u0646\u0627\u06af\u0648\u0646\u06cc \u0686\u0648\u0646 \u0647\u0645\u06a9\u0627\u0631\u06cc\u060c \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062d\u0644 \u0645\u0633\u0626\u0644\u0647 \u0648 \u063a\u0644\u0628\u0647\u200c \u0628\u0631 \u062a\u0631\u0633 \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u062a\u0634\u0648\u06cc\u0642 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0627\u0632 \u0642\u062f\u0631\u062a \u0647\u0648\u0634 \u0648 \u0630\u0647\u0646 \u062e\u0648\u062f \u0628\u0631\u0627\u06cc \u062d\u0644 \u0645\u0634\u06a9\u0644\u0627\u062a \u0628\u0647\u0631\u0647 \u0628\u0628\u0631\u0646\u062f.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/60875\/\u0628\u0632-\u0632\u0646\u06af\u0648\u0644\u0647-\u067e\u0627\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0628\u0632 \u0632\u0646\u06af\u0648\u0644\u0647\u200c\u067e\u0627\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0628\u0632 \u0632\u0646\u06af\u0648\u0644\u0647\u200c\u067e\u0627<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/60875.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u0628\u0632 \u0632\u0646\u06af\u0648\u0644\u0647\u200c\u067e\u0627                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0634\u0628\u0646\u0645 \u0645\u062d\u0645\u062f\u06cc                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0631\u06cc\u0645 \u0647\u0627\u0634\u0645\u06cc                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0642\u0635\u0647\u200c\u0644\u0646\u062f                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiNDQzMDRhNmEtMDEyYS00MmI1LTk3MTgtM2U4NjM4MjFkOTdiIiwiaWF0IjoxNzc4Njk0NDYzLCJleHAiOjUzNzg2OTQ0NjN9.AYPp2w_mTcx5HW2p-H0KK62Ep-48OTKruTvVJ8wuLpw \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/60875\/\u0628\u0632-\u0632\u0646\u06af\u0648\u0644\u0647-\u067e\u0627'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0628\u0632 \u0632\u0646\u06af\u0648\u0644\u0647\u200c\u067e\u0627\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%AA%D8%A7%D8%A8_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D9%88%D8%AF%DA%A9_%DB%8C%DA%A9_%D8%B3%D8%A7%D9%84%D9%87_%D9%88_%D8%AF%D9%88_%D8%B3%D8%A7%D9%84%D9%87\"><\/span>\u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u062f\u0648 \u0633\u0627\u0644\u0647<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634 \u0627\u0632 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a\u060c \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc\u06cc \u0631\u0627 \u06a9\u0647 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u0645\u0646\u0627\u0633\u0628 \u0647\u0633\u062a\u0646\u062f \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.<\/p>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%88%D8%AC%D9%87_%DA%A9%D9%88%DA%86%D9%88%D9%84%D9%88_%D8%AA%DB%8C%E2%80%8C%D8%AA%D8%A7%D9%BE%D8%8C_%D8%AA%DB%8C%E2%80%8C%D8%AA%D8%A7%D9%BE%D8%8C_%D8%A8%D8%AF%D9%88\"><\/span>\u062c\u0648\u062c\u0647 \u06a9\u0648\u0686\u0648\u0644\u0648! \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u0628\u062f\u0648<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/62809.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/62809\/\u062c\u0648\u062c\u0647-\u06a9\u0648\u0686\u0648\u0644\u0648-\u062a\u06cc-\u062a\u0627\u067e\u060c-\u062a\u06cc-\u062a\u0627\u067e\u060c-\u0628\u062f\u0648\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062c\u0648\u062c\u0647 \u06a9\u0648\u0686\u0648\u0644\u0648! \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u0628\u062f\u0648\" >\u062c\u0648\u062c\u0647 \u06a9\u0648\u0686\u0648\u0644\u0648! \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u0628\u062f\u0648<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u062c\u0648\u0631\u062c \u0634\u0627\u0646\u0648\u0646                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0645\u06cc\u0646\u0627 \u067e\u0648\u0631\u0634\u0639\u0628\u0627\u0646\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0627\u0646\u0648\u0646 \u067e\u0631\u0648\u0631\u0634 \u0641\u06a9\u0631\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0648 \u0646\u0648\u062c\u0648\u0627\u0646\u0627\u0646                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/62809\/\u062c\u0648\u062c\u0647-\u06a9\u0648\u0686\u0648\u0644\u0648-\u062a\u06cc-\u062a\u0627\u067e\u060c-\u062a\u06cc-\u062a\u0627\u067e\u060c-\u0628\u062f\u0648'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062c\u0648\u062c\u0647 \u06a9\u0648\u0686\u0648\u0644\u0648! \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u062a\u06cc\u200c\u062a\u0627\u067e\u060c \u0628\u062f\u0648\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0645\u062b\u0644 \u0647\u0631 \u0631\u0648\u0632 \u062f\u06cc\u06af\u0631\u06cc\u060c \u062c\u0648\u062c\u0647 \u06a9\u0648\u0686\u0648\u0644\u0648 \u0647\u0645\u0631\u0627\u0647 \u0645\u0627\u062f\u0631 \u0648 \u0628\u0631\u0627\u062f\u0631\u0634 \u0628\u0631\u0627\u06cc \u062e\u0648\u0631\u062f\u0646 \u062f\u0627\u0646\u0647 \u0628\u0647 \u0628\u0627\u063a \u0631\u0641\u062a\u0647 \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u0646\u0627\u06af\u0647\u0627\u0646 \u0633\u06af \u0628\u0632\u0631\u06af\u06cc \u062c\u0644\u0648\u06cc \u0622\u0646\u200c\u0647\u0627 \u0633\u0628\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062c\u0648\u0631\u062c \u0634\u0627\u0646\u0648\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0642\u062f\u0631\u062a \u062a\u0641\u06a9\u0631 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u067e\u0631\u0631\u0646\u06af \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0632\u0631\u06af\u200c\u062a\u0631 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0632 \u0622\u0646 \u0644\u0630\u062a \u0628\u0628\u0631\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%85%D8%A7%D8%B4%DB%8C%D9%86_%D9%87%D8%A7\"><\/span>\u0645\u0627\u0634\u06cc\u0646 \u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/198351.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/198351\/\u0645\u0627\u0634\u06cc\u0646-\u0647\u0627\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0645\u0627\u0634\u06cc\u0646 \u0647\u0627\" >\u0645\u0627\u0634\u06cc\u0646 \u0647\u0627<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u062c\u06cc\u0644 \u0645\u06a9 \u062f\u0648\u0646\u0627\u0644\u062f                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0622\u0646\u0627\u0647\u06cc\u062a\u0627 \u062d\u0636\u0631\u062a\u06cc \u06a9\u06cc\u0627\u0648\u0646\u062f\u0627\u0646\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/198351\/\u0645\u0627\u0634\u06cc\u0646-\u0647\u0627'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0645\u0627\u0634\u06cc\u0646 \u0647\u0627\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0639\u0644\u0627\u0642\u0647 \u0628\u0647 \u0645\u0641\u0627\u0647\u06cc\u0645 \u0639\u0644\u0645\u06cc \u06af\u0627\u0647\u06cc \u0627\u0632 \u0647\u0645\u0627\u0646 \u0633\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u06af\u06cc \u0648 \u062f\u0648\u0633\u0627\u0644\u06af\u06cc \u062e\u0648\u062f\u0634 \u0631\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u06af\u0631 \u0628\u0647\u200c\u200c\u062f\u0646\u0628\u0627\u0644 \u06a9\u062a\u0627\u0628 \u0645\u062e\u0635\u0648\u0635 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0628\u0647 \u0645\u0641\u0627\u0647\u06cc\u0645 \u0639\u0644\u0645\u06cc \u0628\u067e\u0631\u062f\u0627\u0632\u062f \u06a9\u062a\u0627\u0628 \u0645\u0627\u0634\u06cc\u0646\u200c\u0647\u0627 \u0627\u0632 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0633\u0644\u0627\u0645 \u062f\u0646\u06cc\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0646\u0627\u0633\u0628\u06cc \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u062c\u06cc\u0644 \u0645\u06a9 \u062f\u0648\u0646\u0627\u0644\u062f \u0628\u0627 \u0632\u0628\u0627\u0646 \u0633\u0627\u062f\u0647 \u0648 \u0628\u06cc\u0627\u0646\u06cc \u062f\u0627\u0633\u062a\u0627\u0646\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u0628\u0627 \u062f\u0646\u06cc\u0627\u06cc \u0645\u0627\u0634\u06cc\u0646\u200c\u0647\u0627 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%D9%86%DB%8C%E2%80%8C%D9%86%DB%8C%E2%80%8C%D9%87%D8%A7\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647 \u0646\u06cc\u200c\u0646\u06cc\u200c\u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u0627\u0641\u0633\u0627\u0646\u0647 \u0634\u0639\u0628\u0627\u0646\u200c\u0646\u0698\u0627\u062f \u062f\u0631 <a href=\"https:\/\/taaghche.com\/filter?filter-label=3753&amp;order=undefined\">\u0645\u062c\u0645\u0648\u0639\u0647 \u06a9\u062a\u0627\u0628 \u0646\u06cc\u200c\u0646\u06cc\u200c\u0647\u0627<\/a> \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u0622\u0647\u0646\u06af\u06cc\u0646 \u0648 \u062e\u06cc\u0627\u0644\u200c\u0627\u0646\u06af\u06cc\u0632\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062e\u0644\u0642 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0633\u0647 \u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u0646\u06cc\u200c\u0646\u06cc \u062f\u062e\u062a\u0631\u0647\u0627 \u0648 \u0633\u0647 \u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u0646\u06cc\u200c\u0646\u06cc \u067e\u0633\u0631\u0647\u0627 \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0634\u0627\u0645\u0644 <strong>\u06a9\u062a\u0627\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647<\/strong> \u0627\u0633\u062a \u0648 \u062d\u062a\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062f\u0648\u0633\u0627\u0644\u0647 \u0646\u06cc\u0632 \u0627\u0632 \u0634\u0646\u06cc\u062f\u0646 \u0622\u0646 \u0644\u0630\u062a \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0631\u062f.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/69068\/\u0646\u06cc-\u0646\u06cc-\u0647\u0627-\u0648-\u0627\u062c\u06cc-\u0645\u062c\u06cc\u061b-\u0646\u06cc-\u0646\u06cc-\u062f\u062e\u062a\u0631\u06cc-\u062c\u0644\u062f-\u0627\u0648\u0644\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0646\u06cc\u200c\u0646\u06cc\u200c\u0647\u0627 \u0648 \u0627\u062c\u06cc \u0645\u062c\u06cc\u061b \u0646\u06cc\u200c\u0646\u06cc \u062f\u062e\u062a\u0631\u06cc (\u062c\u0644\u062f \u0627\u0648\u0644)\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0646\u06cc\u200c\u0646\u06cc\u200c\u0647\u0627 \u0648 \u0627\u062c\u06cc \u0645\u062c\u06cc\u061b \u0646\u06cc\u200c\u0646\u06cc \u062f\u062e\u062a\u0631\u06cc (\u062c\u0644\u062f \u0627\u0648\u0644)<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/69068.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u0646\u06cc\u200c\u0646\u06cc\u200c\u0647\u0627 \u0648 \u0627\u062c\u06cc \u0645\u062c\u06cc\u061b \u0646\u06cc\u200c\u0646\u06cc \u062f\u062e\u062a\u0631\u06cc (\u062c\u0644\u062f \u0627\u0648\u0644)                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0641\u0633\u0627\u0646\u0647 \u0634\u0639\u0628\u0627\u0646\u200c\u0646\u0698\u0627\u062f                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0633\u062d\u0631 \u0628\u06cc\u0631\u0627\u0646\u0648\u0646\u062f                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0633\u0645\u0627\u0648\u0627                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiMDFjNzIyMGYtNWI5Yi00NzFhLWI4NGMtZWZlYzBiNTZiNTFhIiwiaWF0IjoxNzc4Njk0NDY0LCJleHAiOjUzNzg2OTQ0NjR9.4TJN3IMMDgq6wZGske-o4tOKe93P_gTvM73KEV93ZMM \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/69068\/\u0646\u06cc-\u0646\u06cc-\u0647\u0627-\u0648-\u0627\u062c\u06cc-\u0645\u062c\u06cc\u061b-\u0646\u06cc-\u0646\u06cc-\u062f\u062e\u062a\u0631\u06cc-\u062c\u0644\u062f-\u0627\u0648\u0644'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0646\u06cc\u200c\u0646\u06cc\u200c\u0647\u0627 \u0648 \u0627\u062c\u06cc \u0645\u062c\u06cc\u061b \u0646\u06cc\u200c\u0646\u06cc \u062f\u062e\u062a\u0631\u06cc (\u062c\u0644\u062f \u0627\u0648\u0644)\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%86%DB%8C_%D9%86%DB%8C_%DA%A9%D9%88%DA%86%D9%88%D9%84%D9%88\"><\/span>\u0646\u06cc \u0646\u06cc \u06a9\u0648\u0686\u0648\u0644\u0648<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/117532.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/117532\/\u0646\u06cc-\u0646\u06cc-\u06a9\u0648\u0686\u0648\u0644\u0648\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0646\u06cc \u0646\u06cc \u06a9\u0648\u0686\u0648\u0644\u0648\" >\u0646\u06cc \u0646\u06cc \u06a9\u0648\u0686\u0648\u0644\u0648<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0631\u0627\u0628\u06cc\u0646 \u0628\u0627\u0644\u0627\u0631\u062f                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0633\u0631\u0648\u0634 \u062e\u0627\u0648\u0631\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0641\u0646\u06cc \u0627\u06cc\u0631\u0627\u0646 (\u06a9\u062a\u0627\u0628 \u0647\u0627\u06cc \u0646\u0631\u062f\u0628\u0627\u0646)                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/117532\/\u0646\u06cc-\u0646\u06cc-\u06a9\u0648\u0686\u0648\u0644\u0648'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0646\u06cc \u0646\u06cc \u06a9\u0648\u0686\u0648\u0644\u0648\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u06af\u0627\u0647\u06cc \u0648\u0627\u0644\u062f\u06cc\u0646 \u0646\u06af\u0631\u0627\u0646 \u0631\u0641\u062a\u0627\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647\u200c\u06cc \u062e\u0648\u062f \u0628\u0627 \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0647\u0633\u062a\u0646\u062f. \u06a9\u062a\u0627\u0628 \u0646\u06cc\u200c\u0646\u06cc \u06a9\u0648\u0686\u0648\u0644\u0648 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u062a\u0631\u0628\u06cc\u062a \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0627\u0633\u062a. \u0631\u0627\u0628\u06cc\u0646 \u0628\u0627\u0644\u0627\u0631\u062f \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0648\u0627\u062c\u0647\u0647\u200c\u06cc \u067e\u0633\u0631\u0628\u0686\u0647\u200c\u0627\u06cc \u0631\u0627 \u0628\u0627 \u0646\u0648\u0632\u0627\u062f \u062a\u0627\u0632\u0647\u200c\u0648\u0627\u0631\u062f \u0631\u0648\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0634\u0646\u0627\u062e\u062a \u0648 \u0647\u0645\u0631\u0627\u0647\u06cc \u0628\u0627 \u0646\u0648\u0632\u0627\u062f \u0628\u0627 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc\u06cc \u0631\u0648\u0628\u0647\u200c\u0631\u0648 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D8%A7%DA%98%D8%AF%D9%87%D8%A7_%D9%88_%D8%AF%D8%B3%D8%AA%D8%B4%D9%88%DB%8C%DB%8C_%D8%B1%D9%81%D8%AA%D9%86\"><\/span>\u0627\u0698\u062f\u0647\u0627 \u0648 \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc \u0631\u0641\u062a\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u0627\u0646\u062f\u06cc \u06cc\u06a9 \u0627\u0698\u062f\u0647\u0627 \u06a9\u0648\u0686\u0648\u0644\u0648 \u0628\u0647 \u0627\u0633\u0645 \u062f\u06cc\u06af\u06cc\u200c\u062f\u0648\u0648 \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0631\u0628\u0627\u0646 \u0627\u0633\u062a. \u0627\u0633\u062a\u06cc\u0648 \u0647\u0631\u0645\u0646 \u062f\u0631 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0627\u0698\u062f\u0647\u0627\u06cc \u0645\u0646 \u062f\u0631 \u062a\u0642\u0627\u0628\u0644 \u0627\u06cc\u0646 \u062f\u0648 \u0634\u062e\u0635\u06cc\u062a \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u0631\u0627 \u0628\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0622\u0645\u0648\u0632\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0628\u0647 \u0645\u0648\u0636\u0648\u0639 \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc\u200c\u200c\u0631\u0641\u062a\u0646 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u062f. \u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062f\u0631 \u0634\u0631\u0648\u0639 \u062f\u0648 \u0633\u0627\u0644\u06af\u06cc \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0627\u0632 \u0645\u0633\u06cc\u0631 \u0631\u0634\u062f\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0637\u06cc \u06a9\u0646\u0646\u062f.<\/p>\n\n\n\n\n<p class=\"audiobook_link\">\n    \u0628\u062e\u0634\u06cc \u0627\u0632\n    <a href=\"https:\/\/taaghche.com\/audiobook\/96983\/\u0627\u0698\u062f\u0647\u0627-\u0648-\u062f\u0633\u062a\u0634\u0648\u06cc\u06cc-\u0631\u0641\u062a\u0646\" title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0627\u0698\u062f\u0647\u0627 \u0648 \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc \u0631\u0641\u062a\u0646\">\u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0627\u0698\u062f\u0647\u0627 \u0648 \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc \u0631\u0641\u062a\u0646<\/a> \u0631\u0627 \u0628\u0634\u0646\u0648\u06cc\u062f.\n<\/p>\n<div class=\"audio\">\n    <div class=\"infobox\">\n        <div class=\"pic\">\n            <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/audioCover\/96983.jpg\" alt=\"\" class=\"cover lazyload\"  src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n        <\/div>\n        <div class=\"book d-flex\">\n            <div class=\"text\">\n                <p class=\"audiobook_title\">\n                    \u0627\u0698\u062f\u0647\u0627 \u0648 \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc \u0631\u0641\u062a\u0646                <\/p>\n                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0633\u062a\u06cc\u0648 \u0647\u0631\u0645\u0646                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u06af\u0648\u06cc\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0628\u06cc\u0646\u0627 \u0686\u06cc\u062a\u200c\u0633\u0627\u0632\u0627\u0646                    <\/span>\n                <\/p>\n                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u062a\u0631\u0627\u0646\u0647 \u067e\u062f\u0631\u0627\u0645                    <\/span>\n                <\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"actions_container\">\n        <div class=\"ready-player-1 player\">\n            <audio>\n                <source src=\"https:\/\/download.taaghche.com\/v2\/download\/eyJhbGciOiJIUzI1NiJ9.eyJoIjoiNmYxNzE0YTYtYmZkMi00NWVkLTk5MzMtYzIwMmZmMGRmYzM5IiwiaWF0IjoxNzc4Njk0NDY0LCJleHAiOjUzNzg2OTQ0NjR9.e7xlzITBMRSGOPuob0rqNhsfXgRuh8cI2I06glsMl6Q \" type=\"audio\/mpeg\">\n            <\/audio>\n\n        <\/div>\n\n        <button type=\"button\" onclick=\"window.location.href='https:\/\/taaghche.com\/audiobook\/96983\/\u0627\u0698\u062f\u0647\u0627-\u0648-\u062f\u0633\u062a\u0634\u0648\u06cc\u06cc-\u0631\u0641\u062a\u0646'\"\n            class=\"link\"                \n            aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc \u0627\u0698\u062f\u0647\u0627 \u0648 \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc \u0631\u0641\u062a\u0646\"\n        >\n            \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0635\u0648\u062a\u06cc\n        <\/button>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%87%D8%B1_%D8%AC%D8%A7%DB%8C%DB%8C_%D8%AC%DB%8C%D8%B4_%D9%86%DA%A9%D9%86\"><\/span>\u0647\u0631 \u062c\u0627\u06cc\u06cc \u062c\u06cc\u0634 \u0646\u06a9\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/123345.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/123345\/\u0647\u0631-\u062c\u0627\u06cc\u06cc-\u062c\u06cc\u0634-\u0646\u06a9\u0646\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0647\u0631 \u062c\u0627\u06cc\u06cc \u062c\u06cc\u0634 \u0646\u06a9\u0646\" >\u0647\u0631 \u062c\u0627\u06cc\u06cc \u062c\u06cc\u0634 \u0646\u06a9\u0646<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0639\u0635\u0648\u0645\u0647 \u0645\u062d\u0645\u062f\u067e\u0648\u0631                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0622\u0628\u0633\u062a\u0627                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/123345\/\u0647\u0631-\u062c\u0627\u06cc\u06cc-\u062c\u06cc\u0634-\u0646\u06a9\u0646'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0647\u0631 \u062c\u0627\u06cc\u06cc \u062c\u06cc\u0634 \u0646\u06a9\u0646\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u0628\u062e\u0634 \u062d\u06cc\u0627\u062a\u06cc \u0632\u0646\u062f\u06af\u06cc \u0627\u0633\u062a. \u0645\u0639\u0635\u0648\u0645\u0647 \u0645\u062d\u0645\u062f\u067e\u0648\u0631 \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0647\u0631 \u062c\u0627\u06cc\u06cc \u062c\u06cc\u0634 \u0646\u06a9\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0642\u0627\u0644\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0622\u0645\u0648\u0632\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f. \u062e\u0631\u0633\u06cc \u0648 \u0647\u0627\u067e\u0648 \u0648 \u0631\u0648\u0628\u0627\u0647 \u0648 \u0645\u06cc\u0645\u0648\u0646 \u062f\u0631 \u062c\u0646\u06af\u0644 \u0645\u0634\u063a\u0648\u0644 \u0628\u0627\u0632\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062e\u0631\u0633\u06cc \u0628\u0647\u200c\u062e\u0627\u0637\u0631 \u062a\u0646\u0628\u0644\u06cc \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0646\u0628\u0627\u06cc\u062f \u062c\u06cc\u0634 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0646\u06cc\u0632 \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646 \u0628\u0627 \u06a9\u0648\u062f\u06a9\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0648 \u0633\u0627\u0644\u06af\u06cc \u0631\u0627 \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0647\u0631 \u0632\u0645\u0627\u0646 \u06a9\u0647 \u0627\u0632 \u067e\u0648\u0634\u06a9 \u06af\u0631\u0641\u062a\u0647 \u0634\u062f\u0646\u062f \u0627\u06cc\u0646 \u0645\u0641\u0647\u0648\u0645 \u062f\u0631 \u0630\u0647\u0646\u0634\u0627\u0646 \u0634\u06a9\u0644 \u06af\u0631\u0641\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%B2%D8%B1%D9%86%DA%AF_%D8%AA%D8%B1_%D8%A7%D8%B2_%D8%AC%DB%8C%D8%B4_%D9%88_%D9%BE%DB%8C_%D9%BE%DB%8C\"><\/span>\u0632\u0631\u0646\u06af \u062a\u0631 \u0627\u0632 \u062c\u06cc\u0634 \u0648 \u067e\u06cc \u067e\u06cc!<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/137218.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/137218\/\u0632\u0631\u0646\u06af-\u062a\u0631-\u0627\u0632-\u062c\u06cc\u0634-\u0648-\u067e\u06cc-\u067e\u06cc\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0632\u0631\u0646\u06af \u062a\u0631 \u0627\u0632 \u062c\u06cc\u0634 \u0648 \u067e\u06cc \u067e\u06cc!\" >\u0632\u0631\u0646\u06af \u062a\u0631 \u0627\u0632 \u062c\u06cc\u0634 \u0648 \u067e\u06cc \u067e\u06cc!<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0644\u0648\u0631\u0627 \u06cc\u0627\u0646\u0627                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0647\u0627\u06cc\u062f\u0647 \u0639\u0628\u062f\u0627\u0644\u062d\u0633\u06cc\u0646 \u0632\u0627\u062f\u0647                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0641\u0646\u06cc \u0627\u06cc\u0631\u0627\u0646 (\u06a9\u062a\u0627\u0628 \u0647\u0627\u06cc \u0646\u0631\u062f\u0628\u0627\u0646)                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/137218\/\u0632\u0631\u0646\u06af-\u062a\u0631-\u0627\u0632-\u062c\u06cc\u0634-\u0648-\u067e\u06cc-\u067e\u06cc'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0632\u0631\u0646\u06af \u062a\u0631 \u0627\u0632 \u062c\u06cc\u0634 \u0648 \u067e\u06cc \u067e\u06cc!\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0627\u06af\u0631 \u062f\u0631 \u0645\u0631\u062d\u0644\u0647\u200c\u0627\u06cc \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u067e\u0648\u0634\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f \u062a\u0627 \u0627\u06cc\u0646 \u0641\u0631\u0627\u06cc\u0646\u062f \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0633\u067e\u0631\u06cc \u06a9\u0646\u06cc\u062f. \u062c\u0648\u0644\u06cc\u0627 \u06a9\u0648\u06a9 \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0627 \u0646\u06af\u0627\u0647\u06cc \u0637\u0646\u0632\u060c \u062e\u0644\u0627\u0642 \u0648 \u0628\u0627\u0632\u06cc\u200c\u06af\u0648\u0646\u0647 \u0628\u0647 \u0628\u0686\u0647\u200c\u0647\u0627 \u06cc\u0627\u062f \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u06cc\u06a9 \u062a\u0648\u0627\u0644\u062a\u200c\u0631\u0648\u06cc \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0634\u0648\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%A7%DB%8C%D9%86_%DA%A9%D8%A7%D8%B1%D8%A7_%DA%A9%D8%A7%D8%B1_%D8%AC%DB%8C%D8%B4%D9%87\"><\/span>\u0627\u06cc\u0646 \u06a9\u0627\u0631\u0627 \u06a9\u0627\u0631 \u062c\u06cc\u0634\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/200111.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/200111\/\u0627\u06cc\u0646-\u06a9\u0627\u0631\u0627-\u06a9\u0627\u0631-\u062c\u06cc\u0634\u0647\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0627\u06cc\u0646 \u06a9\u0627\u0631\u0627 \u06a9\u0627\u0631 \u062c\u06cc\u0634\u0647\" >\u0627\u06cc\u0646 \u06a9\u0627\u0631\u0627 \u06a9\u0627\u0631 \u062c\u06cc\u0634\u0647<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0632\u0647\u0631\u0627 \u0645\u0648\u0633\u0648\u06cc                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0645\u0647\u0631\u0633\u062a\u0627\u0646                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/200111\/\u0627\u06cc\u0646-\u06a9\u0627\u0631\u0627-\u06a9\u0627\u0631-\u062c\u06cc\u0634\u0647'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0627\u06cc\u0646 \u06a9\u0627\u0631\u0627 \u06a9\u0627\u0631 \u062c\u06cc\u0634\u0647\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0632\u0647\u0631\u0627 \u0645\u0648\u0633\u0648\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0627 \u0632\u0628\u0627\u0646 \u0634\u0639\u0631 \u0642\u0627\u0646\u0648\u0646\u200c\u0647\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0631\u0628\u0627\u0631\u0647\u200c\u06cc \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc\u200c\u0631\u0641\u062a\u0646 \u0628\u0631\u0627\u06cc \u0628\u0686\u0647\u200c\u0647\u0627 \u0628\u06cc\u0627\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06af\u0631 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0631\u0627 \u06a9\u0645\u200c\u06a9\u0645 \u0628\u0627 \u0641\u0631\u0627\u06cc\u0646\u062f \u062f\u0633\u062a\u0634\u0648\u06cc\u06cc\u200c\u0631\u0641\u062a\u0646 \u0648 \u0642\u0648\u0627\u0646\u06cc\u0646 \u0622\u0646 \u0622\u0634\u0646\u0627 \u06a9\u0646\u06cc\u062f \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0633\u06cc\u0627\u0631 \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%AE%D8%B1%DA%AF%D9%88%D8%B4%DA%A9_%D9%BE%DB%8C_%D9%BE%DB%8C_%D9%85%DB%8C_%DA%A9%D9%86%D8%AF\"><\/span>\u062e\u0631\u06af\u0648\u0634\u06a9 \u067e\u06cc \u067e\u06cc \u0645\u06cc \u06a9\u0646\u062f!<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/166662.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/166662\/\u062e\u0631\u06af\u0648\u0634\u06a9-\u067e\u06cc-\u067e\u06cc-\u0645\u06cc-\u06a9\u0646\u062f\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062e\u0631\u06af\u0648\u0634\u06a9 \u067e\u06cc \u067e\u06cc \u0645\u06cc \u06a9\u0646\u062f!\" >\u062e\u0631\u06af\u0648\u0634\u06a9 \u067e\u06cc \u067e\u06cc \u0645\u06cc \u06a9\u0646\u062f!<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0631\u06cc\u0633\u062a\u06cc\u0646 \u062c\u0648\u0646\u0632                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u06af\u06cc\u062a\u06cc \u062e\u0627\u0645\u0646\u0647                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u06a9\u062a\u0627\u0628 \u067e\u0627\u0631\u06a9                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/166662\/\u062e\u0631\u06af\u0648\u0634\u06a9-\u067e\u06cc-\u067e\u06cc-\u0645\u06cc-\u06a9\u0646\u062f'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062e\u0631\u06af\u0648\u0634\u06a9 \u067e\u06cc \u067e\u06cc \u0645\u06cc \u06a9\u0646\u062f!\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u062f\u0633\u062a\u0634\u0648\u06cc\u06cc\u200c\u0631\u0641\u062a\u0646 \u0648 \u06a9\u0646\u0627\u0631\u06af\u0630\u0627\u0634\u062a\u0646 \u067e\u0648\u0634\u06a9 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0631\u0627\u062d\u0644 \u0631\u0634\u062f \u0627\u0633\u062a \u06a9\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627\u06cc\u062f \u0622\u0646 \u0631\u0627 \u067e\u0634\u062a\u200c\u0633\u0631 \u0628\u06af\u0630\u0627\u0631\u0646\u062f. \u06a9\u0631\u06cc\u0633\u062a\u06cc\u0646 \u062c\u0648\u0646\u0632 \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062e\u0631\u06af\u0648\u0634\u06a9 \u067e\u06cc\u200c\u067e\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0634\u0646\u0627\u062e\u062a \u0628\u062f\u0646 \u062e\u0648\u062f \u0648 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc\u0634\u0627\u0646 \u0647\u0645\u0631\u0627\u0647\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%82%D8%B5%D9%87_%D9%87%D8%A7%DB%8C%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%DB%B2_%D8%B3%D8%A7%D9%84%D9%87_%D9%87%D8%A7\"><\/span>\u0642\u0635\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/222690.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/222690\/\u0642\u0635\u0647-\u0647\u0627\u06cc\u06cc-\u0628\u0631\u0627\u06cc-\u06f2-\u0633\u0627\u0644\u0647-\u0647\u0627\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0642\u0635\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627\" >\u0642\u0635\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u062c\u0627\u0646 \u0627\u0633\u062a\u06cc\u0645\u0633\u0648\u0646                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0641\u0627\u0637\u0645\u0647 \u0632\u0631\u06af\u0631\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0648\u0633\u0633\u0647 \u0646\u0634\u0631 \u0648 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0630\u06a9\u0631                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/222690\/\u0642\u0635\u0647-\u0647\u0627\u06cc\u06cc-\u0628\u0631\u0627\u06cc-\u06f2-\u0633\u0627\u0644\u0647-\u0647\u0627'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0642\u0635\u0647 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0642\u0635\u0647\u200c\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647\u200c\u0647\u0627 \u0627\u0632 \u062c\u0627\u0646 \u0627\u0633\u062a\u06cc\u0645\u0633\u0648\u0646 \u0634\u0627\u0645\u0644 \u06cc\u0627\u0632\u062f\u0647 \u062f\u0627\u0633\u062a\u0627\u0646 \u06a9\u0648\u062a\u0627\u0647 \u062f\u0631\u0628\u0627\u0631\u0647\u200c\u06cc \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u0627\u0633\u062a. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0686\u06cc\u0632\u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc \u0628\u0627\u06cc\u062f \u0628\u06cc\u0627\u0645\u0648\u0632\u0646\u062f \u0648 \u0627\u06cc\u0646 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647 \u0645\u062b\u0644 \u062f\u0627\u06cc\u0646\u0627\u0633\u0648\u0631\u06cc \u06a9\u0647 \u062d\u0645\u0627\u0645 \u0631\u0627 \u062f\u0648\u0633\u062a \u0646\u062f\u0627\u0631\u062f \u06cc\u0627 \u0628\u0686\u0647 \u0627\u0633\u0628\u200c\u0622\u0628\u06cc\u200c\u0627\u06cc \u06a9\u0647 \u0639\u0627\u0634\u0642 \u0635\u0628\u062d\u0627\u0646\u0647 \u0627\u0633\u062a \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0647\u0645\u0631\u0627\u0647\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u062a\u0631\u0628\u06cc\u062a \u06a9\u0648\u062f\u06a9 \u062f\u0648\u0633\u0627\u0644\u0647 \u0627\u0633\u062a.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%82%D8%B5%D9%87_%D9%87%D8%A7%DB%8C_%DB%B2_%D8%B3%D8%A7%D9%84%D9%87_%D9%87%D8%A7\"><\/span>\u0642\u0635\u0647 \u0647\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/79226.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/79226\/\u0642\u0635\u0647-\u0647\u0627\u06cc-\u06f2-\u0633\u0627\u0644\u0647-\u0647\u0627\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0642\u0635\u0647 \u0647\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627\" >\u0642\u0635\u0647 \u0647\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06af\u0631\u0648\u0647 \u0646\u0648\u06cc\u0633\u0646\u062f\u06af\u0627\u0646 \u0627\u06cc\u06af\u0644\u0648                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0639\u0637\u06cc\u0647 \u0646\u06cc\u06a9\u200c\u0622\u0626\u06cc\u0646 \u06a9\u0648\u067e\u0627\u0626\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u062a\u0627\u0632\u0647\u200c\u0647\u0627                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/79226\/\u0642\u0635\u0647-\u0647\u0627\u06cc-\u06f2-\u0633\u0627\u0644\u0647-\u0647\u0627'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0642\u0635\u0647 \u0647\u0627\u06cc \u06f2 \u0633\u0627\u0644\u0647 \u0647\u0627\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0627\u06af\u0631 \u0628\u0647\u200c\u200c\u062f\u0646\u0628\u0627\u0644 \u06a9\u062a\u0627\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u062f\u0648\u0633\u0627\u0644\u0647 \u0647\u0633\u062a\u06cc\u062f \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u062e\u0648\u0628\u06cc \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0627 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u062e\u06cc\u0627\u0644\u200c\u0627\u0646\u06af\u06cc\u0632\u0634 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u062a\u062e\u06cc\u0644 \u063a\u0631\u0642 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u062a\u062e\u06cc\u0644 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u062a\u0642\u0648\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%DA%AF%D8%B1%DA%AF_%DA%A9%D9%88%DA%86%D9%88%D9%84%D9%88_%D8%AF%DB%8C%DA%AF%D8%B1_%D9%BE%D8%B3%D8%AA%D8%A7%D9%86%DA%A9_%D9%86%D9%85%DB%8C_%D8%AE%D9%88%D8%A7%D9%87%D8%AF\"><\/span>\u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u06cc\u06af\u0631 \u067e\u0633\u062a\u0627\u0646\u06a9 \u0646\u0645\u06cc \u062e\u0648\u0627\u0647\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/214398.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/214398\/\u06af\u0631\u06af-\u06a9\u0648\u0686\u0648\u0644\u0648-\u062f\u06cc\u06af\u0631-\u067e\u0633\u062a\u0627\u0646\u06a9-\u0646\u0645\u06cc-\u062e\u0648\u0627\u0647\u062f\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u06cc\u06af\u0631 \u067e\u0633\u062a\u0627\u0646\u06a9 \u0646\u0645\u06cc \u062e\u0648\u0627\u0647\u062f\" >\u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u06cc\u06af\u0631 \u067e\u0633\u062a\u0627\u0646\u06a9 \u0646\u0645\u06cc \u062e\u0648\u0627\u0647\u062f<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0648\u0631\u06cc\u0627\u0646 \u0644\u0644\u0645\u0627\u0646                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0637\u0647\u0631\u0647 \u062d\u06cc\u062f\u0631\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/214398\/\u06af\u0631\u06af-\u06a9\u0648\u0686\u0648\u0644\u0648-\u062f\u06cc\u06af\u0631-\u067e\u0633\u062a\u0627\u0646\u06a9-\u0646\u0645\u06cc-\u062e\u0648\u0627\u0647\u062f'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u06cc\u06af\u0631 \u067e\u0633\u062a\u0627\u0646\u06a9 \u0646\u0645\u06cc \u062e\u0648\u0627\u0647\u062f\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u06af\u0631\u0641\u062a\u0646 \u067e\u0633\u062a\u0627\u0646\u06a9 \u0627\u0632 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u0647\u0645\u06cc\u0634\u06af\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627\u0633\u062a. \u0647\u0645\u0631\u0627\u0647\u200c\u0634\u062f\u0646 \u0628\u0627 \u06a9\u062a\u0627\u0628 \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u06cc\u06af\u0631 \u067e\u0633\u062a\u0627\u0646\u06a9 \u0646\u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0648 \u062e\u0648\u0627\u0646\u062f\u0646 \u0622\u0646 \u0628\u0631\u0627\u06cc \u0628\u0686\u0647\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u06cc\u0646 \u0641\u0631\u0627\u06cc\u0646\u062f \u0631\u0627 \u0628\u0633\u06cc\u0627\u0631 \u062a\u0633\u0647\u06cc\u0644 \u06a9\u0646\u062f\u061b \u0627\u0632 \u0622\u0646\u200c\u062c\u0627\u06cc\u06cc \u06a9\u0647 \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u0647\u0645 \u0627\u0635\u0644\u0627\u064b \u062f\u0644\u0634 \u0646\u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0627\u06cc\u0646 \u0639\u0627\u062f\u062a \u0631\u0627 \u062a\u0631\u06a9 \u06a9\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%86_%D8%A7%D8%B2_%D9%BE%D8%B3%D8%B4_%D8%A8%D8%B1_%D9%85%DB%8C_%D8%A2%DB%8C%D9%85\"><\/span>\u0645\u0646 \u0627\u0632 \u067e\u0633\u0634 \u0628\u0631 \u0645\u06cc \u0622\u06cc\u0645!<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/208409.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/208409\/\u0645\u0646-\u0627\u0632-\u067e\u0633\u0634-\u0628\u0631-\u0645\u06cc-\u0622\u06cc\u0645\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0645\u0646 \u0627\u0632 \u067e\u0633\u0634 \u0628\u0631 \u0645\u06cc \u0622\u06cc\u0645!\" >\u0645\u0646 \u0627\u0632 \u067e\u0633\u0634 \u0628\u0631 \u0645\u06cc \u0622\u06cc\u0645!<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0644\u0648\u0631\u06cc \u0631\u0627\u06cc\u062a                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0634\u0628\u0646\u0645 \u062d\u06cc\u062f\u0631\u06cc \u067e\u0648\u0631                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0645\u0647\u0631\u0633\u0627                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/208409\/\u0645\u0646-\u0627\u0632-\u067e\u0633\u0634-\u0628\u0631-\u0645\u06cc-\u0622\u06cc\u0645'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0645\u0646 \u0627\u0632 \u067e\u0633\u0634 \u0628\u0631 \u0645\u06cc \u0622\u06cc\u0645!\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0645\u0647\u0645 \u0627\u0633\u062a \u06a9\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u06cc\u0627\u0645\u0648\u0632\u0646\u062f \u0647\u0646\u06af\u0627\u0645 \u0631\u0648\u0628\u0647\u200c\u0631\u0648\u0634\u062f\u0646 \u0628\u0627 \u06cc\u06a9 \u0645\u0634\u06a9\u0644 \u0645\u0648\u0642\u0639\u06cc\u062a \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0628\u0633\u0646\u062c\u0646\u062f \u0648 \u0646\u06af\u0631\u0634 \u062f\u0631\u0633\u062a \u0648 \u0645\u062b\u0628\u062a \u0646\u0633\u0628\u062a \u0628\u0647 \u062e\u0648\u062f \u0648 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u06a9\u062a\u0627\u0628 \u0645\u0646 \u0627\u0632 \u067e\u0633\u0634 \u0628\u0631\u0645\u06cc\u200c\u0622\u06cc\u0645 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0627\u06cc\u0646 \u0646\u06af\u0631\u0634 \u0627\u0632 \u0633\u0646\u06cc\u0646 \u06a9\u0648\u062f\u06a9\u06cc \u0634\u06a9\u0644 \u0628\u06af\u06cc\u0631\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%A7%DB%8C_%D9%88%D8%A7%DB%8C%D8%8C_%DA%AF%D9%85_%D8%B4%D8%AF%D9%85\"><\/span>\u0627\u06cc \u0648\u0627\u06cc\u060c \u06af\u0645 \u0634\u062f\u0645!<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/39662.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/39662\/\u0627\u06cc-\u0648\u0627\u06cc\u060c-\u06af\u0645-\u0634\u062f\u0645\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0627\u06cc \u0648\u0627\u06cc\u060c \u06af\u0645 \u0634\u062f\u0645!\" >\u0627\u06cc \u0648\u0627\u06cc\u060c \u06af\u0645 \u0634\u062f\u0645!<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0633\u062a\u0648\u0627\u0631\u062a \u062c\u06cc. \u0645\u0648\u0631\u0641\u06cc                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0633\u06cc\u0646\u0627 \u0627\u0645\u06cc\u0646\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0641\u0646\u06cc \u0627\u06cc\u0631\u0627\u0646 (\u06a9\u062a\u0627\u0628 \u0647\u0627\u06cc \u0646\u0631\u062f\u0628\u0627\u0646)                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/39662\/\u0627\u06cc-\u0648\u0627\u06cc\u060c-\u06af\u0645-\u0634\u062f\u0645'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0627\u06cc \u0648\u0627\u06cc\u060c \u06af\u0645 \u0634\u062f\u0645!\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u067e\u06cc\u0634\u200c\u0628\u06cc\u0646\u06cc \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0633\u062e\u062a \u0648 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0645\u0648\u0627\u062c\u0647\u0647 \u0628\u0627 \u0622\u0646 \u0627\u0632 \u0646\u06a9\u0627\u062a \u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0645 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646\u06a9\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062f\u0631 \u0628\u0633\u062a\u0631 \u0627\u0645\u0646\u06cc \u0686\u0648\u0646 \u06a9\u062a\u0627\u0628 \u062f\u0631\u0628\u0627\u0631\u0647\u200c\u06cc \u06af\u0645\u200c\u0634\u062f\u0646 \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f \u0628\u062f\u0627\u0646\u0646\u062f \u0628\u0633\u06cc\u0627\u0631 \u0645\u0633\u06cc\u0631 \u0627\u06cc\u0645\u0646\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc \u0648\u0627\u06cc \u06af\u0645 \u0634\u062f\u0645 \u06a9\u062a\u0627\u0628\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0633\u0626\u0644\u0647\u200c\u06cc \u0645\u0647\u0645 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%A7%D8%B2%DB%8C_%D8%A8%D8%A7_%D8%A7%D9%86%DA%AF%D8%B4%D8%AA_%D9%87%D8%A7\"><\/span>\u0628\u0627\u0632\u06cc \u0628\u0627 \u0627\u0646\u06af\u0634\u062a \u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/62576.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/62576\/\u0628\u0627\u0632\u06cc-\u0628\u0627-\u0627\u0646\u06af\u0634\u062a-\u0647\u0627\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0628\u0627\u0632\u06cc \u0628\u0627 \u0627\u0646\u06af\u0634\u062a \u0647\u0627\" >\u0628\u0627\u0632\u06cc \u0628\u0627 \u0627\u0646\u06af\u0634\u062a \u0647\u0627<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0627\u0646\u0648\u0646 \u067e\u0631\u0648\u0631\u0634 \u0641\u06a9\u0631\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0648 \u0646\u0648\u062c\u0648\u0627\u0646\u0627\u0646                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/62576\/\u0628\u0627\u0632\u06cc-\u0628\u0627-\u0627\u0646\u06af\u0634\u062a-\u0647\u0627'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0628\u0627\u0632\u06cc \u0628\u0627 \u0627\u0646\u06af\u0634\u062a \u0647\u0627\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0627\u06af\u0631 \u0628\u0647\u200c\u062f\u0646\u0628\u0627\u0644 \u06a9\u062a\u0627\u0628 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u06a9\u0645\u06a9 \u0622\u0646 \u0628\u0627 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0628\u0627\u0632\u06cc \u06a9\u0646\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0628\u0627\u0632\u06cc \u0628\u0627 \u0627\u0646\u06af\u0634\u062a\u200c\u0647\u0627 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0646\u062f\u0647\u06cc\u062f. \u0645\u0635\u0637\u0641\u06cc \u0631\u062d\u0645\u0627\u0646\u062f\u0648\u0633\u062a \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0627 \u0627\u0644\u0647\u0627\u0645 \u0627\u0632 \u0628\u0627\u0632\u06cc \u0644\u06cc \u0644\u06cc \u0644\u06cc \u0644\u06cc \u062d\u0648\u0636\u06a9 \u0634\u0627\u0646\u0632\u062f\u0647 \u0642\u0635\u0647 \u0631\u0627 \u062f\u0631 \u0642\u0627\u0644\u0628 \u0634\u0639\u0631 \u062e\u0644\u0642 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0627\u0632\u06cc \u0644\u0630\u062a\u200c\u0628\u062e\u0634\u06cc \u0628\u0627 \u0627\u0646\u06af\u0634\u062a\u0627\u0646 \u062f\u0633\u062a \u062a\u0628\u062f\u06cc\u0644 \u0634\u0648\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%A7%D9%84%DB%8C\"><\/span>\u062f\u0627\u0644\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/84539.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/84539\/\u062f\u0627\u0644\u06cc\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062f\u0627\u0644\u06cc\" >\u062f\u0627\u0644\u06cc<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0647\u062f\u06cc \u0645\u0639\u06cc\u0646\u06cc                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0627\u0646\u0648\u0646 \u067e\u0631\u0648\u0631\u0634 \u0641\u06a9\u0631\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0648 \u0646\u0648\u062c\u0648\u0627\u0646\u0627\u0646                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/84539\/\u062f\u0627\u0644\u06cc'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062f\u0627\u0644\u06cc\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u062f\u0627\u0644\u06cc \u06a9\u062a\u0627\u0628\u06cc \u062a\u0635\u0648\u06cc\u0631\u06cc \u0648 \u0628\u062f\u0648\u0646 \u0645\u062a\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0627\u0647\u0645\u06cc\u062a \u0645\u062d\u0628\u062a \u0627\u0634\u0627\u0631\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0627\u0632\u06cc \u062f\u0627\u0644\u06cc \u0631\u0627 \u0628\u0627 \u06a9\u0648\u062f\u06a9 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f \u0648 \u0628\u0647\u200c\u0637\u0648\u0631 \u062e\u0644\u0627\u0642\u0627\u0646\u0647\u200c\u0627\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B1%D8%A7%D9%86%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%DB%8C_%D9%85%DB%8C_%D9%86%DB%8C_%D9%88_%D9%85%D8%A7%D9%85%D8%A7%D9%86%DB%8C\"><\/span>\u062a\u0631\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u06cc \u0645\u06cc \u0646\u06cc \u0648 \u0645\u0627\u0645\u0627\u0646\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/128866.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/128866\/\u0645\u06cc-\u0645\u06cc-\u0646\u06cc-\u0686\u0647-\u062f\u0648\u0633\u062a-\u0646\u0627\u0632\u0646\u06cc\u0646\u06cc\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0645\u06cc \u0645\u06cc \u0646\u06cc \u0686\u0647 \u062f\u0648\u0633\u062a \u0646\u0627\u0632\u0646\u06cc\u0646\u06cc\" >\u0645\u06cc \u0645\u06cc \u0646\u06cc \u0686\u0647 \u062f\u0648\u0633\u062a \u0646\u0627\u0632\u0646\u06cc\u0646\u06cc<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0627\u0635\u0631 \u06a9\u0634\u0627\u0648\u0631\u0632                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0627\u0641\u0642                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/128866\/\u0645\u06cc-\u0645\u06cc-\u0646\u06cc-\u0686\u0647-\u062f\u0648\u0633\u062a-\u0646\u0627\u0632\u0646\u06cc\u0646\u06cc'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0645\u06cc \u0645\u06cc \u0646\u06cc \u0686\u0647 \u062f\u0648\u0633\u062a \u0646\u0627\u0632\u0646\u06cc\u0646\u06cc\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062a\u0631\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u06cc\u200c\u0645\u06cc\u200c\u0646\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u062a\u0631\u0628\u06cc\u062a \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0627\u0633\u062a. \u0646\u0627\u0635\u0631 \u06a9\u0634\u0627\u0648\u0631\u0632 \u0628\u0627 \u0632\u0628\u0627\u0646 \u0634\u0627\u0639\u0631\u0627\u0646\u0647 \u0628\u0647 \u0645\u0648\u0636\u0648\u0639\u0627\u062a\u06cc \u06a9\u0647 \u062f\u063a\u062f\u063a\u0647\u200c\u06cc \u0648\u0627\u0644\u062f\u06cc\u0646 \u062f\u0631 \u062a\u0631\u0628\u06cc\u062a \u0641\u0631\u0632\u0646\u062f\u0634\u0627\u0646 \u0627\u0633\u062a \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u062f. \u0627\u0648 \u0645\u0648\u0636\u0648\u0639\u0627\u062a\u06cc \u0686\u0648\u0646 \u062a\u0645\u06cc\u0632\u06cc\u060c \u062f\u0648\u0633\u062a\u06cc \u0648 \u062f\u0631\u0648\u063a\u200c\u200c\u06af\u0648\u06cc\u06cc \u0631\u0627 \u062f\u0631 \u0642\u0627\u0644\u0628 \u0634\u0639\u0631 \u0628\u06cc\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<p>\u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0645\u062c\u0645\u0648\u0639\u0647 <a href=\"https:\/\/taaghche.com\/filter?filter-label=8714&amp;order=undefined\">\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u06cc \u0645\u06cc \u0646\u06cc<\/a> \u0631\u0627 \u0627\u0632 \u0633\u0627\u06cc\u062a \u0637\u0627\u0642\u0686\u0647 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u0648 \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u0646\u06cc\u062f.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87_%DA%A9%D8%AA%D8%A7%D8%A8%E2%80%8C%D9%87%D8%A7%DB%8C_%DA%AF%D8%B1%D8%AF%D9%88\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u06af\u0631\u062f\u0648<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/195190.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/195190\/\u0633\u0627\u06cc\u0647-\u0645\u0646-\u06a9\u0648\u061f\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0633\u0627\u06cc\u0647 \u0645\u0646 \u06a9\u0648\u061f\" >\u0633\u0627\u06cc\u0647 \u0645\u0646 \u06a9\u0648\u061f<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0647\u0633\u0627 \u0627\u06cc\u0645\u0627\u0646\u06cc                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0645\u0647\u0631\u0633\u0627                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/195190\/\u0633\u0627\u06cc\u0647-\u0645\u0646-\u06a9\u0648\u061f'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0633\u0627\u06cc\u0647 \u0645\u0646 \u06a9\u0648\u061f\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0645\u062c\u0645\u0648\u0639\u0647 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u06af\u0631\u062f\u0648 \u0634\u0627\u0645\u0644 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062d\u0644\u200c\u06a9\u0631\u062f\u0646\u06cc\u200c\u0627\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u0647\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0631\u0627 \u062f\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062a\u0642\u0648\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u067e\u06cc\u062f\u0627\u200c\u06a9\u0631\u062f\u0646 \u062a\u0641\u0627\u0648\u062a\u200c\u0647\u0627\u060c \u062a\u0634\u062e\u06cc\u0635 \u0631\u0646\u06af\u200c\u0647\u0627 \u0648 \u067e\u06cc\u062f\u0627\u06a9\u0631\u062f\u0646 \u0631\u0627\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0642\u062f\u0631\u062a \u062a\u0641\u06a9\u0631 \u0648 \u0631\u0634\u062f \u0630\u0647\u0646\u06cc \u0622\u0646\u200c\u0647\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<p>\u0628\u0631\u0627\u06cc <a href=\"https:\/\/taaghche.com\/label\/%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87-%DA%A9%D8%AA%D8%A7%D8%A8-%D9%87%D8%A7%DB%8C-%DA%AF%D8%B1%D8%AF%D9%88\">\u062f\u0627\u0646\u0644\u0648\u062f \u0645\u062c\u0645\u0648\u0639\u0647 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u06af\u0631\u062f\u0648<\/a> \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0633\u0627\u06cc\u062a \u0637\u0627\u0642\u0686\u0647 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%AA%D8%B9%D8%A7%D9%85%D9%84%DB%8C_%D8%AE%D8%B1%DA%AF%D9%88%D8%B4%DB%8C\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062a\u0639\u0627\u0645\u0644\u06cc \u062e\u0631\u06af\u0648\u0634\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/128590.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/128590\/\u0644\u0627\u0644\u0627-\u06a9\u0646-\u062e\u0631\u06af\u0648\u0634\u06cc\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0644\u0627\u0644\u0627 \u06a9\u0646 \u062e\u0631\u06af\u0648\u0634\u06cc\" >\u0644\u0627\u0644\u0627 \u06a9\u0646 \u062e\u0631\u06af\u0648\u0634\u06cc<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06cc\u0648\u0631\u06af \u0645\u0648\u0644\u0647                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0622\u0646\u0627\u0647\u06cc\u062a\u0627 \u062d\u0636\u0631\u062a\u06cc \u06a9\u06cc\u0627\u0648\u0646\u062f\u0627\u0646\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/128590\/\u0644\u0627\u0644\u0627-\u06a9\u0646-\u062e\u0631\u06af\u0648\u0634\u06cc'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0644\u0627\u0644\u0627 \u06a9\u0646 \u062e\u0631\u06af\u0648\u0634\u06cc\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0645\u062c\u0645\u0648\u0639\u0647 \u062e\u0631\u06af\u0648\u0634\u06cc \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0632 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062a\u0639\u0627\u0645\u0644\u06cc \u0627\u0633\u062a. \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062a\u0639\u0627\u0645\u0644\u06cc \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0631\u0627 \u0628\u0647 \u0645\u0634\u0627\u0631\u06a9\u062a \u0648\u0627\u0645\u06cc\u200c\u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u0646\u06cc\u0632 \u0628\u0633\u06cc\u0627\u0631 \u0644\u0630\u062a\u200c\u0628\u062e\u0634 \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0644\u0627\u0644\u0627 \u06a9\u0646 \u062e\u0631\u06af\u0648\u0634\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627 \u0641\u0631\u0627\u06cc\u0646\u062f \u062e\u0648\u0627\u0628\u06cc\u062f\u0646 \u0622\u0634\u0646\u0627 \u0634\u062f\u0647 \u0648 \u0628\u0627 \u062e\u0631\u06af\u0648\u0634\u06cc \u0647\u0645\u0631\u0627\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u062a\u0627 \u0628\u062e\u0648\u0627\u0628\u062f. \u0645\u062a\u0646 \u0648 \u062a\u0635\u0627\u0648\u06cc\u0631 \u06a9\u062a\u0627\u0628 \u0637\u0648\u0631\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u06a9\u0648\u062f\u06a9 \u062f\u0631 \u0647\u0631 \u0645\u0631\u062d\u0644\u0647 \u0627\u0632 \u0641\u0631\u0627\u06cc\u0646\u062f \u062e\u0648\u0627\u0628\u06cc\u062f\u0646 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0627\u0646\u062c\u0627\u0645 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0628\u0647 \u062e\u0631\u06af\u0648\u0634\u06cc \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062f\u06cc\u06af\u0631 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u06cc\u0639\u0646\u06cc \u06af\u0631\u06cc\u0647 \u0646\u06a9\u0646 \u062e\u0631\u06af\u0648\u0634\u06cc\u060c \u062e\u0631\u06af\u0648\u0634\u06cc \u0632\u0645\u06cc\u0646 \u0645\u06cc\u200c\u062e\u0648\u0631\u062f \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0631\u0627 \u06a9\u0647 \u06a9\u062a\u0627\u0628 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f \u0645\u062b\u0644 \u0641\u0648\u062a\u200c\u06a9\u0631\u062f\u0646 \u062c\u0627\u06cc \u0632\u062e\u0645 \u0648 \u0646\u0627\u0632\u06a9\u0631\u062f\u0646 \u062e\u0631\u06af\u0648\u0634\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u062a\u0627 \u062d\u0627\u0644 \u062e\u0631\u06af\u0648\u0634\u06cc \u062e\u0648\u0628 \u0634\u0648\u062f \u0648 \u062f\u06cc\u06af\u0631 \u06af\u0631\u06cc\u0647 \u0646\u06a9\u0646\u062f. \u0628\u0627 \u06a9\u062a\u0627\u0628 \u0628\u0631\u0648 \u062d\u0645\u0627\u0645 \u062e\u0631\u06af\u0648\u0634\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u06cc\u06a9 \u062a\u062c\u0631\u0628\u0647\u200c\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u0648 \u0644\u0630\u062a\u200c\u0628\u062e\u0634 \u0627\u0632 \u062d\u0645\u0627\u0645\u200c\u0631\u0641\u062a\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u06a9\u062a\u0627\u0628 \u0628\u0647 \u062a\u0642\u0648\u06cc\u062a \u062d\u0631\u06a9\u062a \u0648 \u062a\u062c\u0631\u0628\u0647\u200c\u06cc \u062d\u0633\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062a\u0635\u0627\u0648\u06cc\u0631 \u06a9\u062a\u0627\u0628 \u0646\u06cc\u0632 \u0628\u0633\u06cc\u0627\u0631 \u062f\u0648\u0633\u062a\u200c\u062f\u0627\u0634\u062a\u0646\u06cc \u0647\u0633\u062a\u0646\u062f \u0648 \u0628\u0686\u0647\u200c\u0647\u0627 \u0627\u0632 \u062f\u06cc\u062f\u0646 \u0622\u0646\u200c\u0647\u0627 \u062d\u0633\u0627\u0628\u06cc \u06a9\u06cc\u0641 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D9%82%D9%87%D8%B1%D9%85%D8%A7%D9%86_%D8%B4%D9%86%D9%84%E2%80%8C%D9%BE%D9%88%D8%B4\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0642\u0647\u0631\u0645\u0627\u0646 \u0634\u0646\u0644\u200c\u067e\u0648\u0634<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/116364.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/116364\/\u0642\u0647\u0631\u0645\u0627\u0646-\u0634\u0646\u0644-\u067e\u0648\u0634\u061b-\u0631\u0648\u0632-\u0628\u062f\u0648\u0646-\u067e\u0648\u0634\u06a9\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0642\u0647\u0631\u0645\u0627\u0646 \u0634\u0646\u0644 \u067e\u0648\u0634\u061b \u0631\u0648\u0632 \u0628\u062f\u0648\u0646 \u067e\u0648\u0634\u06a9!\" >\u0642\u0647\u0631\u0645\u0627\u0646 \u0634\u0646\u0644 \u067e\u0648\u0634\u061b \u0631\u0648\u0632 \u0628\u062f\u0648\u0646 \u067e\u0648\u0634\u06a9!<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0644\u06cc\u0632 \u0641\u0644\u0686\u0631                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0622\u0646\u0627\u0647\u06cc\u062a\u0627 \u062d\u0636\u0631\u062a\u06cc \u06a9\u06cc\u0627\u0648\u0646\u062f\u0627\u0646\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/116364\/\u0642\u0647\u0631\u0645\u0627\u0646-\u0634\u0646\u0644-\u067e\u0648\u0634\u061b-\u0631\u0648\u0632-\u0628\u062f\u0648\u0646-\u067e\u0648\u0634\u06a9'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0642\u0647\u0631\u0645\u0627\u0646 \u0634\u0646\u0644 \u067e\u0648\u0634\u061b \u0631\u0648\u0632 \u0628\u062f\u0648\u0646 \u067e\u0648\u0634\u06a9!\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u062f\u0631 \u0645\u062c\u0645\u0648\u0639\u0647 \u0642\u0647\u0631\u0645\u0627\u0646 \u0634\u0646\u0644 \u067e\u0648\u0634 \u0634\u062e\u0635\u06cc\u062a \u0627\u0635\u0644\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u06cc\u06a9 \u0641\u06cc\u0644 \u06a9\u0648\u0686\u0648\u0644\u0648 \u0628\u0647 \u0627\u0633\u0645 \u0644\u0648\u06cc\u06cc \u0627\u0633\u062a. \u0647\u0641\u062a \u06a9\u062a\u0627\u0628 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f\u0647 \u0627\u0633\u062a \u0648 \u0644\u0648\u06cc\u06cc \u062f\u0631 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u06a9\u062a\u0627\u0628 \u0647\u0627 \u0645\u0627\u062c\u0631\u0627\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0644\u0648\u06cc\u06cc \u0645\u062b\u0644 \u0628\u0642\u06cc\u0647 \u0628\u0686\u0647\u200c\u0647\u0627 \u062e\u06cc\u0644\u06cc \u0633\u0631\u06cc\u0639 \u0631\u0634\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0628\u0627\u06cc\u062f \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0646\u062f. \u06af\u0627\u0647\u06cc \u0627\u0632 \u062a\u062c\u0631\u0628\u0647\u200c\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0645\u06cc\u200c\u062a\u0631\u0633\u062f \u0627\u0645\u0627 \u0628\u0639\u062f \u0627\u0632 \u0627\u0645\u062a\u062d\u0627\u0646\u200c\u06a9\u0631\u062f\u0646 \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u062e\u0648\u0634\u0634 \u0645\u06cc\u200c\u0622\u06cc\u062f \u0648 \u0639\u0627\u062f\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0631\u0648\u0632\u06cc \u0645\u06cc\u200c\u0631\u0633\u062f \u06a9\u0647 \u0644\u0648\u06cc\u06cc \u0628\u0627\u06cc\u062f \u067e\u0648\u0634\u06a9 \u0631\u0627 \u06a9\u0646\u0627\u0631 \u0628\u06af\u0630\u0627\u0631\u062f \u06cc\u0627 \u062a\u062e\u062a\u0634 \u0631\u0627 \u0639\u0648\u0636 \u06a9\u0646\u062f \u06cc\u0627 \u062d\u062a\u06cc \u063a\u0630\u0627\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0628\u062e\u0648\u0631\u062f \u06a9\u0647 \u062a\u0627 \u0628\u0647 \u062d\u0627\u0644 \u0646\u062e\u0648\u0631\u062f\u0647 \u0627\u0633\u062a. \u0627\u0648 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0646\u0645\u06cc\u200c\u062f\u0627\u0646\u062f \u0686\u0647 \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646\u200c\u0647\u0627 \u0645\u0648\u0636\u0648\u0639\u0627\u062a\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627 \u0622\u0646\u200c\u0647\u0627 \u0631\u0648\u0628\u0647\u200c\u0631\u0648 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u0628\u0627\u06cc\u062f \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u067e\u0634\u062a \u0633\u0631 \u0628\u06af\u0630\u0627\u0631\u0646\u062f. \u0644\u0648\u06cc\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0648\u0633\u062a \u062e\u0648\u0628\u06cc \u0628\u0631\u0627\u06cc \u0628\u0686\u0647\u200c\u0647\u0627 \u0628\u0627\u0634\u062f \u062a\u0627 \u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u0627\u062d\u0644 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627\u0644\u0627\u06cc \u06f2 \u0633\u0627\u0644 \u0646\u06cc\u0632 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<p>\u0627\u06cc\u0646 <a href=\"https:\/\/taaghche.com\/category\/%DA%A9%D8%AA%D8%A7%D8%A8-%D8%AF%D8%A7%D8%B3%D8%AA%D8%A7%D9%86-%DA%A9%D9%88%D8%AF%DA%A9-%D9%88-%D9%86%D9%88%D8%AC%D9%88%D8%A7%D9%86%D8%A7%D9%86\">\u06a9\u062a\u0627\u0628 \u0642\u0635\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646\u0647<\/a> \u0648 \u0633\u0627\u06cc\u0631 \u062c\u0644\u062f\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0637\u0627\u0642\u0686\u0647 \u062e\u0631\u06cc\u062f \u0648 \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u0646\u06cc\u062f.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D9%85%D8%A7_%D8%A7%DB%8C%D9%86%D8%AC%D8%A7_%D8%B2%D9%86%D8%AF%DA%AF%DB%8C_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%DB%8C%D9%85\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0645\u0627 \u0627\u06cc\u0646\u062c\u0627 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/150487.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/150487\/\u0645\u0627-\u0627\u06cc\u0646\u062c\u0627-\u0632\u0646\u062f\u06af\u06cc-\u0645\u06cc-\u06a9\u0646\u06cc\u0645\u061b-\u0631\u0646\u06af-\u0647\u0627\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0645\u0627 \u0627\u06cc\u0646\u062c\u0627 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645\u061b \u0631\u0646\u06af \u0647\u0627\" >\u0645\u0627 \u0627\u06cc\u0646\u062c\u0627 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645\u061b \u0631\u0646\u06af \u0647\u0627<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0644\u06cc\u0648\u0631 \u062c\u0641\u0631\u0632                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0634\u0628\u0646\u0645 \u062d\u06cc\u062f\u0631\u06cc \u067e\u0648\u0631                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/150487\/\u0645\u0627-\u0627\u06cc\u0646\u062c\u0627-\u0632\u0646\u062f\u06af\u06cc-\u0645\u06cc-\u06a9\u0646\u06cc\u0645\u061b-\u0631\u0646\u06af-\u0647\u0627'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0645\u0627 \u0627\u06cc\u0646\u062c\u0627 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645\u061b \u0631\u0646\u06af \u0647\u0627\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0627\u0644\u06cc\u0648\u0631 \u062c\u0641\u0631\u0632 \u06a9\u062a\u0627\u0628\u06cc \u062f\u0627\u0631\u062f \u0628\u0627 \u0639\u0646\u0648\u0627\u0646 \u0645\u0627 \u0627\u06cc\u0646\u062c\u0627 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645. \u0627\u0648 \u062f\u0631 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0645\u0627 \u0627\u06cc\u0646\u062c\u0627 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0627\u0632 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0686\u0647\u0627\u0631 \u06a9\u062a\u0627\u0628 \u0645\u0641\u0627\u0647\u06cc\u0645\u06cc \u0686\u0648\u0646 \u0639\u062f\u062f\u0647\u0627\u060c \u0631\u0646\u06af\u200c\u0647\u0627\u060c \u062d\u06cc\u0648\u0627\u0646\u200c\u0647\u0627 \u0648 \u0645\u062a\u0636\u0627\u062f\u0647\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u06cc\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u062c\u0641\u0631\u0632 \u062a\u0635\u0648\u06cc\u0631\u06af\u0631\u06cc \u0645\u0627\u0647\u0631\u06cc \u0627\u0633\u062a \u0648 \u0628\u0627 \u062a\u0635\u0648\u06cc\u0631\u06a9\u0631\u062f\u0646 \u0622\u0646\u0686\u0647 \u06a9\u0647 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0627\u0637\u0631\u0627\u0641 \u0648 \u0631\u0648\u06cc \u06a9\u0631\u0647\u200c\u06cc \u0632\u0645\u06cc\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u0628\u0647 \u0622\u0645\u0648\u0632\u0634 \u0627\u06cc\u0646 \u0645\u0641\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06a9\u062a\u0627\u0628 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647\u200c\u06cc \u0645\u0641\u0627\u0647\u06cc\u0645\u06cc \u0686\u0648\u0646 \u062d\u06cc\u0648\u0627\u0646\u200c\u0647\u0627\u060c \u0627\u0639\u062f\u0627\u062f\u060c \u0645\u062a\u0636\u0627\u062f\u0647\u0627 \u0648 \u0631\u0646\u06af\u200c\u0647\u0627 \u0628\u0627\u0634\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%AE%D9%85%DB%8C%D8%B1%DB%8C%E2%80%8C%D9%87%D8%A7\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062e\u0645\u06cc\u0631\u06cc\u200c\u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/150509.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/150509\/\u062e\u0645\u06cc\u0631\u06cc-\u0647\u0627\u061b-\u0627\u062d\u0633\u0627\u0633-\u0647\u0627\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062e\u0645\u06cc\u0631\u06cc \u0647\u0627\u061b \u0627\u062d\u0633\u0627\u0633 \u0647\u0627\" >\u062e\u0645\u06cc\u0631\u06cc \u0647\u0627\u061b \u0627\u062d\u0633\u0627\u0633 \u0647\u0627<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0644\u0627\u0631\u06cc\u0633\u0627 \u0647\u0627\u0646\u0633\u06a9                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0622\u0646\u0627\u0647\u06cc\u062a\u0627 \u062d\u0636\u0631\u062a\u06cc \u06a9\u06cc\u0627\u0648\u0646\u062f\u0627\u0646\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/150509\/\u062e\u0645\u06cc\u0631\u06cc-\u0647\u0627\u061b-\u0627\u062d\u0633\u0627\u0633-\u0647\u0627'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062e\u0645\u06cc\u0631\u06cc \u0647\u0627\u061b \u0627\u062d\u0633\u0627\u0633 \u0647\u0627\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u062f\u0631\u062d\u0627\u0644 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0647\u0633\u062a\u0646\u062f \u062a\u0627 \u062d\u0648\u0627\u0633 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647\u200c\u06a9\u0627\u0631 \u06af\u06cc\u0631\u0646\u062f. \u0645\u062c\u0645\u0648\u0639\u0647 \u062e\u0645\u06cc\u0631\u06cc\u200c\u0647\u0627 \u0628\u0633\u06cc\u0627\u0631 \u062e\u0648\u0628 \u0628\u0647 \u0627\u06cc\u0646 \u0646\u06cc\u0627\u0632 \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a. \u0633\u0647 \u06a9\u062a\u0627\u0628 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0647 \u0645\u0648\u0636\u0648\u0639\u0627\u062a \u0645\u062a\u0636\u0627\u062f\u0647\u0627\u060c \u0627\u062d\u0633\u0627\u0633\u200c\u0647\u0627 \u0648 \u062d\u0631\u06a9\u062a\u200c\u0647\u0627 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u0646\u062f. \u062a\u0635\u0627\u0648\u06cc\u0631 \u0627\u06cc\u0646 \u0633\u0647 \u06a9\u062a\u0627\u0628 \u0628\u0633\u06cc\u0627\u0631 \u0633\u0627\u062f\u0647 \u0648 \u062e\u0644\u0648\u062a \u0647\u0633\u062a\u0646\u062f. \u0628\u0631\u0627\u06cc \u062a\u0635\u0627\u0648\u06cc\u0631 \u0627\u0632 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0634\u0627\u062f\u060c \u0648\u0627\u0636\u062d \u0648 \u062a\u0627 \u062d\u062f\u06cc \u0631\u0648\u0634\u0646 \u0648 \u062a\u06cc\u0631\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u06a9\u0648\u062f\u06a9 \u0628\u0647\u200c\u0631\u0627\u062d\u062a\u06cc \u0628\u062a\u0648\u0627\u0646\u062f \u062d\u0627\u0644\u0627\u062a \u0648 \u0646\u06a9\u0627\u062a \u0645\u0647\u0645 \u0631\u0627 \u0628\u0628\u06cc\u0646\u062f. \u062f\u0631 \u062f\u0648 \u06a9\u062a\u0627\u0628\u06cc \u06a9\u0647 \u0645\u0648\u0636\u0648\u0639\u0627\u062a \u0645\u062a\u0636\u0627\u062f\u0647\u0627 \u0648 \u0627\u062d\u0633\u0627\u0633\u200c\u0647\u0627 \u0645\u0637\u0631\u062d \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0648\u062f\u06a9 \u0628\u0627 \u062f\u06cc\u062f\u0646 \u062a\u0635\u0627\u0648\u06cc\u0631 \u0628\u0627 \u0647\u0631 \u062d\u0633 \u0622\u0634\u0646\u0627 \u0634\u062f\u0647 \u0648 \u0645\u062a\u0636\u0627\u062f\u0647\u0627\u06cc \u0633\u0627\u062f\u0647 \u0631\u0627 \u0645\u06cc\u200c\u0634\u0646\u0627\u0633\u062f. \u0647\u0646\u06af\u0627\u0645 \u062e\u0648\u0627\u0646\u062f\u0646 \u06a9\u062a\u0627\u0628 \u0645\u062a\u0636\u0627\u062f\u0647\u0627 \u0639\u0644\u0627\u0648\u0647\u200c\u0628\u0631 \u062f\u06cc\u062f\u0646 \u062a\u0635\u0627\u0648\u06cc\u0631 \u06a9\u062a\u0627\u0628 \u0622\u0648\u0631\u062f\u0646 \u0645\u062b\u0627\u0644\u200c\u0647\u0627\u06cc \u0639\u06cc\u0646\u06cc \u0648 \u0644\u0645\u0633 \u0622\u0646\u200c\u0647\u0627 \u062a\u0648\u0633\u0637 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645\u06a9\u200c\u06a9\u0646\u0646\u062f\u0647 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u06a9\u062a\u0627\u0628 \u0633\u0648\u0645 \u06a9\u0647 \u062f\u0631\u0628\u0627\u0631\u0647\u200c\u06cc \u062d\u0631\u06a9\u0627\u062a \u0627\u0633\u062a \u0648\u0627\u0631\u062f \u062a\u0639\u0627\u0645\u0644 \u0628\u0627 \u06a9\u0648\u062f\u06a9 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u062a\u0634\u0648\u06cc\u0642 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u062d\u0631\u06a9\u0627\u062a\u06cc \u06a9\u0647 \u06af\u0641\u062a\u0647\u200c\u0634\u062f\u0647 \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f. \u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0628\u0627\u0632\u06cc \u0644\u0630\u062a \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0628\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0647 \u0627\u0631\u0645\u063a\u0627\u0646 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%AF%D9%86%DB%8C%D8%A7%DB%8C_%D9%BE%D9%BE%D8%A7\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062f\u0646\u06cc\u0627\u06cc \u067e\u067e\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/209642.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/209642\/\u067e\u067e\u0627-\u062e\u0648\u0627\u0628\u0634-\u0646\u0645\u06cc-\u0622\u06cc\u062f\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u067e\u067e\u0627 \u062e\u0648\u0627\u0628\u0634 \u0646\u0645\u06cc \u0622\u06cc\u062f\" >\u067e\u067e\u0627 \u062e\u0648\u0627\u0628\u0634 \u0646\u0645\u06cc \u0622\u06cc\u062f<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0627\u0631\u06a9 \u0628\u06cc\u06a9\u0631                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0645\u0647\u0633\u0627 \u062e\u0633\u0631\u0648\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0627\u0641\u0642                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/209642\/\u067e\u067e\u0627-\u062e\u0648\u0627\u0628\u0634-\u0646\u0645\u06cc-\u0622\u06cc\u062f'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u067e\u067e\u0627 \u062e\u0648\u0627\u0628\u0634 \u0646\u0645\u06cc \u0622\u06cc\u062f\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u062f\u0646\u06cc\u0627\u06cc \u067e\u067e\u0627 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0622\u0646 \u067e\u067e\u0627 \u06cc\u06a9 \u0645\u0627\u062c\u0631\u0627\u06cc\u06cc \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc \u0648 \u062f\u063a\u062f\u063a\u0647\u200c\u0647\u0627\u06cc \u0622\u0646 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u06cc\u06a9 \u06a9\u062a\u0627\u0628 \u067e\u067e\u0627 \u0628\u0627\u06cc\u062f \u0628\u0647 \u062f\u0646\u062f\u0627\u0646\u067e\u0632\u0634\u06a9\u06cc \u0628\u0631\u0648\u062f\u060c \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062f\u06cc\u06af\u0631 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0628\u0647 \u0622\u06a9\u0648\u0627\u0631\u06cc\u0648\u0645 \u0628\u0631\u0648\u062f \u0648 \u062f\u0631 \u062c\u0644\u062f\u06cc \u062f\u06cc\u06af\u0631 \u0686\u0634\u0645\u0634 \u0636\u0639\u06cc\u0641 \u0634\u062f\u0647 \u0648 \u0628\u0627\u06cc\u062f \u0639\u06cc\u0646\u06a9 \u0628\u0632\u0646\u062f. \u0628\u062e\u0634\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0634\u0627\u0645\u0644 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0627\u0633\u062a \u0645\u062b\u0644 \u067e\u067e\u0627 \u062e\u0648\u0627\u0628\u0634 \u0646\u0645\u06cc\u200c\u0622\u06cc\u062f \u0648 \u067e\u067e\u0627 \u0628\u0647 \u062a\u0639\u0637\u06cc\u0644\u0627\u062a \u0645\u06cc\u200c\u0631\u0648\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D9%86%DA%AF%D8%A7%D9%87_%DA%A9%D9%86\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0646\u06af\u0627\u0647 \u06a9\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/216697.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/216697\/\u0646\u06af\u0627\u0647-\u06a9\u0646\u060c-\u0645\u0646-\u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0645\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0646\u06af\u0627\u0647 \u06a9\u0646\u060c \u0645\u0646 \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0645\" >\u0646\u06af\u0627\u0647 \u06a9\u0646\u060c \u0645\u0646 \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0645<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0647\u0644\u0646\u0647 \u0647\u06cc\u0644\u062a\u0648\u0646                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0633\u067e\u06cc\u062f\u0647 \u0634\u0647\u06cc\u062f\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0627\u0641\u0642                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/216697\/\u0646\u06af\u0627\u0647-\u06a9\u0646\u060c-\u0645\u0646-\u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0645'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0646\u06af\u0627\u0647 \u06a9\u0646\u060c \u0645\u0646 \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0645\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u062f\u0631 \u067e\u0698\u0648\u0647\u0634\u06cc \u0628\u0631\u0631\u0633\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0634\u0646\u06cc\u062f\u0646 \u0648\u0627\u0698\u06af\u0627\u0646 \u062c\u062f\u06cc\u062f \u0648 \u062d\u062a\u06cc \u0633\u062e\u062a \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0641\u06cc\u062f \u0628\u0627\u0634\u062f. \u0622\u0646\u200c\u0647\u0627 \u0628\u0627 \u0633\u0631\u0639\u062a\u06cc \u0628\u0627\u0648\u0631\u0646\u06a9\u0631\u062f\u0646\u06cc \u0647\u0631 \u0648\u0627\u0698\u06af\u0627\u0646\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u0634\u0646\u0648\u0646\u062f \u0631\u0627 \u062c\u0630\u0628 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u061b \u067e\u0633 \u0686\u0647 \u062e\u0648\u0628 \u0627\u0633\u062a \u062a\u0627 \u0648\u0627\u0698\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0631 \u0645\u0639\u0631\u0636 \u0634\u0646\u06cc\u062f\u0646 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u062f\u0646\u06cc\u0627\u06cc \u0633\u0627\u0644\u0645 \u0648 \u062e\u0648\u0628\u06cc \u062f\u0639\u0648\u062a \u06a9\u0646\u062f. \u0645\u062c\u0645\u0648\u0639\u0647 \u0646\u06af\u0627\u0647 \u06a9\u0646 \u062f\u0631 \u0633\u0647 \u062c\u0644\u062f \u0646\u06af\u0627\u0647 \u06a9\u0646 \u0645\u0646 \u06cc\u06a9 \u0645\u0647\u0646\u062f\u0633\u0645\u060c \u0646\u06af\u0627\u0647 \u06a9\u0646 \u0645\u0646 \u06cc\u06a9 \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0645 \u0648 \u0646\u06af\u0627\u0647 \u06a9\u0646 \u0645\u0646 \u06cc\u06a9 \u0622\u0634\u067e\u0632\u0645\u060c \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u0628\u0647 \u062f\u0646\u06cc\u0627\u06cc \u06a9\u0634\u0641\u060c \u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc \u062c\u0630\u0627\u0628 \u0648 \u062f\u0646\u06cc\u0627\u06cc \u0637\u0639\u0645 \u0648 \u0628\u0648 \u062f\u0639\u0648\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f. \u06a9\u062a\u0627\u0628 \u0645\u0646 \u06cc\u06a9 \u0622\u0634\u067e\u0632\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0633\u062a\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0627\u0634\u062f \u0628\u0631\u0627\u06cc \u0622\u0634\u0646\u0627\u06cc\u06cc \u06a9\u0648\u062f\u06a9 \u0628\u0627 \u062d\u0648\u0627\u0633 \u0686\u0634\u0627\u06cc\u06cc \u0648 \u0628\u0648\u06cc\u0627\u06cc\u06cc \u0628\u0627\u0634\u062f. \u0645\u0646 \u06cc\u06a9 \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0633\u062a\u0631 \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0627\u0634\u062f \u0628\u0631\u0627\u06cc \u06a9\u0634\u0641 \u0645\u062d\u06cc\u0637 \u0627\u0637\u0631\u0627\u0641 \u0648 \u0648\u0633\u0627\u06cc\u0644 \u062c\u062f\u06cc\u062f \u0628\u0627\u0634\u062f \u0648 \u06a9\u0645\u06a9 \u200c\u06a9\u0646\u062f \u062a\u0627 \u062d\u0633 \u0644\u0627\u0645\u0633\u0647\u200c\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062a\u0642\u0648\u06cc\u062a \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627\u0644\u0627\u06cc \u06f2 \u0633\u0627\u0644 \u0646\u06cc\u0632 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%DA%AF%D8%B1%DA%AF%D9%88%D8%B4%DA%A9%D8%9B_%DA%AF%D8%B1%DA%AF_%DA%A9%D9%88%DA%86%D9%88%D9%84%D9%88_%D8%AF%D8%B1_%D8%AE%D8%A7%D9%86%D9%88%D8%A7%D8%AF%D9%87_%D8%AE%D8%B1%DA%AF%D9%88%D8%B4_%D9%87%D8%A7\"><\/span>\u06af\u0631\u06af\u0648\u0634\u06a9\u061b \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062e\u0631\u06af\u0648\u0634 \u0647\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/89074.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/89074\/\u06af\u0631\u06af\u0648\u0634\u06a9\u061b-\u06af\u0631\u06af-\u06a9\u0648\u0686\u0648\u0644\u0648-\u062f\u0631-\u062e\u0627\u0646\u0648\u0627\u062f\u0647-\u062e\u0631\u06af\u0648\u0634-\u0647\u0627\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u06af\u0631\u06af\u0648\u0634\u06a9\u061b \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062e\u0631\u06af\u0648\u0634 \u0647\u0627\" >\u06af\u0631\u06af\u0648\u0634\u06a9\u061b \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062e\u0631\u06af\u0648\u0634 \u0647\u0627<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u06cc\u0645\u06cc \u062f\u0627\u06cc\u06a9\u0645\u0646                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0634\u0628\u0646\u0645 \u062d\u06cc\u062f\u0631\u06cc\u200c\u067e\u0648\u0631                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/89074\/\u06af\u0631\u06af\u0648\u0634\u06a9\u061b-\u06af\u0631\u06af-\u06a9\u0648\u0686\u0648\u0644\u0648-\u062f\u0631-\u062e\u0627\u0646\u0648\u0627\u062f\u0647-\u062e\u0631\u06af\u0648\u0634-\u0647\u0627'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u06af\u0631\u06af\u0648\u0634\u06a9\u061b \u06af\u0631\u06af \u06a9\u0648\u0686\u0648\u0644\u0648 \u062f\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062e\u0631\u06af\u0648\u0634 \u0647\u0627\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0627\u06af\u0631 \u0628\u0647\u200c\u062f\u0646\u0628\u0627\u0644 \u06a9\u062a\u0627\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0628\u0627 \u0645\u0648\u0636\u0648\u0639 \u067e\u0630\u06cc\u0631\u0634 \u0646\u0648\u0632\u0627\u062f \u062c\u062f\u06cc\u062f \u0647\u0633\u062a\u06cc\u062f \u06a9\u062a\u0627\u0628 \u06af\u0631\u06af\u0648\u0634\u06a9 \u06af\u0632\u06cc\u0646\u0647\u200c\u06cc \u062e\u0648\u0628\u06cc \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u0627\u06cc\u0645\u06cc \u062f\u0627\u06cc\u06a9\u0645\u0646 \u062f\u0631 \u06a9\u062a\u0627\u0628 \u06af\u0631\u06af\u0648\u0634\u06a9 \u0645\u0648\u0636\u0648\u0639 \u067e\u0630\u06cc\u0631\u0634 \u062e\u0648\u0627\u0647\u0631 \u06cc\u0627 \u0628\u0631\u0627\u062f\u0631 \u06a9\u0648\u0686\u06a9\u200c\u062a\u0631 \u0631\u0627 \u0645\u0637\u0631\u062d \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0627\u0633\u062a\u0627\u0646 \u06af\u0631\u06af\u0648\u0634\u06a9 \u0627\u0632 \u0631\u0648\u0632\u06cc \u0634\u0631\u0648\u0639 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u06cc\u06a9 \u06af\u0631\u06af \u0646\u0648\u0632\u0627\u062f \u062c\u0644\u0648\u06cc \u062e\u0627\u0646\u0647\u200c\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u06cc \u062e\u0631\u06af\u0648\u0634\u06cc \u067e\u06cc\u062f\u0627\u06cc\u0634 \u0645\u06cc\u200c\u0634\u0648\u062f. \u067e\u062f\u0631 \u0648 \u0645\u0627\u062f\u0631 \u062e\u0631\u06af\u0648\u0634\u06cc \u0627\u0648 \u0631\u0627 \u0628\u0647 \u0641\u0631\u0632\u0646\u062f\u06cc \u0645\u06cc\u200c\u067e\u0630\u06cc\u0631\u0646\u062f \u0627\u0645\u0627 \u062e\u0631\u06af\u0648\u0634\u06cc \u062e\u06cc\u0644\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062c\u0631\u0627 \u062e\u0648\u0634\u062d\u0627\u0644 \u0646\u06cc\u0633\u062a. \u0627\u0648 \u0645\u062f\u0627\u0645 \u0628\u0647 \u067e\u062f\u0631 \u0648 \u0645\u0627\u062f\u0631 \u0648 \u0627\u0637\u0631\u0627\u0641\u06cc\u0627\u0646\u0634 \u06af\u0648\u0634\u0632\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u06af\u0631\u06af\u06cc \u0647\u0645\u0647\u200c\u06cc \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u06cc\u06a9 \u0644\u0642\u0645\u0647\u200c\u06cc \u0686\u067e \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f. \u06af\u0631\u06af\u06cc \u06a9\u0645\u200c\u06a9\u0645 \u0628\u0632\u0631\u06af \u0645\u06cc\u200c\u0634\u0648\u062f\u061b \u0627\u0645\u0627 \u0631\u0627\u0628\u0637\u0647\u200c\u06cc \u062e\u0631\u06af\u0648\u0634\u06cc \u0628\u0627 \u0627\u0648 \u0647\u0645\u0686\u0646\u0627\u0646 \u062e\u0648\u0628 \u0646\u06cc\u0633\u062a. \u062a\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u06cc\u06a9 \u0631\u0648\u0632 \u062e\u0631\u06af\u0648\u0634\u06cc \u0648 \u06af\u0631\u06af\u06cc \u0628\u0627\u06cc\u062f \u0628\u0627 \u0647\u0645 \u0628\u0647 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0628\u0631\u0648\u0646\u062f \u062a\u0627 \u0647\u0648\u06cc\u062c \u0628\u062e\u0631\u0646\u062f. \u0686\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0627\u06af\u0631 \u0628\u0627 \u06cc\u06a9 \u062e\u0631\u0633 \u0628\u0632\u0631\u06af \u0631\u0648\u0628\u0647\u200c\u0631\u0648 \u0634\u0648\u0646\u062f\u061f<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%B4%D8%A7%DB%8C%D8%AF_%D8%B3%DB%8C%D8%A8_%D8%A8%D8%A7%D8%B4%D8%AF\"><\/span>\u0634\u0627\u06cc\u062f \u0633\u06cc\u0628 \u0628\u0627\u0634\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/149504.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/149504\/\u0634\u0627\u06cc\u062f-\u0633\u06cc\u0628-\u0628\u0627\u0634\u062f\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0634\u0627\u06cc\u062f \u0633\u06cc\u0628 \u0628\u0627\u0634\u062f\" >\u0634\u0627\u06cc\u062f \u0633\u06cc\u0628 \u0628\u0627\u0634\u062f<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0634\u06cc\u0646\u0633\u0648\u06a9\u0647 \u06cc\u0648\u0634\u06cc \u062a\u06a9\u0647                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0631\u0636\u06cc \u0647\u06cc\u0631\u0645\u0646\u062f\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0627\u0641\u0642                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/149504\/\u0634\u0627\u06cc\u062f-\u0633\u06cc\u0628-\u0628\u0627\u0634\u062f'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0634\u0627\u06cc\u062f \u0633\u06cc\u0628 \u0628\u0627\u0634\u062f\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u06a9\u062a\u0627\u0628 \u0634\u0627\u06cc\u062f \u0633\u06cc\u0628 \u0628\u0627\u0634\u062f \u062a\u062e\u06cc\u0644 \u0628\u0686\u0647\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u067e\u0631\u0648\u0627\u0632 \u062f\u0631\u0645\u06cc\u200c\u0622\u0648\u0631\u062f. \u0646\u0648\u06cc\u0633\u0646\u062f\u0647 \u0627\u0632 \u06cc\u06a9 \u0633\u06cc\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u062e\u0648\u0627\u0646\u0646\u062f\u0647 \u0631\u0627 \u0648\u0627\u062f\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u062c\u0648\u0631 \u062f\u06cc\u06af\u0631\u06cc \u0628\u0647 \u0622\u0646 \u0646\u06af\u0627\u0647 \u06a9\u0646\u062f. \u0646\u06af\u0627\u0647 \u0645\u062a\u0641\u0627\u0648\u062a \u0628\u0647 \u0627\u0634\u06cc\u0627 \u0627\u0637\u0631\u0627\u0641 \u0628\u0647 \u062a\u0642\u0648\u06cc\u062a \u0642\u0648\u0647\u200c\u06cc \u062a\u062e\u06cc\u0644 \u0648 \u062d\u0644 \u0645\u0633\u0626\u0644\u0647 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0628\u0633\u06cc\u0627\u0631 \u062a\u0645\u0627\u06cc\u0644 \u062f\u0627\u0631\u0646\u062f \u062a\u0627 \u0628\u0627 \u0644\u0645\u0633\u200c\u06a9\u0631\u062f\u0646\u060c \u0627\u0634\u06cc\u0627 \u0627\u0637\u0631\u0627\u0641\u0634\u0627\u0646 \u0631\u0627 \u0628\u0634\u0646\u0627\u0633\u0646\u062f. \u0628\u0627 \u0622\u0646 \u0628\u0627\u0632\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0622\u0646 \u0631\u0627 \u067e\u0631\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u06af\u0627\u0647\u06cc \u0622\u0646 \u0634\u06cc\u0621 \u0631\u0627 \u0628\u0647 \u062f\u0647\u0627\u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u0628\u0631\u0646\u062f. \u06a9\u062a\u0627\u0628 \u0634\u0627\u06cc\u062f \u0633\u06cc\u0628 \u0628\u0627\u0634\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0628\u062f\u06cc\u0644 \u0628\u0647 \u06cc\u06a9 \u0628\u0627\u0632\u06cc \u0628\u0631\u0627\u06cc \u062d\u0633\u200c\u06a9\u0631\u062f\u0646 \u0648 \u0644\u0645\u0633 \u0627\u0634\u06cc\u0627 \u0645\u062e\u062a\u0644\u0641 \u0634\u0648\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%B3%D9%84%D8%A7%D9%85_%D8%AF%D9%86%DB%8C%D8%A7\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0633\u0644\u0627\u0645 \u062f\u0646\u06cc\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/119714.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/119714\/\u062f\u0646\u06cc\u0627\u060c-\u0633\u0644\u0627\u0645\u061b-\u0628\u062f\u0646-\u0645\u0646\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062f\u0646\u06cc\u0627\u060c \u0633\u0644\u0627\u0645\u061b \u0628\u062f\u0646 \u0645\u0646\" >\u062f\u0646\u06cc\u0627\u060c \u0633\u0644\u0627\u0645\u061b \u0628\u062f\u0646 \u0645\u0646<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u062c\u06cc\u0644 \u0645\u06a9 \u062f\u0648\u0646\u0627\u0644\u062f                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0645\u062d\u0645\u062f \u0641\u0627\u0636\u0644\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0641\u0631\u0648\u0627\u06a9                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/119714\/\u062f\u0646\u06cc\u0627\u060c-\u0633\u0644\u0627\u0645\u061b-\u0628\u062f\u0646-\u0645\u0646'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062f\u0646\u06cc\u0627\u060c \u0633\u0644\u0627\u0645\u061b \u0628\u062f\u0646 \u0645\u0646\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u062c\u06cc\u0644 \u0645\u06a9\u200c\u062f\u0648\u0646\u0627\u0644\u062f \u062f\u0631 \u0645\u062c\u0645\u0648\u0639\u0647 \u0633\u0644\u0627\u0645 \u062f\u0646\u06cc\u0627 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc\u06cc \u0631\u0627 \u062e\u0644\u0642 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0637\u0631\u0627\u0641 \u062e\u0648\u062f \u0622\u0634\u0646\u0627 \u0634\u0648\u0646\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0628\u062f\u0646 \u0645\u0646 \u0628\u0686\u0647\u200c\u0647\u0627 \u0628\u0627 \u0627\u062c\u0632\u0627\u06cc \u0628\u062f\u0646 \u0648 \u06a9\u0627\u0631\u06a9\u0631\u062f \u0647\u0631\u06a9\u062f\u0627\u0645 \u0628\u0647\u200c\u0635\u0648\u0631\u062a \u062e\u06cc\u0644\u06cc \u0633\u0627\u062f\u0647 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0628\u0686\u0647\u200c\u0647\u0627\u06cc \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u06cc\u0627\u062f \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f \u06a9\u0647 \u0647\u0645\u0647\u200c\u06cc \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u0645\u062b\u0644 \u0627\u0646\u0633\u0627\u0646\u200c\u0647\u0627 \u0632\u0645\u0627\u0646\u06cc \u0628\u0686\u0647 \u0647\u0633\u062a\u0646\u062f \u0648 \u06a9\u0645\u200c\u06a9\u0645 \u0628\u0632\u0631\u06af \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062f\u0631 \u0645\u0632\u0631\u0639\u0647 \u0628\u0627 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u0627\u0647\u0644\u06cc \u0648 \u0635\u062f\u0627\u06cc \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0622\u0628 \u0648 \u0647\u0648\u0627 \u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0622\u0628 \u0648 \u0647\u0648\u0627\u06cc \u0647\u0631 \u0631\u0648\u0632 \u0631\u0627 \u0628\u0627 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0686\u06a9 \u06a9\u0646\u0646\u062f \u0648 \u062f\u0631\u0628\u0627\u0631\u0647\u200c\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0631 \u0647\u0631 \u0622\u0628 \u0648 \u0647\u0648\u0627 \u0686\u0647 \u0644\u0628\u0627\u0633\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a \u0635\u062d\u0628\u062a \u06a9\u0646\u0646\u062f. \u0628\u0631\u062e\u06cc \u0645\u0639\u062a\u0642\u062f\u0646\u062f \u06a9\u0647 \u06a9\u062a\u0627\u0628\u200c\u200c\u0647\u0627\u06cc \u0645\u062e\u0635\u0648\u0635 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0628\u0627\u06cc\u062f \u0634\u0627\u0645\u0644 \u0645\u0648\u0636\u0648\u0639\u0627\u062a\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0628\u06cc\u0646\u0646\u062f \u0648 \u0644\u0645\u0633 \u06a9\u0646\u0646\u062f\u061b \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648 \u0645\u062c\u0645\u0648\u0639\u0647 \u0633\u0644\u0627\u0645 \u062f\u0646\u06cc\u0627 \u062a\u062c\u0631\u0628\u06cc\u0627\u062a \u0645\u0644\u0645\u0648\u0633\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0628\u0627\u063a\u0628\u0627\u0646\u06cc \u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062a\u062c\u0631\u0628\u0647\u200c\u06cc \u06a9\u0627\u0634\u062a \u06af\u06cc\u0627\u0647\u0627\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062e\u0648\u062f \u0628\u0647 \u0627\u0631\u0645\u063a\u0627\u0646 \u0622\u0648\u0631\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%B3%D8%B1%D8%B3%D8%B1%DB%8C_%D8%AF%D8%B3_%D8%AF%D8%B3%DB%8C\"><\/span>\u0633\u0631\u0633\u0631\u06cc \u062f\u0633 \u062f\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/85419.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/85419\/\u0633\u0631\u0633\u0631\u06cc-\u062f\u0633-\u062f\u0633\u06cc\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0633\u0631\u0633\u0631\u06cc \u062f\u0633 \u062f\u0633\u06cc\" >\u0633\u0631\u0633\u0631\u06cc \u062f\u0633 \u062f\u0633\u06cc<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0634\u0631\u0627\u0631\u0647 \u0648\u0638\u06cc\u0641\u0647 \u0634\u0646\u0627\u0633                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0627\u0646\u0648\u0646 \u067e\u0631\u0648\u0631\u0634 \u0641\u06a9\u0631\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0648 \u0646\u0648\u062c\u0648\u0627\u0646\u0627\u0646                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/85419\/\u0633\u0631\u0633\u0631\u06cc-\u062f\u0633-\u062f\u0633\u06cc'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0633\u0631\u0633\u0631\u06cc \u062f\u0633 \u062f\u0633\u06cc\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0632\u0647\u0631\u0647 \u067e\u0631\u06cc\u0631\u062e \u0645\u0639\u062a\u0642\u062f \u0627\u0633\u062a \u0645\u0627\u062f\u0631 \u0648 \u067e\u062f\u0631 \u0647\u0645\u0631\u0627\u0647\u200c\u062a\u0631\u06cc\u0646 \u0648 \u0628\u0647\u062a\u0631\u06cc\u0646 \u062f\u0648\u0633\u062a\u200c\u0647\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0647\u0633\u062a\u0646\u062f \u0648 \u0686\u0647 \u062e\u0648\u0628 \u0627\u0633\u062a \u0627\u06cc\u0646 \u0647\u0645\u0631\u0627\u0647\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0644\u0630\u062a\u200c\u0628\u062e\u0634 \u0628\u0648\u062f\u0647 \u0648 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0628\u0627\u0632\u06cc \u0628\u0627\u0634\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u0633\u0631\u0633\u0631\u06cc \u062f\u0633 \u062f\u0633\u06cc \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0632 \u0634\u0639\u0631\u0647\u0627 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0630\u0647\u0646 \u06a9\u0648\u062f\u06a9 \u062f\u0631\u06af\u06cc\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u062d\u0631\u06a9\u0627\u062a \u0628\u062f\u0646 \u0631\u0627 \u0628\u0647\u200c\u062f\u0646\u0628\u0627\u0644 \u062f\u0627\u0631\u062f. \u062f\u0631 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u0634\u0639\u0631\u0647\u0627\u06cc \u0634\u0627\u062f \u06cc\u06a9 \u062d\u0631\u06a9\u062a \u062e\u0627\u0635 \u0645\u0637\u0631\u062d \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0622\u0646 \u0631\u0627 \u0628\u0627 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f. \u062a\u06a9\u0631\u0627\u0631 \u0645\u062f\u0627\u0648\u0645 \u0627\u0633\u0627\u0645\u06cc \u0627\u062c\u0632\u0627\u06cc \u0628\u062f\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u06a9\u0648\u062f\u06a9 \u06a9\u0645\u200c\u06a9\u0645 \u0628\u0627 \u0627\u06cc\u0646 \u0627\u062c\u0632\u0627 \u0648 \u062d\u0631\u06a9\u0627\u062a \u0622\u0634\u0646\u0627 \u0634\u0648\u062f. \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0647\u0631 \u0634\u0639\u0631 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0648\u0627\u0644\u062f\u06cc\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u062a\u0627 \u0646\u062d\u0648\u0647\u200c\u06cc \u062e\u0648\u0627\u0646\u062f\u0646 \u0634\u0639\u0631 \u0648 \u0641\u0639\u0627\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f \u0631\u0627 \u06af\u0648\u0634\u0632\u062f \u06a9\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%AE%D8%B1%D8%B3%DB%8C_%D9%88_%D8%AF%D9%88%D8%B3%D8%AA%D8%A7%D9%86\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u062e\u0631\u0633\u06cc \u0648 \u062f\u0648\u0633\u062a\u0627\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/83695.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/83695\/\u062e\u0631\u0633\u06cc-\u0686\u0631\u0627-\u0645\u06cc-\u062a\u0631\u0633\u06cc\u061f\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062e\u0631\u0633\u06cc \u0686\u0631\u0627 \u0645\u06cc\u200c\u062a\u0631\u0633\u06cc\u061f\" >\u062e\u0631\u0633\u06cc \u0686\u0631\u0627 \u0645\u06cc\u200c\u062a\u0631\u0633\u06cc\u061f<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0627\u0631\u0645\u0627 \u0648\u06cc\u0644\u0633\u0648\u0646                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0641\u06cc\u0631\u0648\u0632\u0647 \u06a9\u0627\u062a\u0628                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/83695\/\u062e\u0631\u0633\u06cc-\u0686\u0631\u0627-\u0645\u06cc-\u062a\u0631\u0633\u06cc\u061f'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062e\u0631\u0633\u06cc \u0686\u0631\u0627 \u0645\u06cc\u200c\u062a\u0631\u0633\u06cc\u061f\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0645\u062c\u0645\u0648\u0639\u0647 \u062e\u0631\u0633\u06cc \u0648 \u062f\u0648\u0633\u062a\u0627\u0646 \u0628\u0627 \u062a\u0635\u0627\u0648\u06cc\u0631 \u0631\u0646\u06af\u0627\u0631\u0646\u06af \u0648 \u0634\u0627\u062f\u0634 \u062d\u0633\u0627\u0628\u06cc \u0628\u0631\u0627\u06cc \u0628\u0686\u0647\u200c\u0647\u0627 \u062f\u0648\u0633\u062a\u200c\u062f\u0627\u0634\u062a\u0646\u06cc \u0627\u0633\u062a. \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644 \u0686\u0647\u0627\u0631 \u062c\u0644\u062f \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0631\u0627 \u0645\u0646\u062a\u0634\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0648\u06cc\u0698\u06af\u06cc \u0645\u0647\u0645 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0642\u0627\u0644\u0628 \u0634\u0639\u0631 \u062a\u0639\u0631\u06cc\u0641 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0622\u0647\u0646\u06af\u06cc\u0646 \u0628\u0648\u062f\u0646 \u06a9\u0644\u0627\u0645 \u062a\u0648\u062c\u0647 \u0628\u0686\u0647\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u062e\u0648\u062f \u062c\u0644\u0628 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062e\u0631\u0633\u06cc \u0648 \u063a\u0627\u0631 \u0648 \u062e\u0631 \u0648 \u067e\u0641 \u06cc\u06a9 \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0627\u0645\u0632\u0647 \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc\u200c\u0627\u0641\u062a\u062f. \u062e\u0631\u0633\u06cc \u062f\u0631 \u063a\u0627\u0631 \u062e\u0648\u062f \u062e\u0648\u0627\u0628\u06cc\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0648\u0633\u062a\u0627\u0646\u0634 \u0628\u0647 \u063a\u0627\u0631\u0634 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f\u060c \u0628\u0631\u0627\u06cc \u062e\u0648\u062f \u063a\u0630\u0627 \u062f\u0631\u0633\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0627\u0632 \u06af\u0631\u0645\u0627\u06cc \u0622\u062a\u0634 \u0644\u0630\u062a \u0645\u06cc\u200c\u0628\u0631\u0646\u062f. \u0686\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0627\u06af\u0631 \u062e\u0631\u0633 \u0646\u0627\u06af\u0647\u0627\u0646 \u0627\u0632 \u062e\u0648\u0627\u0628 \u0628\u067e\u0631\u062f\u061f \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062e\u0631\u0633\u06cc \u0648 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0642\u0634\u0646\u06af \u0628\u0686\u0647\u200c\u0647\u0627 \u0628\u0627 \u062e\u0631\u0633\u06cc \u0647\u0645\u0631\u0627\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u062a\u0627 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0632\u06cc\u0628\u0627\u06cc\u06cc \u06a9\u0647 \u062e\u062f\u0627\u0648\u0646\u062f \u062e\u0644\u0642 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0631\u0627 \u0628\u0628\u06cc\u0646\u0646\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062e\u0631\u0633\u06cc \u0648 \u0635\u0628\u0631 \u0648 \u0627\u0646\u062a\u0638\u0627\u0631\u060c \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627 \u0645\u0641\u0647\u0648\u0645 \u0635\u0628\u0631 \u0648 \u0645\u0646\u062a\u0638\u0631\u0645\u0627\u0646\u062f\u0646 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u0645\u06cc\u200c\u0622\u0645\u0648\u0632\u0646\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u062a\u0641\u0627\u0641\u0627\u062a \u062e\u0648\u0628 \u0628\u0627\u06cc\u062f \u062a\u0644\u0627\u0634 \u06a9\u0646\u0646\u062f \u0648 \u0635\u0628\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627\u0644\u0627\u06cc \u06f2 \u0633\u0627\u0644 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u062e\u0648\u0627\u0646\u06cc\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%AA%D9%82_%D8%AA%D9%82%D8%8C_%D8%A8%DB%8C%D8%A7_%D8%A8%DB%8C%D8%B1%D9%88%D9%86\"><\/span>\u062a\u0642 \u062a\u0642\u060c \u0628\u06cc\u0627 \u0628\u06cc\u0631\u0648\u0646<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/85761.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/85761\/\u062a\u0642-\u062a\u0642\u060c-\u0628\u06cc\u0627-\u0628\u06cc\u0631\u0648\u0646\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062a\u0642 \u062a\u0642\u060c \u0628\u06cc\u0627 \u0628\u06cc\u0631\u0648\u0646\" >\u062a\u0642 \u062a\u0642\u060c \u0628\u06cc\u0627 \u0628\u06cc\u0631\u0648\u0646<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0648\u06cc\u0646 \u0647\u0646\u06a9\u0633                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0633\u0627\u0646\u0627\u0632 \u0622\u06cc\u062a\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/85761\/\u062a\u0642-\u062a\u0642\u060c-\u0628\u06cc\u0627-\u0628\u06cc\u0631\u0648\u0646'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062a\u0642 \u062a\u0642\u060c \u0628\u06cc\u0627 \u0628\u06cc\u0631\u0648\u0646\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0686\u0647\u0627\u0631 \u062a\u062e\u0645 \u0632\u0631\u062f\u060c \u0635\u0648\u0631\u062a\u06cc\u060c \u0622\u0628\u06cc \u0648 \u0633\u0628\u0632 \u062f\u0631 \u062a\u0635\u0648\u06cc\u0631 \u062f\u06cc\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0645\u0646\u062a\u0638\u0631 \u0645\u06cc\u200c\u0645\u0627\u0646\u06cc\u0645 \u062a\u0627 \u0628\u0628\u06cc\u0646\u06cc\u0645 \u0686\u0647 \u0645\u0648\u062c\u0648\u062f\u0627\u062a\u06cc \u0627\u0632 \u062a\u062e\u0645\u200c\u0647\u0627 \u0628\u06cc\u0631\u0648\u0646 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f. \u06a9\u0645\u200c\u06a9\u0645 \u062a\u062e\u0645\u200c\u0647\u0627 \u0645\u06cc\u200c\u0634\u06a9\u0646\u0646\u062f \u0648 \u0627\u0632 \u062a\u062e\u0645\u200c\u0647\u0627\u06cc \u0632\u0631\u062f \u0648 \u0635\u0648\u0631\u062a\u06cc \u0648 \u0622\u0628\u06cc \u0633\u0647 \u062c\u0648\u062c\u0647 \u0628\u06cc\u0631\u0648\u0646 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f \u0627\u0645\u0627 \u062e\u0628\u0631\u06cc \u0627\u0632 \u0634\u06a9\u0633\u062a\u0646 \u062a\u062e\u0645 \u0633\u0628\u0632 \u0646\u06cc\u0633\u062a. \u062c\u0648\u062c\u0647\u200c\u0647\u0627 \u0628\u0647 \u062a\u062e\u0645 \u0633\u0628\u0632 \u0646\u0648\u06a9 \u0645\u06cc\u200c\u0632\u0646\u0646\u062f \u062a\u0627 \u062c\u0648\u062c\u0647\u200c\u06cc \u0686\u0647\u0627\u0631\u0645 \u0647\u0645 \u0628\u06cc\u0631\u0648\u0646 \u0628\u06cc\u0627\u06cc\u062f\u061b \u0627\u0645\u0627 \u0628\u0627 \u0634\u06a9\u0633\u062a\u0646 \u062a\u062e\u0645 \u0633\u0628\u0632 \u06cc\u06a9 \u0633\u0648\u0633\u0645\u0627\u0631 \u0628\u06cc\u0631\u0648\u0646 \u0645\u06cc\u200c\u0622\u06cc\u062f \u0648 \u062c\u0648\u062c\u0647\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0631\u0633\u0646\u062f \u0648 \u0641\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0633\u0648\u0633\u0645\u0627\u0631 \u062a\u0646\u0647\u0627 \u0645\u06cc\u200c\u0645\u0627\u0646\u062f \u0648 \u0646\u0627\u0631\u0627\u062d\u062a \u0645\u06cc\u200c\u0634\u0648\u062f. \u0622\u06cc\u0627 \u062c\u0648\u062c\u0647\u200c\u0647\u0627 \u0648 \u0633\u0648\u0633\u0645\u0627\u0631 \u0628\u0627 \u0647\u0645\u062f\u06cc\u06af\u0631 \u062f\u0648\u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u061f \u0645\u062a\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645 \u0627\u0633\u062a \u0648 \u0628\u06cc\u0634\u062a\u0631 \u062f\u0627\u0633\u062a\u0627\u0646 \u0627\u0632 \u0631\u0648\u06cc \u062a\u0635\u0627\u0648\u06cc\u0631 \u067e\u06cc\u0634 \u0645\u06cc\u200c\u0631\u0648\u062f. \u062a\u0635\u0627\u0648\u06cc\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0644\u0637\u06cc\u0641 \u0648 \u062f\u0648\u0633\u062a\u200c\u062f\u0627\u0634\u062a\u0646\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0628\u0686\u0647\u200c\u0647\u0627 \u062a\u0635\u0627\u0648\u06cc\u0631 \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u0646\u062f \u062a\u0627 \u0628\u0628\u06cc\u0646\u062f \u0628\u0627\u0644\u0627\u0654\u062e\u0631\u0647 \u0686\u0647 \u0627\u062a\u0641\u0627\u0642\u06cc \u0645\u06cc\u0641\u062a\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%AC%D9%85%D9%88%D8%B9%D9%87%E2%80%8C%DB%8C_%D8%A8%D8%A7_%D8%B3%D8%B1_%D8%A8%D8%B1%DB%8C%D9%85_%D8%AA%D9%88%DB%8C_%DA%A9%D8%AA%D8%A7%D8%A8\"><\/span>\u0645\u062c\u0645\u0648\u0639\u0647\u200c\u06cc \u0628\u0627 \u0633\u0631 \u0628\u0631\u06cc\u0645 \u062a\u0648\u06cc \u06a9\u062a\u0627\u0628&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"bookbox\">\n        <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/148302.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/148302\/\u062a\u0648-\u0628\u06cc\u0634\u0647-\u062f\u06cc\u062f\u0647-\u0645\u06cc-\u0634\u0647\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062a\u0648 \u0628\u06cc\u0634\u0647 \u062f\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0647\" >\u062a\u0648 \u0628\u06cc\u0634\u0647 \u062f\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0647<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0646\u06cc\u0644\u0648\u0641\u0631 \u0628\u0647\u0627\u0631\u06cc                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0646\u0634\u0631 \u0627\u0641\u0642                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/148302\/\u062a\u0648-\u0628\u06cc\u0634\u0647-\u062f\u06cc\u062f\u0647-\u0645\u06cc-\u0634\u0647'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062a\u0648 \u0628\u06cc\u0634\u0647 \u062f\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0647\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0646\u06cc\u0644\u0648\u0641\u0631 \u0628\u0647\u0627\u0631\u06cc \u062f\u0631 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0628\u0627 \u0632\u0628\u0627\u0646 \u0634\u0639\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u0628\u0627 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u0648 \u0627\u0634\u06cc\u0627\u06cc \u0645\u062d\u06cc\u0637 \u0627\u0637\u0631\u0627\u0641 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062a\u0648 \u0645\u0632\u0631\u0639\u0647 \u06a9\u06cc \u0628\u0648\u062f\u061f \u0686\u06cc \u0628\u0648\u062f\u061f \u0628\u0686\u0647\u200c\u0647\u0627 \u0628\u0627 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u0627\u0647\u0644\u06cc \u062f\u0631 \u0645\u0632\u0631\u0639\u0647 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u061b \u06cc\u0627 \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062c\u0627\u0646\u0648\u0631\u0627\u0646 \u062a\u0647 \u0622\u0628 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u062f\u0631\u0648\u0646 \u0622\u0628 \u0631\u0627 \u0645\u06cc\u200c\u0628\u06cc\u0646\u0646\u062f. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u062a\u0635\u0627\u0648\u06cc\u0631 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u0631\u0627 \u0645\u06cc\u200c\u0628\u06cc\u0646\u0646\u062f \u0648 \u0628\u0627 \u0628\u0644\u0646\u062f\u062e\u0648\u0627\u0646\u06cc \u0648\u0627\u0644\u062f\u06cc\u0646 \u0628\u0627 \u0635\u062f\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u0647\u0645 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%AE%D8%A7%D9%86%D9%85_%D8%AD%D9%86%D8%A7_%D8%A8%D9%87_%DA%AF%D8%B1%D8%AF%D8%B4_%D9%85%DB%8C_%D8%B1%D9%88%D8%AF\"><\/span>\u062e\u0627\u0646\u0645 \u062d\u0646\u0627 \u0628\u0647 \u06af\u0631\u062f\u0634 \u0645\u06cc \u0631\u0648\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/208046.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/208046\/\u062e\u0627\u0646\u0645-\u062d\u0646\u0627-\u0628\u0647-\u06af\u0631\u062f\u0634-\u0645\u06cc-\u0631\u0648\u062f\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062e\u0627\u0646\u0645 \u062d\u0646\u0627 \u0628\u0647 \u06af\u0631\u062f\u0634 \u0645\u06cc \u0631\u0648\u062f\" >\u062e\u0627\u0646\u0645 \u062d\u0646\u0627 \u0628\u0647 \u06af\u0631\u062f\u0634 \u0645\u06cc \u0631\u0648\u062f<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u067e\u062a \u0647\u0627\u0686\u06cc\u0646\u0632                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0637\u0627\u0647\u0631\u0647 \u0622\u062f\u06cc\u0646\u0647 \u067e\u0648\u0631                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0639\u0644\u0645\u06cc \u0648 \u0641\u0631\u0647\u0646\u06af\u06cc                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/208046\/\u062e\u0627\u0646\u0645-\u062d\u0646\u0627-\u0628\u0647-\u06af\u0631\u062f\u0634-\u0645\u06cc-\u0631\u0648\u062f'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062e\u0627\u0646\u0645 \u062d\u0646\u0627 \u0628\u0647 \u06af\u0631\u062f\u0634 \u0645\u06cc \u0631\u0648\u062f\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0645\u0627\u062c\u0631\u0627\u06cc \u0631\u0648\u0632\u06cc \u0631\u0627 \u0631\u0648\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u062e\u0627\u0646\u0645 \u062d\u0646\u0627 \u0628\u0647 \u06af\u0631\u062f\u0634 \u0645\u06cc\u200c\u0631\u0648\u062f. \u0634\u0627\u06cc\u062f \u062f\u0631 \u0638\u0627\u0647\u0631 \u06cc\u06a9 \u06af\u0631\u062f\u0634 \u0645\u0639\u0645\u0648\u0644\u06cc \u0628\u0647 \u0646\u0638\u0631 \u0628\u0631\u0633\u062f \u0627\u0645\u0627 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062f\u0631 \u062a\u0635\u0627\u0648\u06cc\u0631 \u0627\u0635\u0644 \u0645\u0627\u062c\u0631\u0627 \u0631\u0627 \u062a\u0645\u0627\u0634\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u062a\u0635\u0627\u0648\u06cc\u0631 \u06a9\u062a\u0627\u0628 \u0644\u062d\u0638\u0627\u062a \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0645\u0632\u0647\u200c\u0627\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062e\u0644\u0642 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0686\u0634\u0645\u0627\u0646 \u06a9\u0648\u062f\u06a9 \u062f\u0631 \u0644\u0627\u0628\u0647\u200c\u0644\u0627\u06cc \u062a\u0635\u0627\u0648\u06cc\u0631 \u0645\u06cc\u200c\u0686\u0631\u062e\u062f \u062a\u0627 \u0627\u062a\u0641\u0627\u0641\u0627\u062a \u0631\u0627 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0647\u0645 \u0642\u0631\u0627\u0631 \u062f\u0647\u062f. <\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%87%D9%85%D8%A7%D9%86_%D8%A7%D9%86%D8%A7%D8%B1\"><\/span>\u0645\u0647\u0645\u0627\u0646 \u0627\u0646\u0627\u0631<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/102568.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/102568\/\u0645\u0647\u0645\u0627\u0646-\u0627\u0646\u0627\u0631\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0645\u0647\u0645\u0627\u0646 \u0627\u0646\u0627\u0631\" >\u0645\u0647\u0645\u0627\u0646 \u0627\u0646\u0627\u0631<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0633\u067e\u06cc\u062f\u0647  \u062e\u0644\u06cc\u0644\u06cc                    <\/span>  \n                <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/102568\/\u0645\u0647\u0645\u0627\u0646-\u0627\u0646\u0627\u0631'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0645\u0647\u0645\u0627\u0646 \u0627\u0646\u0627\u0631\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u06a9\u062a\u0627\u0628 \u0645\u0647\u0645\u0627\u0646 \u0627\u0646\u0627\u0631 \u062f\u0627\u0633\u062a\u0627\u0646 \u06a9\u0631\u0645\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9 \u0634\u0628 \u0645\u0647\u0645\u0627\u0646 \u062f\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0646\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0645\u0627\u062f\u0631 \u0646\u06af\u0631\u0627\u0646 \u0628\u0686\u0647\u200c\u0647\u0627\u06cc\u0634 \u0627\u0633\u062a \u0627\u0645\u0627 \u0628\u0686\u0647\u200c\u0647\u0627 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u0646\u062f \u06a9\u0631\u0645 \u06a9\u0648\u0686\u0648\u0644\u0648 \u0645\u0647\u0645\u0627\u0646 \u0622\u0646\u200c\u0647\u0627 \u0628\u0627\u0634\u062f \u0648 \u067e\u06cc\u0634\u0634\u0627\u0646 \u0628\u0645\u0627\u0646\u062f. \u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u062f\u0631 \u0634\u0628 \u06cc\u0644\u062f\u0627 \u062e\u0627\u0637\u0631\u0647\u200c\u0627\u06cc \u062f\u0648\u0633\u062a\u200c\u062f\u0627\u0634\u062a\u0646\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0686\u0647\u200c\u0647\u0627 \u0628\u0647 \u06cc\u0627\u062f\u06af\u0627\u0631 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f. <\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B3%DA%A9%D8%A7%D8%B1_%D9%84%D9%86%DA%AF%D9%87_%D8%AC%D9%88%D8%B1%D8%A7%D8%A8%DB%8C\"><\/span>\u0627\u0633\u06a9\u0627\u0631 \u0644\u0646\u06af\u0647 \u062c\u0648\u0631\u0627\u0628\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/128540.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/128540\/\u0627\u0633\u06a9\u0627\u0631-\u0644\u0646\u06af\u0647-\u062c\u0648\u0631\u0627\u0628\u06cc\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0627\u0633\u06a9\u0627\u0631 \u0644\u0646\u06af\u0647 \u062c\u0648\u0631\u0627\u0628\u06cc\" >\u0627\u0633\u06a9\u0627\u0631 \u0644\u0646\u06af\u0647 \u062c\u0648\u0631\u0627\u0628\u06cc<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u06cc. \u0627\u0686. \u0628\u0646\u062c\u0627\u0645\u06cc\u0646                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0622\u0646\u0627\u0647\u06cc\u062a\u0627 \u062d\u0636\u0631\u062a\u06cc \u06a9\u06cc\u0627\u0648\u0646\u062f\u0627\u0646\u06cc                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/128540\/\u0627\u0633\u06a9\u0627\u0631-\u0644\u0646\u06af\u0647-\u062c\u0648\u0631\u0627\u0628\u06cc'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0627\u0633\u06a9\u0627\u0631 \u0644\u0646\u06af\u0647 \u062c\u0648\u0631\u0627\u0628\u06cc\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u062f\u0627\u0633\u062a\u0627\u0646 \u062f\u0631\u0628\u0627\u0631\u0647\u200c\u06cc \u06a9\u0648\u0686\u0648\u0644\u0648\u06cc\u06cc \u0628\u0647 \u0627\u0633\u0645 \u0627\u0633\u06a9\u0627\u0631 \u0627\u0633\u062a. \u0627\u0633\u06a9\u0627\u0631 \u0647\u0645\u06cc\u0634\u0647 \u062c\u0648\u0631\u0627\u0628\u0634 \u0631\u0627 \u06af\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062c\u0648\u0631\u0627\u0628 \u0627\u0633\u06a9\u0627\u0631 \u062f\u0631 \u0635\u0641\u062d\u0627\u062a \u06a9\u062a\u0627\u0628 \u0642\u0627\u06cc\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0628\u0686\u0647\u200c\u0647\u0627 \u0628\u0627\u06cc\u062f \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f. \u0627\u0633\u06a9\u0627\u0631 \u0644\u0646\u06af\u0647 \u062c\u0648\u0631\u0627\u0628\u06cc \u06cc\u06a9 \u06a9\u062a\u0627\u0628 \u062a\u0639\u0627\u0645\u0644\u06cc \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0642\u062a \u062f\u06cc\u062f\u0627\u0631\u06cc \u0628\u0686\u0647\u200c\u0647\u0627 \u0631\u0627 \u062a\u0642\u0648\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B2%D9%86_%D8%B1%D9%88%DB%8C_%D8%AF%D8%B1%D8%AE%D8%AA_%D8%AC%D8%A7%D8%AF%D9%88%DB%8C%DB%8C\"><\/span>\u0628\u0632\u0646 \u0631\u0648\u06cc \u062f\u0631\u062e\u062a \u062c\u0627\u062f\u0648\u06cc\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/102374.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/102374\/\u0628\u0632\u0646-\u0631\u0648\u06cc-\u062f\u0631\u062e\u062a-\u062c\u0627\u062f\u0648\u06cc\u06cc\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u0628\u0632\u0646 \u0631\u0648\u06cc \u062f\u0631\u062e\u062a \u062c\u0627\u062f\u0648\u06cc\u06cc\" >\u0628\u0632\u0646 \u0631\u0648\u06cc \u062f\u0631\u062e\u062a \u062c\u0627\u062f\u0648\u06cc\u06cc<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u06a9\u0631\u0633\u062a\u06cc \u0645\u06cc\u062a\u0633\u0648\u0646                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0634\u06cc\u062f\u0627 \u0631\u0646\u062c\u0628\u0631                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u067e\u0631\u062a\u0642\u0627\u0644                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/102374\/\u0628\u0632\u0646-\u0631\u0648\u06cc-\u062f\u0631\u062e\u062a-\u062c\u0627\u062f\u0648\u06cc\u06cc'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u0628\u0632\u0646 \u0631\u0648\u06cc \u062f\u0631\u062e\u062a \u062c\u0627\u062f\u0648\u06cc\u06cc\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0628\u0632\u0646 \u0631\u0648\u06cc \u062f\u0631\u062e\u062a \u062c\u0627\u062f\u0648\u06cc\u06cc \u06cc\u06a9 \u06a9\u062a\u0627\u0628 \u062a\u0639\u0627\u0645\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0647\u0631 \u0635\u0641\u062d\u0647 \u0627\u0632 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u06a9\u0627\u0631\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f \u0648 \u0628\u0627 \u0631\u0641\u062a\u0646 \u0628\u0647 \u0635\u0641\u062d\u0647\u200c\u06cc \u0628\u0639\u062f \u0628\u0686\u0647\u200c\u0647\u0627 \u0645\u062a\u0648\u062c\u0647 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u062f\u0631\u062e\u062a \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u0622\u0634\u0646\u0627\u06cc\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627 \u0631\u0648\u0646\u062f \u0631\u0634\u062f \u062f\u0631\u062e\u062a \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0645\u062a\u0648\u062c\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0647\u0631 \u0641\u0635\u0644 \u0686\u0647 \u0627\u062a\u0641\u0627\u0642\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a\u0627\u0646 \u0645\u06cc\u0641\u062a\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"bookbox\">\n    <h3><span class=\"ez-toc-section\" id=\"%D8%AF%DA%A9%D9%85%D9%87_%D9%82%D8%B1%D9%85%D8%B2_%D8%B1%D8%A7_%D9%81%D8%B4%D8%A7%D8%B1_%D8%A8%D8%AF%D9%87\"><\/span>\u062f\u06a9\u0645\u0647 \u0642\u0631\u0645\u0632 \u0631\u0627 \u0641\u0634\u0627\u0631 \u0628\u062f\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>    <div class=\"box d-flex\">\n\n        <img decoding=\"async\" data-src=\"https:\/\/img.taaghche.com\/frontCover\/208149.jpg?w=150\"  alt=\"\" class=\"bookpic lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\">\n\n        <div class=\"infobox\">\n            <div class=\"text\">\n                <a class=\"book_link\" href=\"https:\/\/taaghche.com\/book\/208149\/\u062f\u06a9\u0645\u0647-\u0642\u0631\u0645\u0632-\u0631\u0627-\u0641\u0634\u0627\u0631-\u0628\u062f\u0647\"  title=\"\u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u062a\u0627\u0628 \u062f\u06a9\u0645\u0647 \u0642\u0631\u0645\u0632 \u0631\u0627 \u0641\u0634\u0627\u0631 \u0628\u062f\u0647\" >\u062f\u06a9\u0645\u0647 \u0642\u0631\u0645\u0632 \u0631\u0627 \u0641\u0634\u0627\u0631 \u0628\u062f\u0647<\/a>\n                                <p>\n                    <span>\u0646\u0648\u06cc\u0633\u0646\u062f\u0647:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0644\u06a9\u0633 \u0644\u06cc\u0648\u0686                    <\/span>  \n                <\/p>\n                                    <p>   \n                    <span>\u0645\u062a\u0631\u062c\u0645:<\/span>\n                    <span class='info_text'>\n                        \u0634\u06cc\u062f\u0627 \u0631\u0646\u062c\u0628\u0631                    <\/span>  \n                    <\/p>\n                                <p>\n                    <span>\u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a:<\/span>\n                    <span class='info_text'>\n                        \u0627\u0646\u062a\u0634\u0627\u0631\u0627\u062a \u0639\u0644\u0645\u06cc \u0648 \u0641\u0631\u0647\u0646\u06af\u06cc                    <\/span>\n                <\/p>\n            <\/div>\n            <button\n                type=\"button\"\n                class=\"buy_btn\"\n                onclick=\"window.location.href='https:\/\/taaghche.com\/book\/208149\/\u062f\u06a9\u0645\u0647-\u0642\u0631\u0645\u0632-\u0631\u0627-\u0641\u0634\u0627\u0631-\u0628\u062f\u0647'\"\n                aria-label=\"\u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628 \u062f\u06a9\u0645\u0647 \u0642\u0631\u0645\u0632 \u0631\u0627 \u0641\u0634\u0627\u0631 \u0628\u062f\u0647\"\n                >\n                \u062e\u0631\u06cc\u062f \u06a9\u062a\u0627\u0628\n            <\/button>\n\n        <\/div>\n    <\/div>\n    <div class=\"text\">\n        <p>\n            <p>\u0627\u06af\u0631 \u0628\u0647\u200c\u062f\u0646\u0628\u0627\u0644 \u06a9\u062a\u0627\u0628 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0622\u0645\u0648\u0632\u0634\u06cc \u0628\u0627\u0634\u062f \u0648 \u062f\u0631\u0639\u06cc\u0646\u200c\u062d\u0627\u0644 \u062e\u0644\u0627\u0642\u060c \u06a9\u062a\u0627\u0628 \u062f\u06a9\u0645\u0647 \u0642\u0631\u0645\u0632 \u0631\u0627 \u0641\u0634\u0627\u0631 \u0628\u062f\u0647 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0646\u062f\u0647\u06cc\u062f. \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u06cc\u06a9 \u0637\u0631\u0627\u062d\u06cc \u0628\u0633\u06cc\u0627\u0631 \u062c\u0630\u0627\u0628 \u0648 \u062e\u0644\u0627\u0642 \u062f\u0627\u0631\u062f. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627 \u0627\u06cc\u0646 \u06a9\u062a\u0627\u0628 \u0648\u0627\u0631\u062f \u06cc\u06a9 \u0628\u0627\u0632\u06cc \u062c\u0627\u0644\u0628 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0628\u0647\u200c\u0637\u0648\u0631 \u063a\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0648 \u0646\u0627\u062e\u0648\u062f\u0622\u06af\u0627\u0647 \u0631\u0646\u06af\u200c\u0647\u0627 \u0631\u0627 \u06cc\u0627\u062f \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f \u0648 \u0645\u062a\u0648\u062c\u0647 \u062a\u0641\u0627\u0648\u062a \u0628\u06cc\u0646 \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u062f\u0631 \u0647\u0631 \u0635\u0641\u062d\u0647 \u062f\u0633\u062a\u0648\u0631\u0647\u0627\u06cc \u0633\u0627\u062f\u0647\u200c\u0627\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0645\u062b\u0644\u0627 \u0628\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f \u062f\u06a9\u0645\u0647 \u0631\u0627 \u0641\u0634\u0627\u0631 \u0628\u062f\u0647 \u0648 \u062f\u0631\u0646\u0647\u0627\u06cc\u062a \u0646\u062a\u06cc\u062c\u0647 \u0631\u0627 \u0628\u0647 \u0627\u0648 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f. \u062a\u0635\u0627\u0648\u06cc\u0631 \u0628\u0632\u0631\u06af \u0648 \u06af\u0648\u06cc\u0627 \u0647\u0633\u062a\u0646\u062f \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u0627\u0646\u062c\u0627\u0645 \u062f\u0633\u062a\u0648\u0631\u0647\u0627 \u0647\u062f\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n        <\/p>\n    <\/div>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0633\u0631\u06cc\u0639 \u0631\u0634\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u062e\u0648\u0627\u0646\u062f\u0646 \u06a9\u062a\u0627\u0628 \u062a\u0648\u0633\u0637 \u0648\u0627\u0644\u062f\u06cc\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0647 \u0631\u0634\u062f \u0628\u0647\u062a\u0631 \u0622\u0646\u200c\u0647\u0627\u060c \u062f\u0631\u06a9 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u0648 \u0628\u0631\u0642\u0631\u0627\u0631\u06cc \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u06a9\u0645\u06a9\u06cc \u0628\u0633\u06cc\u0627\u0631 \u062e\u0648\u0628\u06cc \u0647\u0633\u062a\u0646\u062f \u0628\u0631\u0627\u06cc \u0645\u0647\u0627\u0631\u062a\u200c\u0622\u0645\u0648\u0632\u06cc \u0648 \u0632\u0628\u0627\u0646\u200c\u0622\u0645\u0648\u0632\u06cc.<\/p>\n\n\n\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0627\u0632 \u0628\u0644\u0627\u06af \u0637\u0627\u0642\u0686\u0647 \u062a\u0644\u0627\u0634 \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u0645 \u062a\u0627 \u0628\u0627 \u0645\u0639\u0631\u0641\u06cc \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u200c\u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u0648\u0627\u0644\u062f\u06cc\u0646 \u0631\u0627 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u062a\u0627\u0628 \u06cc\u0627\u0631\u06cc \u062f\u0647\u06cc\u0645 \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u06a9\u062a\u0627\u0628 \u062e\u0648\u0628 \u0631\u0627 \u0628\u0627\u0631\u0647\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0628\u062e\u0648\u0627\u0646\u0646\u062f \u0648 \u0644\u062d\u0638\u0627\u062a \u0646\u0627\u0628\u06cc \u0631\u0627 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0628\u0633\u0627\u0632\u0646\u062f \u0648 \u0628\u0647 \u0631\u0634\u062f \u0648 \u062a\u06a9\u0627\u0645\u0644 \u0628\u0647\u062a\u0631 \u062f\u0644\u0628\u0646\u062f \u062e\u0648\u062f \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f.<\/p>\n\n\n                                        <div class=\"relatedpost\">\n                        <div class=\"d-flex align-items-center\">\n                            <img decoding=\"async\" data-src=\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2025\/10\/\u06a9\u062a\u0627\u0628-\u0628\u0631\u0627\u06cc-\u06af\u0631\u0648\u0647-\u0633\u0646\u06cc-\u0627\u0644\u0641.webp\" class=\"relatedimg lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/675;\" \/>\n                            <div class=\"inforelated\">\n                                <p>\n                                    \u062f\u0631 \u0645\u062c\u0644\u0647\u200c\u06cc \u0637\u0627\u0642\u0686\u0647 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:\n                                <\/p>\n                                <a href=\"https:\/\/taaghche.com\/blog\/1404\/08\/05\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%af%d8%b1%d9%88%d9%87-%d8%b3%d9%86%db%8c-%d8%a7%d9%84%d9%81\/\" target=\"_blank\">                      \n                                    <p class=\"relatedname\">\n                                        \u0628\u0647\u062a\u0631\u06cc\u0646 \u062f\u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627 \u0648 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u06af\u0631\u0648\u0647 \u0633\u0646\u06cc \u0627\u0644\u0641                                    <\/p>\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0648\u0627\u0646\u200c\u0634\u0646\u0627\u0633\u0627\u0646 \u0648 \u0639\u0644\u0645\u0627\u06cc \u062a\u0639\u0644\u06cc\u0645\u200c\u0648\u062a\u0631\u0628\u06cc\u062a \u0645\u0639\u062a\u0642\u062f \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0648\u0631\u0647\u200c\u06cc \u062a\u0648\u0644\u062f \u062a\u0627 \u06f2\u0633\u0627\u0644\u06af\u06cc \u062f\u0648\u0631\u0647\u200c\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u062d\u06cc\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062f\u0648\u0631\u0647 \u0627\u0632 \u0631\u0634\u062f \u06a9\u0648\u062f\u06a9 \u0631\u0627 \u062f\u0648\u0631\u0647\u200c\u06cc \u062d\u0633\u06cc\u200c\u062d\u0631\u06a9\u062a\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u06af\u0648\u06cc\u0646\u062f\u061b \u0686\u0648\u0646 \u06a9\u0648\u062f\u06a9 \u0628\u0627 \u062d\u0631\u06a9\u0627\u062a \u0648 \u0627\u0639\u0636\u0627\u06cc \u062d\u0633\u06cc \u062e\u0648\u062f \u0628\u0627 \u0645\u062d\u06cc\u0637 \u0648 \u0627\u0637\u0631\u0627\u0641\u06cc\u0627\u0646 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0631\u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0632\u06cc\u0631 \u06f2 \u0633\u0627\u0644 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0627\u0645\u0627 \u0630\u0647\u0646 \u0622\u0646\u200c\u0647\u0627 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0648 \u0622\u0645\u0627\u062f\u06af\u06cc [&hellip;]<\/p>\n","protected":false},"author":51,"featured_media":17408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[46,860,863,872],"tags":[],"class_list":["post-17407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-46","category-860","category-863","category-872"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06f0 \u062a\u0627 \u06f2 \u0633\u0627\u0644\u0647 | \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc \u062a\u0627 \u0642\u0635\u0647<\/title>\n<meta name=\"description\" content=\"\u062f\u0631 \u0627\u06cc\u0646 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0637\u0627\u0642\u0686\u0647 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u06cc\u0633\u062a \u06a9\u062a\u0627\u0628 \u0646\u0648\u0632\u0627\u062f\u060c \u06a9\u062a\u0627\u0628 \u0645\u062e\u0635\u0648\u0635 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u067e\u0631\u062f\u0627\u062e\u062a\u06cc\u0645\u061b \u0642\u0635\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0634\u0645\u0627.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/\u06a9\u062a\u0627\u0628-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06f0 \u062a\u0627 \u06f2 \u0633\u0627\u0644\u0647 | \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc \u062a\u0627 \u0642\u0635\u0647\" \/>\n<meta property=\"og:description\" content=\"\u062f\u0631 \u0627\u06cc\u0646 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0637\u0627\u0642\u0686\u0647 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u06cc\u0633\u062a \u06a9\u062a\u0627\u0628 \u0646\u0648\u0632\u0627\u062f\u060c \u06a9\u062a\u0627\u0628 \u0645\u062e\u0635\u0648\u0635 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u067e\u0631\u062f\u0627\u062e\u062a\u06cc\u0645\u061b \u0642\u0635\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0634\u0645\u0627.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/\u06a9\u062a\u0627\u0628-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0648\u0628\u0644\u0627\u06af \u0637\u0627\u0642\u0686\u0647\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/taaghche\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T12:58:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T13:39:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@taaghche_ebook\" \/>\n<meta name=\"twitter:site\" content=\"@taaghche_ebook\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/\"},\"author\":{\"name\":\"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc\",\"@id\":\"https:\/\/taaghche.com\/blog\/#\/schema\/person\/db45f21a4ff67811d5737f55303f6c3e\"},\"headline\":\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u0633\u0627\u0644\u0647\",\"datePublished\":\"2024-12-09T12:58:53+00:00\",\"dateModified\":\"2025-10-27T13:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/\"},\"wordCount\":1,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/taaghche.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp\",\"articleSection\":[\"\u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\",\"\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0628\u0631\u06af\u0632\u06cc\u062f\u0647\u200c \u0648 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc\",\"\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646\",\"\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0648 \u0631\u0645\u0627\u0646\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/\",\"url\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/\",\"name\":\"\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06f0 \u062a\u0627 \u06f2 \u0633\u0627\u0644\u0647 | \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc \u062a\u0627 \u0642\u0635\u0647\",\"isPartOf\":{\"@id\":\"https:\/\/taaghche.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp\",\"datePublished\":\"2024-12-09T12:58:53+00:00\",\"dateModified\":\"2025-10-27T13:39:43+00:00\",\"description\":\"\u062f\u0631 \u0627\u06cc\u0646 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0637\u0627\u0642\u0686\u0647 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u06cc\u0633\u062a \u06a9\u062a\u0627\u0628 \u0646\u0648\u0632\u0627\u062f\u060c \u06a9\u062a\u0627\u0628 \u0645\u062e\u0635\u0648\u0635 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u067e\u0631\u062f\u0627\u062e\u062a\u06cc\u0645\u061b \u0642\u0635\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0634\u0645\u0627.\",\"breadcrumb\":{\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#primaryimage\",\"url\":\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp\",\"contentUrl\":\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp\",\"width\":1200,\"height\":675,\"caption\":\"\u06a9\u062a\u0627\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u0646\u0648\u0632\u0627\u062f\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\/\/taaghche.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u0633\u0627\u0644\u0647\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/taaghche.com\/blog\/#website\",\"url\":\"https:\/\/taaghche.com\/blog\/\",\"name\":\"\u0648\u0628\u0644\u0627\u06af \u0637\u0627\u0642\u0686\u0647\",\"description\":\"\u0645\u0639\u0631\u0641\u06cc \u0648 \u0628\u0631\u0631\u0633\u06cc \u06a9\u062a\u0627\u0628 \u0648 \u0631\u0645\u0627\u0646\",\"publisher\":{\"@id\":\"https:\/\/taaghche.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/taaghche.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/taaghche.com\/blog\/#organization\",\"name\":\"\u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u06a9\u062a\u0627\u0628 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0637\u0627\u0642\u0686\u0647\",\"url\":\"https:\/\/taaghche.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/taaghche.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2018\/08\/taaghchebrand.png\",\"contentUrl\":\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2018\/08\/taaghchebrand.png\",\"width\":400,\"height\":400,\"caption\":\"\u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u06a9\u062a\u0627\u0628 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0637\u0627\u0642\u0686\u0647\"},\"image\":{\"@id\":\"https:\/\/taaghche.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/taaghche\",\"https:\/\/x.com\/taaghche_ebook\",\"https:\/\/instagram.com\/taaghche_ebookstore\/\",\"https:\/\/fa.wikipedia.org\/wiki\/\u0637\u0627\u0642\u0686\u0647_(\u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631)\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/taaghche.com\/blog\/#\/schema\/person\/db45f21a4ff67811d5737f55303f6c3e\",\"name\":\"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/taaghche.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2025\/07\/\u0622\u06cc\u0644\u0627\u0631-\u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc-250x250.jpg\",\"contentUrl\":\"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2025\/07\/\u0622\u06cc\u0644\u0627\u0631-\u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc-250x250.jpg\",\"caption\":\"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc\"},\"description\":\"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc \u0647\u0633\u062a\u0645. \u0633\u0627\u0644 \u06f1\u06f3\u06f7\u06f6 \u062f\u0631 \u062a\u0647\u0631\u0627\u0646 \u0628\u0647 \u062f\u0646\u06cc\u0627 \u0622\u0645\u062f\u0645. \u062a\u0627 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u06cc\u0627\u062f\u0645 \u0627\u0633\u062a \u0647\u0645\u06cc\u0634\u0647 \u0627\u0632 \u062f\u06cc\u062f\u0646 \u06a9\u0644\u0645\u0627\u062a \u0647\u06cc\u062c\u0627\u0646\u200c\u0632\u062f\u0647 \u0645\u06cc\u200c\u0634\u062f\u0645 \u0648 \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0645 \u0628\u0647 \u06cc\u06a9 \u0686\u06cc\u0632 \u062c\u0627\u062f\u0648\u06cc\u06cc \u0646\u06af\u0627\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0645. \u0648\u0642\u062a\u06cc \u067e\u062f\u0631\u0645 \u0631\u0648\u0632\u0646\u0627\u0645\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646\u062f \u06cc\u0627 \u0648\u0642\u062a\u06cc \u0645\u0627\u062f\u0631\u0645 \u0628\u0631\u0627\u06cc\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646\u062f \u0647\u0645\u06cc\u0634\u0647 \u0628\u0647 \u0633\u0645\u062a \u06a9\u0644\u0645\u0627\u062a \u0648 \u0646\u0648\u0634\u062a\u0647\u200c\u0647\u0627 \u062c\u0630\u0628 \u0645\u06cc\u200c\u0634\u062f\u0645. \u062a\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u06a9\u0645\u200c\u06a9\u0645 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u062c\u0627\u06cc\u06af\u0627\u0647 \u0648\u06cc\u0698\u0647\u200c\u0627\u06cc \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc\u200c\u0627\u0645 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0646\u062f\u061b \u0622\u0646\u0642\u062f\u0631 \u062c\u062f\u06cc \u06a9\u0647 \u0631\u0634\u062a\u0647\u200c\u0647\u0627\u06cc \u0645\u0647\u0646\u062f\u0633\u06cc \u0631\u0627 \u06a9\u0646\u0627\u0631 \u06af\u0630\u0627\u0634\u062a\u0645 \u0648 \u06a9\u062a\u0627\u0628\u062f\u0627\u0631\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0631\u062f\u0645. \u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u0631\u0634\u062a\u0647\u200c\u06cc \u06a9\u062a\u0627\u0628\u062f\u0627\u0631\u06cc \u0645\u0646 \u0631\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0628\u0627\u0648\u0631 \u0631\u0633\u0627\u0646\u062f \u06a9\u0647 \u06a9\u0627\u0631 \u062f\u0631 \u062d\u0648\u0632\u0647\u200c\u06cc \u06a9\u062a\u0627\u0628 \u0686\u06cc\u0632\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u0645 \u0647\u0645\u06cc\u0634\u0647 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0645 \u0648 \u0645\u0646 \u0631\u0627 \u062e\u0648\u0634\u062d\u0627\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0646\u0648\u0634\u062a\u0646 \u0627\u0632 \u0622\u0646 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0634\u0645\u0627 \u0628\u0639\u062f \u0627\u0632 \u0639\u0634\u0642 \u0628\u0647 \u062e\u0648\u0627\u0646\u062f\u0646 \u0628\u0647 \u0622\u0646 \u0639\u0644\u0627\u0642\u0647 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0648 \u0627\u06cc\u0646 \u0627\u062a\u0641\u0627\u0642 \u0628\u0631\u0627\u06cc \u0645\u0646 \u0647\u0645 \u0627\u0641\u062a\u0627\u062f. \u062e\u0648\u0634\u062d\u0627\u0644\u0645 \u06a9\u0647 \u062a\u0627 \u0628\u0647 \u0627\u0644\u0627\u0646 \u0628\u0631\u0627\u06cc \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u0648\u06cc\u0646\u0634 \u0648 \u0645\u0631\u062f\u0645\u06a9 \u0645\u0631\u0648\u0631 \u06a9\u062a\u0627\u0628 \u0646\u0648\u0634\u062a\u0647\u200c\u200c\u0627\u0645 \u0648 \u0646\u0648\u0634\u062a\u0646 \u0628\u0631\u0627\u06cc \u0637\u0627\u0642\u0686\u0647 \u0646\u06cc\u0632 \u0645\u0648\u0647\u0628\u062a\u06cc \u0628\u0648\u062f\u0647 \u06a9\u0647 \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0646\u0635\u06cc\u0628\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a. \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0645\u0646 \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u0647\u0633\u062a\u0646\u062f. \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u062f\u0646\u06cc\u0627\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0627\u0632 \u0628\u0648\u062f\u0646 \u062f\u0631 \u0622\u0646\u200c\u0647\u0627 \u0644\u0630\u062a \u0645\u06cc\u200c\u0628\u0631\u0645 \u0648 \u0627\u06af\u0631 \u0628\u0627 \u0646\u0648\u0634\u062a\u0646 \u0645\u0646 \u06a9\u0633\u06cc \u0628\u062a\u0648\u0627\u0646\u062f \u0627\u06cc\u0646 \u062d\u0633 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u062f \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u062a\u062e\u0631 \u0648 \u062e\u0648\u0634\u062d\u0627\u0644 \u062e\u0648\u0627\u0647\u0645 \u0634\u062f.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/ailar-esmaeili-87934a22b\"],\"url\":\"https:\/\/taaghche.com\/blog\/author\/ailaresmaeili\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06f0 \u062a\u0627 \u06f2 \u0633\u0627\u0644\u0647 | \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc \u062a\u0627 \u0642\u0635\u0647","description":"\u062f\u0631 \u0627\u06cc\u0646 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0637\u0627\u0642\u0686\u0647 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u06cc\u0633\u062a \u06a9\u062a\u0627\u0628 \u0646\u0648\u0632\u0627\u062f\u060c \u06a9\u062a\u0627\u0628 \u0645\u062e\u0635\u0648\u0635 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u067e\u0631\u062f\u0627\u062e\u062a\u06cc\u0645\u061b \u0642\u0635\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0634\u0645\u0627.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/\u06a9\u062a\u0627\u0628-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644\/","og_locale":"fa_IR","og_type":"article","og_title":"\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06f0 \u062a\u0627 \u06f2 \u0633\u0627\u0644\u0647 | \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc \u062a\u0627 \u0642\u0635\u0647","og_description":"\u062f\u0631 \u0627\u06cc\u0646 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0637\u0627\u0642\u0686\u0647 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u06cc\u0633\u062a \u06a9\u062a\u0627\u0628 \u0646\u0648\u0632\u0627\u062f\u060c \u06a9\u062a\u0627\u0628 \u0645\u062e\u0635\u0648\u0635 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u067e\u0631\u062f\u0627\u062e\u062a\u06cc\u0645\u061b \u0642\u0635\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0634\u0645\u0627.","og_url":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/\u06a9\u062a\u0627\u0628-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644\/","og_site_name":"\u0648\u0628\u0644\u0627\u06af \u0637\u0627\u0642\u0686\u0647","article_publisher":"https:\/\/www.facebook.com\/taaghche","article_published_time":"2024-12-09T12:58:53+00:00","article_modified_time":"2025-10-27T13:39:43+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp","type":"image\/webp"}],"author":"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc","twitter_card":"summary_large_image","twitter_creator":"@taaghche_ebook","twitter_site":"@taaghche_ebook","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"6 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#article","isPartOf":{"@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/"},"author":{"name":"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc","@id":"https:\/\/taaghche.com\/blog\/#\/schema\/person\/db45f21a4ff67811d5737f55303f6c3e"},"headline":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u0633\u0627\u0644\u0647","datePublished":"2024-12-09T12:58:53+00:00","dateModified":"2025-10-27T13:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/taaghche.com\/blog\/#organization"},"image":{"@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#primaryimage"},"thumbnailUrl":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp","articleSection":["\u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646","\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0628\u0631\u06af\u0632\u06cc\u062f\u0647\u200c \u0648 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc","\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646","\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0648 \u0631\u0645\u0627\u0646"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/","url":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/","name":"\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06f0 \u062a\u0627 \u06f2 \u0633\u0627\u0644\u0647 | \u0627\u0632 \u0644\u0627\u0644\u0627\u06cc\u06cc \u062a\u0627 \u0642\u0635\u0647","isPartOf":{"@id":"https:\/\/taaghche.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#primaryimage"},"image":{"@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#primaryimage"},"thumbnailUrl":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp","datePublished":"2024-12-09T12:58:53+00:00","dateModified":"2025-10-27T13:39:43+00:00","description":"\u062f\u0631 \u0627\u06cc\u0646 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0637\u0627\u0642\u0686\u0647 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0644\u06cc\u0633\u062a \u06a9\u062a\u0627\u0628 \u0646\u0648\u0632\u0627\u062f\u060c \u06a9\u062a\u0627\u0628 \u0645\u062e\u0635\u0648\u0635 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u062f\u0648\u0633\u0627\u0644\u0647 \u067e\u0631\u062f\u0627\u062e\u062a\u06cc\u0645\u061b \u0642\u0635\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0644\u0646\u0634\u06cc\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0634\u0645\u0627.","breadcrumb":{"@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#primaryimage","url":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp","contentUrl":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2024\/12\/\u0628\u0647\u062a\u0631\u06cc\u0646-\u06a9\u062a\u0627\u0628\u0647\u0627\u06cc-\u062f\u0627\u0633\u062a\u0627\u0646-\u0628\u0631\u0627\u06cc-\u06a9\u0648\u062f\u06a9\u0627\u0646-\u0632\u06cc\u0631-\u06f2-\u0633\u0627\u0644.webp","width":1200,"height":675,"caption":"\u06a9\u062a\u0627\u0628 \u062f\u0627\u0633\u062a\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u06a9\u0648\u062f\u06a9 \u06cc\u06a9 \u0633\u0627\u0644\u0647 \u0648 \u0646\u0648\u0632\u0627\u062f"},{"@type":"BreadcrumbList","@id":"https:\/\/taaghche.com\/blog\/1403\/09\/19\/%da%a9%d8%aa%d8%a7%d8%a8-%d8%a8%d8%b1%d8%a7%db%8c-%da%a9%d9%88%d8%af%da%a9-%d8%b2%db%8c%d8%b1-%db%b2-%d8%b3%d8%a7%d9%84\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/taaghche.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0628\u0631\u0627\u06cc \u0646\u0648\u0632\u0627\u062f\u0627\u0646 \u0648 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u06cc\u06a9\u0633\u0627\u0644\u0647"}]},{"@type":"WebSite","@id":"https:\/\/taaghche.com\/blog\/#website","url":"https:\/\/taaghche.com\/blog\/","name":"\u0648\u0628\u0644\u0627\u06af \u0637\u0627\u0642\u0686\u0647","description":"\u0645\u0639\u0631\u0641\u06cc \u0648 \u0628\u0631\u0631\u0633\u06cc \u06a9\u062a\u0627\u0628 \u0648 \u0631\u0645\u0627\u0646","publisher":{"@id":"https:\/\/taaghche.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taaghche.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/taaghche.com\/blog\/#organization","name":"\u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u06a9\u062a\u0627\u0628 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0637\u0627\u0642\u0686\u0647","url":"https:\/\/taaghche.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/taaghche.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2018\/08\/taaghchebrand.png","contentUrl":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2018\/08\/taaghchebrand.png","width":400,"height":400,"caption":"\u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u06a9\u062a\u0627\u0628 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0637\u0627\u0642\u0686\u0647"},"image":{"@id":"https:\/\/taaghche.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/taaghche","https:\/\/x.com\/taaghche_ebook","https:\/\/instagram.com\/taaghche_ebookstore\/","https:\/\/fa.wikipedia.org\/wiki\/\u0637\u0627\u0642\u0686\u0647_(\u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631)"]},{"@type":"Person","@id":"https:\/\/taaghche.com\/blog\/#\/schema\/person\/db45f21a4ff67811d5737f55303f6c3e","name":"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/taaghche.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2025\/07\/\u0622\u06cc\u0644\u0627\u0631-\u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc-250x250.jpg","contentUrl":"https:\/\/taaghche.com\/blog\/wp-content\/uploads\/2025\/07\/\u0622\u06cc\u0644\u0627\u0631-\u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc-250x250.jpg","caption":"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc"},"description":"\u0622\u06cc\u0644\u0627\u0631 \u0627\u0633\u0645\u0627\u0639\u06cc\u0644\u06cc \u0647\u0633\u062a\u0645. \u0633\u0627\u0644 \u06f1\u06f3\u06f7\u06f6 \u062f\u0631 \u062a\u0647\u0631\u0627\u0646 \u0628\u0647 \u062f\u0646\u06cc\u0627 \u0622\u0645\u062f\u0645. \u062a\u0627 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u06cc\u0627\u062f\u0645 \u0627\u0633\u062a \u0647\u0645\u06cc\u0634\u0647 \u0627\u0632 \u062f\u06cc\u062f\u0646 \u06a9\u0644\u0645\u0627\u062a \u0647\u06cc\u062c\u0627\u0646\u200c\u0632\u062f\u0647 \u0645\u06cc\u200c\u0634\u062f\u0645 \u0648 \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0645 \u0628\u0647 \u06cc\u06a9 \u0686\u06cc\u0632 \u062c\u0627\u062f\u0648\u06cc\u06cc \u0646\u06af\u0627\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0645. \u0648\u0642\u062a\u06cc \u067e\u062f\u0631\u0645 \u0631\u0648\u0632\u0646\u0627\u0645\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646\u062f \u06cc\u0627 \u0648\u0642\u062a\u06cc \u0645\u0627\u062f\u0631\u0645 \u0628\u0631\u0627\u06cc\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646\u062f \u0647\u0645\u06cc\u0634\u0647 \u0628\u0647 \u0633\u0645\u062a \u06a9\u0644\u0645\u0627\u062a \u0648 \u0646\u0648\u0634\u062a\u0647\u200c\u0647\u0627 \u062c\u0630\u0628 \u0645\u06cc\u200c\u0634\u062f\u0645. \u062a\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u06a9\u0645\u200c\u06a9\u0645 \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u062c\u0627\u06cc\u06af\u0627\u0647 \u0648\u06cc\u0698\u0647\u200c\u0627\u06cc \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc\u200c\u0627\u0645 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0646\u062f\u061b \u0622\u0646\u0642\u062f\u0631 \u062c\u062f\u06cc \u06a9\u0647 \u0631\u0634\u062a\u0647\u200c\u0647\u0627\u06cc \u0645\u0647\u0646\u062f\u0633\u06cc \u0631\u0627 \u06a9\u0646\u0627\u0631 \u06af\u0630\u0627\u0634\u062a\u0645 \u0648 \u06a9\u062a\u0627\u0628\u062f\u0627\u0631\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0631\u062f\u0645. \u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u0631\u0634\u062a\u0647\u200c\u06cc \u06a9\u062a\u0627\u0628\u062f\u0627\u0631\u06cc \u0645\u0646 \u0631\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0628\u0627\u0648\u0631 \u0631\u0633\u0627\u0646\u062f \u06a9\u0647 \u06a9\u0627\u0631 \u062f\u0631 \u062d\u0648\u0632\u0647\u200c\u06cc \u06a9\u062a\u0627\u0628 \u0686\u06cc\u0632\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u0645 \u0647\u0645\u06cc\u0634\u0647 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0645 \u0648 \u0645\u0646 \u0631\u0627 \u062e\u0648\u0634\u062d\u0627\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0646\u0648\u0634\u062a\u0646 \u0627\u0632 \u0622\u0646 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0634\u0645\u0627 \u0628\u0639\u062f \u0627\u0632 \u0639\u0634\u0642 \u0628\u0647 \u062e\u0648\u0627\u0646\u062f\u0646 \u0628\u0647 \u0622\u0646 \u0639\u0644\u0627\u0642\u0647 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0648 \u0627\u06cc\u0646 \u0627\u062a\u0641\u0627\u0642 \u0628\u0631\u0627\u06cc \u0645\u0646 \u0647\u0645 \u0627\u0641\u062a\u0627\u062f. \u062e\u0648\u0634\u062d\u0627\u0644\u0645 \u06a9\u0647 \u062a\u0627 \u0628\u0647 \u0627\u0644\u0627\u0646 \u0628\u0631\u0627\u06cc \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u0648\u06cc\u0646\u0634 \u0648 \u0645\u0631\u062f\u0645\u06a9 \u0645\u0631\u0648\u0631 \u06a9\u062a\u0627\u0628 \u0646\u0648\u0634\u062a\u0647\u200c\u200c\u0627\u0645 \u0648 \u0646\u0648\u0634\u062a\u0646 \u0628\u0631\u0627\u06cc \u0637\u0627\u0642\u0686\u0647 \u0646\u06cc\u0632 \u0645\u0648\u0647\u0628\u062a\u06cc \u0628\u0648\u062f\u0647 \u06a9\u0647 \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0646\u0635\u06cc\u0628\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a. \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0645\u0646 \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u0647\u0633\u062a\u0646\u062f. \u06a9\u062a\u0627\u0628\u200c\u0647\u0627 \u062f\u0646\u06cc\u0627\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0627\u0632 \u0628\u0648\u062f\u0646 \u062f\u0631 \u0622\u0646\u200c\u0647\u0627 \u0644\u0630\u062a \u0645\u06cc\u200c\u0628\u0631\u0645 \u0648 \u0627\u06af\u0631 \u0628\u0627 \u0646\u0648\u0634\u062a\u0646 \u0645\u0646 \u06a9\u0633\u06cc \u0628\u062a\u0648\u0627\u0646\u062f \u0627\u06cc\u0646 \u062d\u0633 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u062f \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u062a\u062e\u0631 \u0648 \u062e\u0648\u0634\u062d\u0627\u0644 \u062e\u0648\u0627\u0647\u0645 \u0634\u062f.","sameAs":["https:\/\/www.linkedin.com\/in\/ailar-esmaeili-87934a22b"],"url":"https:\/\/taaghche.com\/blog\/author\/ailaresmaeili\/"}]}},"_links":{"self":[{"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/posts\/17407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/comments?post=17407"}],"version-history":[{"count":11,"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/posts\/17407\/revisions"}],"predecessor-version":[{"id":22765,"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/posts\/17407\/revisions\/22765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/media\/17408"}],"wp:attachment":[{"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/media?parent=17407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/categories?post=17407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taaghche.com\/blog\/wp-json\/wp\/v2\/tags?post=17407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}